{"id":112493,"date":"2017-03-11T18:20:09","date_gmt":"2017-03-11T17:20:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=112493"},"modified":"2017-03-17T11:33:05","modified_gmt":"2017-03-17T10:33:05","slug":"la-storia-a-scuola-sotto-le-eruzioni-del-mostro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/11\/la-storia-a-scuola-sotto-le-eruzioni-del-mostro\/","title":{"rendered":"LA STORIA \/ A SCUOLA SOTTO LE ERUZIONI DEL MOSTRO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"769\" title=\"img1024-700_dettaglio2_Ilva-Taranto1\" class=\"aligncenter size-full wp-image-112494\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/img1024-700_dettaglio2_Ilva-Taranto1.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/img1024-700_dettaglio2_Ilva-Taranto1.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/img1024-700_dettaglio2_Ilva-Taranto1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/img1024-700_dettaglio2_Ilva-Taranto1-768x577.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/img1024-700_dettaglio2_Ilva-Taranto1-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>di <strong>Giuseppe Puppo______<\/strong><\/p>\n<p>Scandali, speculazioni, affari leciti e meno leciti, ne \u00e8 piena la\u00a0vicenda ormai ultradecennale\u00a0in questa citt\u00e0 bella quanto sfortunata, costretta a convivere con un Mostro dentro&#8230;Un Mostro assassino. Cordate, piani di acquisto, decreti salva &#8211; Ilva&#8230;Decreti salva &#8211; Tarantini, invece niente, mai. Eppure il mostro continua ad avvelenare e ad uccidere. Eppure la logica \u00e8 sempre quella: &#8220;Dove vanno a mangiare, se chiude l&#8217; Ilva?&#8221;. Cos\u00ec, per mangiare, si continua a morire, a Taranto e dintorni, molti dintorni, fino a tutto il Salento.<\/p>\n<p>Un presidente del consiglio che pensava a fare i decreti per salvare la fabbrica, e non la gente, perch\u00e9 \u00e8 &#8220;strategico&#8221; per certa politica consentire gli affari, di riflesso anche i propri, e la salute delle persone strategica evidentemente non \u00e8. Un presidente della Regione, nonch\u00e9 assessore alla Sanit\u00e0, a tempo perso, che oramai pensa solo a diventare segretario nazionale\u00a0del Pd, in servizio permanente effettivo.<\/p>\n<p>E via a ritroso, l&#8217; elenco sarebbe lunghissimo.<\/p>\n<p>La politica, certa politica, non fa, perch\u00e9 a chiudere l&#8217; Ilva basterebbe una firma, e poi avviare le bonifiche, e la riconversione economica del territorio, e di lavoro ce ne sarebbe pi\u00f9 di prima. E vaffanculo ai Riva prima e i Mercegaglia di adesso, e come si dice vaffanculo in lingua indiana?<\/p>\n<p>No, la politica non fa, anzi, ha impedito di fare alla magistratura, che avrebbe voluto fare al posto suo, chiudere, senza se e senza ma. E chi le ha fatte, se non la politica, quelle norme per cui fra poco anche quel po&#8217; di giustizia che avrebbe potuto assicurare il processo &#8216;Ambiente svenduto&#8217; cadr\u00e0 in prescrizione? Vedrete, finir\u00e0 tutto in una bolla di sapone.<\/p>\n<p>Sar\u00e0 cos\u00ec, fino quando i cittadini non sapranno fare essi stessi politica, non delegarla con un voto, spesso tradito.<\/p>\n<p>Diventando essi stessi &#8216;politici&#8217;, con la partecipazione, con l&#8217; informazione diretta.<\/p>\n<p>Informazione, come l&#8217; ultima che arriva &#8216;stasera con un lancio Ansa, che riprende un intervento diretto, di una mamma tarantina. Ve\u00a0ne riporto qui di seguito l&#8217; essenziale.<\/p>\n<p>Scusate se mi sono lasciato andare, vi chiedo perdono se mi sono incazzato, ma lascio tutto come mi \u00e8 venuto di getto: ad apprendere\u00a0ancora di certe cose, di che vita sia se devi stare sprangato a casa tua, e la mattina devi spalare veleno dai balconi, e devi morire un po&#8217; ogni giorno, per poter vivere, il sangue mi ribolle, la moderazione mi si perde, e poi c&#8217;\u00e8 solo tanta commozione.<\/p>\n<p>Un abbraccio a Sabrina, ai suoi figli, e a tutti i bambini di Taranto che hanno diritto al loro futuro.\u00a0\u00a0______<\/p>\n<p><em>&#8220;Ragazzi, bambini, per favore copritevi bene naso e bocca, Wind day si prolunga, andare a scuola \u00e8 un diritto. Speriamo capiscano che bisogna sospendere le lezioni in queste giornate, chi pu\u00f2 vada in auto almeno il tragitto casa-scuola, scuola-casa \u00e8 pi\u00f9 protetto. Che tristezza&#8221;. <\/em><\/p>\n<p><em>E&#8217; lo sfogo di una mamma residente nel rione Tamburi di Taranto, Sabrina Corisi, figlia di un ex operaio dell&#8217;Ilva morto di tumore, che ha scritto una lettera a una dirigente scolastica chiedendo di sospendere le lezioni e ha postato su Facebook anche un video che la ritrae mentre spala polvere nera dalla sua abitazione.<\/em><\/p>\n<p><em>Si tratta delle polveri provenienti dai parchi minerali dell&#8217;Ilva che vengono spinte dal vento verso le abitazioni del rione a ridosso del Siderurgico. Oggi \u00e8 il terzo dei quattro giorni segnalati dall&#8217;Arpa come Wind day, che sta a indicare la giornata di forte vento proveniente dall&#8217;area industriale, in grado di provocare &#8220;una dispersione delle concentrazioni inquinanti di PM10 &#8211; come spiega anche una nota del Comune &#8211; nei soli quartieri vicini all&#8217;area industriale&#8221;. <\/em><\/p>\n<p><em>Nell&#8217;occasione la polizia locale provveder\u00e0 alla deviazione del traffico veicolare in entrata dal quartiere Tamburi e proveniente da Paolo VI.<\/em><\/p>\n<p><em>&#8220;Ci manca il coraggio, altrimenti &#8211; ha scritto Sabrina Corisi sul social network &#8211; tutti e dico tutti potevamo pretendere quello che \u00e8 giusto per i nostri figli&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/11\/la-storia-a-scuola-sotto-le-eruzioni-del-mostro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/11\/la-storia-a-scuola-sotto-le-eruzioni-del-mostro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo______ Scandali, speculazioni, affari leciti e meno leciti, ne \u00e8 piena la\u00a0vicenda ormai ultradecennale\u00a0in questa citt\u00e0 bella quanto sfortunata, costretta a convivere con un Mostro dentro&#8230;Un Mostro assassino. Cordate, piani di acquisto, decreti salva &#8211; Ilva&#8230;Decreti salva &#8211; Tarantini, invece niente, mai. Eppure il mostro continua ad avvelenare e ad uccidere. Eppure la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":112494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112493"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=112493"}],"version-history":[{"count":10,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112493\/revisions"}],"predecessor-version":[{"id":112496,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112493\/revisions\/112496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/112494"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=112493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=112493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=112493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}