{"id":112577,"date":"2017-03-13T11:26:23","date_gmt":"2017-03-13T10:26:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=112577"},"modified":"2017-03-13T11:39:20","modified_gmt":"2017-03-13T10:39:20","slug":"tifosi-del-catania-pronti-alla-violenza-brevi-di-nera","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/13\/tifosi-del-catania-pronti-alla-violenza-brevi-di-nera\/","title":{"rendered":"TIFOSI DEL CATANIA PRONTI ALLA VIOLENZA \/ LADRO DI CARAMELLE \/ BREVI DI NERA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"215\" title=\"Foto\" class=\"aligncenter size-medium wp-image-112578\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/Foto-300x215.jpg\" \/>(g.m.)______Lecce. Prima della partita di calcio col Catania, verso le 13.00, in un&#8217; area di servizio sulla statale da Brindisi, agenti della Digos, in procinto di controllare un gruppo di tifosi ospiti in viaggio su di un pullman, hanno rivenuto una quantit\u00e0 di materiale pericoloso, da loro abbandonato, prima che scattasse la perquisizione: torce, bastoni, mazze tubi di gomma (nella foto). Tutto sequestrato.<\/p>\n<p>&nbsp;<\/p>\n<p>Taranto. Arrestato &#8211; ma si trova ora ai domiciliari &#8211; un ladro di caramelle, anzi, per la precisione di gomme da masticare. E&#8217; un uomo\u00a0di\u00a036 \u00a0anni, che ha oltrepassato la cassa di un supermercato nascondendo senza pagarla una confezione di settantasei pacchetti, del valore di 200 euro.\u00a0Il personale della sicurezza interna per\u00f2 lo ha notato, lo ha fermato ed ha avvisato i Carabinieri che, raccolta la denuncia del responsabile del centro commerciale, lo hanno arrestato\u00a0con l&#8217;accusa di furto aggravato.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/13\/tifosi-del-catania-pronti-alla-violenza-brevi-di-nera\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/13\/tifosi-del-catania-pronti-alla-violenza-brevi-di-nera\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Lecce. Prima della partita di calcio col Catania, verso le 13.00, in un&#8217; area di servizio sulla statale da Brindisi, agenti della Digos, in procinto di controllare un gruppo di tifosi ospiti in viaggio su di un pullman, hanno rivenuto una quantit\u00e0 di materiale pericoloso, da loro abbandonato, prima che scattasse la perquisizione: torce, bastoni, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":112578,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112577"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=112577"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112577\/revisions"}],"predecessor-version":[{"id":112580,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112577\/revisions\/112580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/112578"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=112577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=112577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=112577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}