{"id":11266,"date":"2013-02-19T07:56:00","date_gmt":"2013-02-19T07:56:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11266"},"modified":"2013-02-19T07:57:22","modified_gmt":"2013-02-19T07:57:22","slug":"come-risolvere-il-caso-maradona","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/19\/come-risolvere-il-caso-maradona\/","title":{"rendered":"COME RISOLVERE IL CASO MARADONA"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p><strong><span style=\"font-family: 'Times New Roman';font-size: small\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/19\/come-risolvere-il-caso-maradona\/maradona\/\" rel=\"attachment wp-att-11269\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maradona.jpg\" alt=\"\" width=\"600\" height=\"600\" class=\"alignleft size-full wp-image-11269\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maradona.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maradona-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maradona-300x300.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>Diritto Tributario. Come risolvere il caso Maradona. L&#8217; &#8220;autotutela&#8221; l&#8217;unica chance per Diego. Un interessante contributo del tributarista Villani e dall&#8217;avvocatessa Rizzelli, che fa chiarezza sulle voci apparse sulla stampa su un caso tutto italiano e che offre preziosi spunti difensivi anche per i &#8221; piccoli&#8221; contribuenti<\/span><\/strong><br \/>\n<span style=\"font-family: 'Times New Roman';font-size: small\">Lo \u201c<a title=\"blocked::http:\/\/www.sportellodeidiritti.org\/\" href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d\u00a0 si batte da sempre contro l&#8217;evasione ma anche per un fisco pi\u00f9 equo, corretto e a misura di contribuente, ma il caso &#8220;tributario&#8221; di Diego Maradona, da anni sulle cronache italiane per i continui colpi di scena, gli ultimi ad inizio febbraio di quest&#8217;anno con una serie di code polemiche, riteniamo che abbia bisogno di qualche chiarimento per capire cosa \u00e9 accaduto e l&#8217;ultimo epilogo della vicenda che ha causato scalpore e soprattutto disinformazione per il susseguirsi di notizie, in parte distorte, perch\u00e9 non affidate ai tecnici di una materia, quale il diritto tributario, ostica e di non semplice divulgazione.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ecco perch\u00e9 Giovanni D&#8217;Agata, fondatore dello \u201c<a title=\"blocked::http:\/\/www.sportellodeidiritti.org\/\" href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d, ritiene utile portare all&#8217;attenzione della cittadinanza e dei media un interessante contributo del noto tributarista leccese avvocato Maurizio Villani e dell&#8217;avvocatessa Paola Rizzelli che chiarisce i dettagli dell'&#8221;affaire Maradona&#8221;, fornendo interessanti spunti anche per i contribuenti coinvolti in analoghe, ma meno eclatanti vicende.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Lecce, 18 febbraio 2013<\/span><\/p>\n<p><strong><em><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Giovanni D\u2019AGATA<\/span><\/em><\/strong><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">COME RISOLVERE IL CASO MARADONA<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">L\u2019autotutela, l\u2019unica chance per Diego<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Con sentenza n. 598\/01\/13, depositata lo scorso 1\u00b0 febbraio, la Commissione tributaria centrale di Napoli ha rigettato la richiesta di intervento adesivo dipendente avanzata dal calciatore Maradona nel giudizio in questione, rispetto al quale lo stesso Maradona era rimasto estraneo.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Nella specie, la controversia \u00e8 scaturita dalla notifica nei confronti della S. S. Calcio Napoli s.p.a., in merito agli esercizi che vanno dal 1985 al 1990, di avvisi di accertamento con i quali il competente ufficio finanziario contestava l&#8217;omesso versamento delle ritenute che avrebbe dovuto operare sulle maggiori retribuzioni corrisposte ai calciatori Maradona, Careca e Alemao.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Secondo l\u2019ufficio, difatti, ai calciatori erano stati corrisposti maggiori compensi, occultati dalla interposizione di societ\u00e0 estere, per cui lo stesso procedeva altres\u00ec al recupero del maggior reddito accertato, notificando gli avvisi di accertamento anche ai tre calciatori. Tutti gli avvisi di accertamento in questione, poi, venivano tempestivamente impugnati, dinanzi all\u2019autorit\u00e0 giudiziaria competente, fatta eccezione per\u00f2 per l&#8217;avviso notificato a Maradona.Con sentenza del 20 dicembre 1993,successivamente impugnata dalla societ\u00e0, dai calciatori e dall\u2019ufficio, la Commissione tributaria di primo grado di Napoli, previa riunione dei ricorsi, accoglieva le ragioni della societ\u00e0 limitatamente a rettifiche riguardanti altri rapporti, mentre rigettava \u201cnel resto i ricorsi per quanto riguarda l\u2019omesso versamento delle ritenute d\u2019acconto relative ai corrispettivi di lavoro di Maradona \u2026, con salvezza degli effetti derivanti dalla dichiarazione integrativa presentata\u201d. Rigettava, altres\u00ec, i ricorsi di due calciatori \u201cper la parte relativa ai redditi non coperti dalle dichiarazioni integrative presentate\u201d. Con sentenza del 6 settembre 1994, poi, l\u2019adita Commissione tributaria di secondo grado di Napoli rigettava il ricorso della societ\u00e0 e quello dell\u2019ufficio, mentre accoglieva quello dei due calciatori. L\u2019Ufficio ha conseguentemente proposto ricorso alla Commissione tributaria centrale di Napoli che, in considerazione dell\u2019avvenuta definizione della lite da parte della societ\u00e0 ai sensi dell\u2019art. 16 della legge n. 289\/2002 e delle dichiarazioni integrative presentate dai due calciatori ai sensi della legge n. 413\/1991, ha dichiarato l\u2019estinzione dei giudizi relativi alla fallita societ\u00e0 e ai due calciatori, rigettando la richiesta di intervento adesivo avanzata da Maradona.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Il calciatore argentino, infatti, pur non avendo impugnato gli avvisi di accertamento, era intervenuto nel corso del giudizio chiedendo di poter godere degli effetti della sentenza, attesa l\u2019inscindibilit\u00e0 tra la contestazione a lui mossa e quella fatta alla societ\u00e0. Orbene, secondo l\u2019adita Commissione, invece, la chiusura della controversia da parte della societ\u00e0 Napoli Calcio non comporta la definizione automatica degli obblighi del calciatore Maradona, la cui obbligazione tributaria deve essere soddisfatta in base alla propria aliquota marginale. Questo per diverse ragioni.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Innanzitutto, perch\u00e9 il calciatore \u00e8 rimasto estraneo al giudizio, non impugnando l\u2019avviso di accertamento notificatogli, cosicch\u00e9 l\u2019obbligazione tributaria nei suoi confronti si \u00e8 consolidata, con conseguente inapplicabilit\u00e0 dell\u2019art. 14, comma 3, del D. Lgs. n. 546\/1992.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Secondariamente, poi, anche perch\u00e9 \u201cla definizione della controversia nei confronti della societ\u00e0, in forza di una norma di condono, ha natura soggettiva e non pu\u00f2 riflettersi sugli obblighi di altri soggetti: la decisione della controversia nei confronti della societ\u00e0 non implica un accertamento in fatto di cui possa beneficiare il contribuente\u201d. \u201cN\u00e9 il condono della societ\u00e0 pu\u00f2 estendersi al calciatore che avrebbe potuto a sua volta accedere al condono, se avesse ritenuto di contestare tempestivamente l\u2019 accertamento\u201d.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">In definitiva, dunque, l\u2019unica strada ancora percorribile al Pibe de Oro resta quella dell\u2019autotutela, con conseguente possibilit\u00e0 d\u2019impugnare un eventuale rifiuto (Cass., SS. UU., del 23 aprile 2009, n. 9669).<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Lecce, 18 febbraio 2013 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Avv. Maurizio Villani<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Avv. Paola Rizzelli<\/span><\/p>\n<p><span style=\"font-family: Arial;font-size: x-small\">\u00a0<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/19\/come-risolvere-il-caso-maradona\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/19\/come-risolvere-il-caso-maradona\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Diritto Tributario. Come risolvere il caso Maradona. L&#8217; &#8220;autotutela&#8221; l&#8217;unica chance per Diego. Un interessante contributo del tributarista Villani e dall&#8217;avvocatessa Rizzelli, che fa chiarezza sulle voci apparse sulla stampa su un caso tutto italiano e che offre preziosi spunti difensivi anche per i &#8221; piccoli&#8221; contribuenti Lo \u201cSportello dei Diritti\u201d\u00a0 si batte da sempre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11269,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11266"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11266"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11266\/revisions"}],"predecessor-version":[{"id":11268,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11266\/revisions\/11268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11269"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}