{"id":112814,"date":"2017-03-16T14:34:49","date_gmt":"2017-03-16T13:34:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=112814"},"modified":"2017-03-20T09:59:47","modified_gmt":"2017-03-20T08:59:47","slug":"emissioni-nocive-l-oncologo-giuseppe-serravezza-della-lilt-riafferma-l-opposizione-al-gasdotto-tap","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/16\/emissioni-nocive-l-oncologo-giuseppe-serravezza-della-lilt-riafferma-l-opposizione-al-gasdotto-tap\/","title":{"rendered":"&#8220;Emissioni nocive&#8221;, L&#8217; ONCOLOGO GIUSEPPE SERRAVEZZA DELLA LILT RIAFFERMA L&#8217; OPPOSIZIONE AL GASDOTTO TAP"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" title=\"maxresdefault\" class=\"aligncenter size-large wp-image-112815\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/maxresdefault1-1024x576.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/maxresdefault1-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/maxresdefault1-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/maxresdefault1-768x432.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/maxresdefault1-1536x864.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/maxresdefault1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>(g.p<em>.)______&#8221;La riduzione di pressione del gas operata della centrale detta appunto di depressurizzazione prima dell&#8217; immissione nella rete ordinaria causerebbe emissioni nocive per la salute<\/em>&#8220;.\u00a0Il\u00a0dottor Giuseppe\u00a0Serravezza (nella foto), da venticinque anni impegnato nel Salento nella lotta al cancro,\u00a0non ha dubbi nel ribadire la propria opposizione al gasdotto Tap.<\/p>\n<p>Lo ha fatto questa mattina, rispondendo ad una domanda di leccecronaca.it al riguardo, nel corso della conferenza stampa, tenutasi a Palazzo Adorno della Provincia, in cui la Lega Italiana Lotta Tumori ha presentato\u00a0l&#8217; iniziativa della settimana dedicata alla prevenzione, che parte sabato prossimo, da articolare con corretta alimentazione e nuovi stili di vita; ed ha inoltre\u00a0illustrato propri dati epidemiologici, che\u00a0confermano purtroppo l&#8217; aumento dei casi di tumore\u00a0a Lecce\u00a0in maniera esponenziale e superiore alla media<\/p>\n<p>L&#8217; oncologo, che ha detto di non sapere che fine abbiano fatto i suoi esposti presentati in Procura al riguardo, ha spiegato che comunque si \u00a0tratterebbe di altre emissioni nocive, che si aggiungerebbero alle emissioni nocive gi\u00e0 presenti provenienti da Ilva, Cerano e &#8220;tanti cerini&#8221;, come ha\u00a0chiamato altre fabbriche inquinanti, sia pur pi\u00f9 piccole.<\/p>\n<p>La sua valutazione al riguardo \u00e8 dettagliata in una dichiarazione scritta diffusa appunto in apertura di conferenza stampa: <em>&#8220;Ilva, Cerano, Tap: vecchie e nuove emergenze ambientali, le prime due sicuramente responsabili delle tante storie di malattie tumorali, cardiovascolari, neurologiche, endocrine, che affliggono il Salento; la Tap che rischia di peggiorare una situazione ambientale e sanitaria gi\u00e0 tanto grave<\/em>&#8220;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/16\/emissioni-nocive-l-oncologo-giuseppe-serravezza-della-lilt-riafferma-l-opposizione-al-gasdotto-tap\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/16\/emissioni-nocive-l-oncologo-giuseppe-serravezza-della-lilt-riafferma-l-opposizione-al-gasdotto-tap\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.)______&#8221;La riduzione di pressione del gas operata della centrale detta appunto di depressurizzazione prima dell&#8217; immissione nella rete ordinaria causerebbe emissioni nocive per la salute&#8220;.\u00a0Il\u00a0dottor Giuseppe\u00a0Serravezza (nella foto), da venticinque anni impegnato nel Salento nella lotta al cancro,\u00a0non ha dubbi nel ribadire la propria opposizione al gasdotto Tap. Lo ha fatto questa mattina, rispondendo ad [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":112815,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112814"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=112814"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112814\/revisions"}],"predecessor-version":[{"id":113051,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112814\/revisions\/113051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/112815"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=112814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=112814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=112814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}