{"id":114411,"date":"2017-04-04T00:04:46","date_gmt":"2017-04-03T22:04:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=114411"},"modified":"2017-04-03T23:09:44","modified_gmt":"2017-04-03T21:09:44","slug":"diario-del-giorno-dopo-teatro-i-suoceri-albanesi-a-melendugno-mercoledi-5","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/diario-del-giorno-dopo-teatro-i-suoceri-albanesi-a-melendugno-mercoledi-5\/","title":{"rendered":"DIARIO DEL GIORNO DOPO \/ TEATRO \/ &#8216;I SUOCERI ALBANESI&#8217; A MELENDUGNO MERCOLEDI&#8217; 5"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"199\" title=\"168742\" class=\"aligncenter size-medium wp-image-114412\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/168742-300x199.jpg\" \/>Mercoled\u00ec 5 aprile, alle 21.30, a\u00a0Melendugno, al Nuovo Cinema Paradiso, in piazza Risorgimento, sulla\u00a0scena Francesco Pannofino, Emanuela Rossi, in &#8220;I SUOCERI ALBANESI&#8221;, di Gianni Clementi, con Andrea Lolli, Silvia Brogi, Maurizio Pepe, Filippo Lagan\u00e0, Elisabetta Clementi, per la regia di Claudio Boccaccini.<\/p>\n<p>Una famiglia borghese: un padre, una madre e una figlia. Entrambi cercano quotidianamente di trasmettere alla figlia Camilla, 16enne, valori importanti: l\u2019importanza della politica, della solidariet\u00e0, della fratellanza. La rottura di una tubazione del bagno di servizio, che rischia di allagare l\u2019appartamento sottostante, obbliga i coniugi a chiamare una ditta per il restauro.Viaggi su barconi fatiscenti, periodi di clandestinit\u00e0, infine l\u2019agognato permesso di soggiorno fanno parte del passato dei due operai albanesi.Un esempio da seguire per Camilla e i giovani come lei, ma un giorno Lucio dimentica un importante documento, torna a casa ad un orario imprevisto e le certezze sue e di Ginevra crollano come un castello di carte.<\/p>\n<p>Biglietti da 13 a 21 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/diario-del-giorno-dopo-teatro-i-suoceri-albanesi-a-melendugno-mercoledi-5\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/diario-del-giorno-dopo-teatro-i-suoceri-albanesi-a-melendugno-mercoledi-5\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 5 aprile, alle 21.30, a\u00a0Melendugno, al Nuovo Cinema Paradiso, in piazza Risorgimento, sulla\u00a0scena Francesco Pannofino, Emanuela Rossi, in &#8220;I SUOCERI ALBANESI&#8221;, di Gianni Clementi, con Andrea Lolli, Silvia Brogi, Maurizio Pepe, Filippo Lagan\u00e0, Elisabetta Clementi, per la regia di Claudio Boccaccini. Una famiglia borghese: un padre, una madre e una figlia. Entrambi cercano quotidianamente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":114412,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114411"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=114411"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114411\/revisions"}],"predecessor-version":[{"id":114414,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114411\/revisions\/114414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/114412"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=114411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=114411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=114411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}