{"id":114437,"date":"2017-04-04T13:53:50","date_gmt":"2017-04-04T11:53:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=114437"},"modified":"2017-04-08T13:17:11","modified_gmt":"2017-04-08T11:17:11","slug":"il-mito-dell-immortalita-da-trismegisto-e-tolkien-in-un-incontro-sabato-8-a-milano-con-gli-autori-dei-saggi-dell-editore-salentino-stefano-donoo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/il-mito-dell-immortalita-da-trismegisto-e-tolkien-in-un-incontro-sabato-8-a-milano-con-gli-autori-dei-saggi-dell-editore-salentino-stefano-donoo\/","title":{"rendered":"IL MITO DELL&#8217; IMMORTALITA&#8217; DA TRISMEGISTO A TOLKIEN IN UN INCONTRO SABATO 8 A MILANO CON GLI AUTORI DEI SAGGI DELL&#8217; EDITORE SALENTINO STEFANO DONNO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"690\" title=\"tolkien-10\" class=\"aligncenter size-large wp-image-114438\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/tolkien-10-1024x690.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/tolkien-10-1024x690.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/tolkien-10-300x202.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/tolkien-10-768x518.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/tolkien-10-1536x1036.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/tolkien-10.jpg 1572w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>(Rdl)______Da Trismegisto, mitico filosofo iniziatico dell&#8217; et\u00e0 ellenistica, a Tolkien (nella foto), mitico romanziere della letteratura fantasy contemporanea. Sabato 8 aprile evento culturale unico nel suo genere,\u00a0per affrontare dall\u2019antichit\u00e0 nella tradizione filosofica, alla modernit\u00e0 nella letteratura, la problematica legata al desiderio ancestrale dell\u2019uomo di essere immortale e dunque onnipotente.<\/p>\n<p>L&#8217; incontro, dal titolo \u00a0\u201c<strong>Mito, Alchimia, Immortalit\u00e0 da Ermete Trismegisto a J.R.R. Tolkien<\/strong>\u201d,\u00a0\u00a0sar\u00e0 alle 16.00, a\u00a0Milano, presso la Libreria Esoterica Primordia, in via Piacenza 20, e vedr\u00e0 la partecipazione di\u00a0Enrica Perucchietti, Paolo Battistel e Stefano Donno che presentano per la prima volta insieme e in anteprima nazionale le loro nuove pubblicazioni per iQdB Edizioni dell&#8217; editore salentino\u00a0Stefano Donno:\u00a0&#8220;Il mito dell\u2019immortalit\u00e0&#8221; di <strong>Enrica Perucchietti<\/strong>; &#8220;Breve commentario alla Tavola Smeraldina&#8221; di Ermete Trismegisto&#8221; a cura di <strong>Stefano Donno<\/strong>; &#8220;J.R.R. Tolkien &#8211; Il lungo sentiero tra Ombra e Luce&#8221;, di <strong>Paolo Battistel<\/strong>.<\/p>\n<p>Diamo qui di seguito qualche cenno su autori e opere.<\/p>\n<p><strong>&#8220;Il mito dell\u2019immortalit\u00e0&#8221; di Enrica Perucchietti, iQdB Edizioni.\u00a0<\/strong><\/p>\n<p>La ricerca della vita eterna ha ossessionato l\u2019Uomo di ogni epoca e cultura: se per alcuni l\u2019immortalit\u00e0 veniva concepita come una \u201cdannazione\u201d (si pensi alla maledizione che colpisce l\u2019Ebreo errante), per altri era da intendere come un \u201cpremio\u201d da conseguire dopo un lungo lavoro di ricerca magica, spirituale e iniziatica. La modernit\u00e0 abbraccia i sogni millenari degli alchimisti, svuotandoli e facendone la cornice dei progressi della tecnica. La pulsione dell\u2019uomo moderno \u00e8 quella di migliorare le proprie potenzialit\u00e0, per giungere infine a sostituirsi alla compiuta evoluzione naturale, per proseguire il proprio corso secondo autonome finalit\u00e0.<\/p>\n<p>Le nuove tecnologie hanno acquisito un tale potere di suggestione e di condizionamento che sono destinate a modificare i rapporti sociali e politici del futuro verso la costituzione di una societ\u00e0 piramidale e oligarchica.<\/p>\n<p>Dall\u2019Elixir alchemico di lunga vita alle derive nere della Magia Avatarica, il sogno di poter sconfiggere la morte sopravvive ora nel Transumanesimo con il mind uploading (il trasferimento di mente), la telomerasi, la crionica o progetti volti a resuscitare i morti (Reanima). Come nella peggiore distopia, si potr\u00e0\u201cvendere\u201d l\u2019illusione dell\u2019immortalit\u00e0, installando le memorie dei padri nei corpi dei figli.<\/p>\n<p>Il mito alchemico della trasmutazione si converte cos\u00ec nei progetti prometeici volti alla creazione di un uomo OGM, di un individuo geneticamente modificato che possa soddisfare le esigenze del potere: obbedienza, sottomissione, omologazione.<\/p>\n<p>Enrica Perucchietti vive e lavora a Torino come giornalista, scrittrice ed editor. Oltre a numerose pubblicazioni su riviste digitali e cartacee, \u00e8 autrice di numerosi saggi. \u00c8 docente presso la Libera Universit\u00e0 italiana degli Studi Esoterici \u201cAchille D\u2019Angelo \u2013 Giacomo Catinella\u201d &#8211; Facolt\u00e0 di Scienze Tradizionali ed Esoteriche della Saint Nicholas Moscow University.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8220;J.R.R. Tolkien &#8211; Il lungo sentiero tra Ombra e Luce&#8221; di Paolo Battistel<\/strong><\/p>\n<p>Chi era J.R.R. Tolkien? Da dove nasce il mito che troviamo nelle pagine de Il Signore degli Anelli? \u00c8 una semplice opera di fantasia come sostengono alcuni critici o affonda le proprie radici in altro? In questo testo l\u2019autore mostra come Tolkien abbia ripreso e rielaborato gli antichi miti che insegnava nei suoi corsi universitari a Oxford per plasmare una mitologia primigenia e coerente: \u00e8 da qui che prende forma la sua opera innovativa che vede tra i suoi modelli letterari il Beowulf. Paolo Battistel accompagna il lettore alla scoperta della trattazione del concetto del Male che, anche se incarnato da figure semidivine come Sauron e Melkor, si muove sul filo sottile tra il Male metafisico degli gnostici e il Male morale di Agostino.<\/p>\n<p>L\u2019autore analizza inoltre cosa rappresenta l\u2019Incantata Terra di Lorien nel pensiero di Tolkien e come il desiderio di raggiungere il Paradiso in Terra, cio\u00e8 la terra degli d\u00e8i e degli elfi luminosi di ascendenza germanica, sia uno dei temi che ha mosso la ricerca di Tolkien fin dalla pi\u00f9 giovane et\u00e0. Il filologo di Oxford riporta nella spoglia dimensione dell\u2019uomo contemporaneo, intrappolato in una societ\u00e0 che soddisfa soltanto i suoi bisogni apparenti, il ritorno alla pienezza della dimensione del mito.<\/p>\n<p>Paolo Battistel \u00e8 laureato in filosofia con una tesi in Mitologia. Specializzato nello studio dei miti e delle leggende precristiane vanta la pubblicazione di diversi libri d\u2019argomento storico e mitologico come Il dio cornuto, Il sangue di Caino e I figli di Lucifero. \u00c8 autore della raccolta di fiabe occitane dal titolo Lu Barban, il diavolo e le streghe e del saggio storico Il mistero della Roccaforte dei Rosacroce. Collabora con la trasmissione televisiva di Italia 1 \u00abMistero\u00bb e con diverse riviste giornalistiche di settore. Ha una cattedra di Mitologia alla Libera Universit\u00e0 Achille d\u2019Angelo Giacomo Catinella a Lecce. Vive e lavora a Torino come scrittore ed editor.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8220;Breve commentario alla Tavola Smeraldina di Ermete Trismegisto&#8221; a cura di Stefano Donno.<\/strong><\/p>\n<p>Dalla prefazione di Enrica Perucchietti:<\/p>\n<p><em>\u201cQuando l\u2019amico Stefano Donno mi ha chiamato per chiedermi di scrivere la prefazione del presente saggio, stavo rileggendo, a distanza di anni, Il Leone rosso, il romanzo esoterico di Maria Szepes. Sincronicit\u00e0 volle che la sera stessa incappassi nella parte in cui Hans ascolta, spiando di nascosto il maestro alchimista Rochard, un dialogo tra questi e l\u2019amico Bahr. <\/em><\/p>\n<p><em>Il dialogo in questione si concentra proprio sulla Tavola Smeraldina e sull\u2019interpretazione che da secoli gli iniziati cercano di carpire alle sibilline parole della Tabula. Caso volle che avessi ripreso in mano il libro dopo una conversazione avuta qualche giorno prima con un altro amico: rileggendo le parole di Szepes su Ermete Trismegisto non potei che sorridere e accettare di cuore di curare questa breve prefazione. Pungolata dalla sincronicit\u00e0, decisi anche che avrei inserito alcune citazioni del libro. Nel passo citato, il medico e alchimista Rochard spiega allo scettico Bahr, che verr\u00e0 poco dopo guarito grazie al Lapis e finir\u00e0 per credere ciecamente in quei principii che negava e derideva, che \u00abLa rivelazione di Ermete Trismegisto racchiude in s\u00e9 allo stesso modo i segreti pi\u00f9 profondi della creazione, quali l\u2019essenza delle forze che costituiscono i mondi trascendenti, le cosiddette regioni astrali. Ma oltre a questo designa anche l\u2019alchimia nel senso stretto del termine, il cuore segreto dell\u2019alchimia, la formula spirituale della preparazione dell\u2019Elisir di Vita\u00bb.<\/em><\/p>\n<p>Stefano Donno (1975) si laureato nel 2005 in Filosofia presso l\u2019Universit\u00e0 degli Studi di Lecce. Nel febbraio 2013 riceve una Laurea HC in Juridical Science presso la Moscow University Sancti Nicolai. \u00c8 stato Gran Siniscalco dell\u2019Ordo Equestris Templi Arcadia, Gran Siniscalco (Cavaliere Ereditario di Commenda) del Santissimo Ordine Nobiliare Aragonese di San Giacomo di Compostela, e Caballero de Merito del Soberano Orden Militar Espanola de los Caballeros Templarios. Ha ricoperto dall\u2019aprile 2016 al febbraio 2017 la carica di Vice Preside della Libera Universit\u00e0 di Studi Esoterici \u201cAchille d\u2019Angelo &#8211; Giacomo Catinella\u201d di Lecce. Nel 2016 partecipa come relatore al 16\u00b0 Simposio Mondiale su Scienza, Tradizione e Dimensioni del Sacro a San Marino e VI Convegno Ufologico Interregionale per la Puglia e la Basilicata del Centro Ufologico Nazionale (CUN). Dal 1998 ha collaborato attraverso suoi saggi, recensioni e interventi\u00a0a riviste e testate giornalistiche.<\/p>\n<p>Dal 1998 suoi versi e racconti sono inseriti nelle seguenti antologie: L\u2019autodidatta, Scripturae, Argonauti, Terribili e Ammutinati, 70 poesie per Don Mazzi, Verso Levante \u2013 un secolo di poesia pugliese, Sul Boxer del nonno verso la poesia, Assalto ai Forni, Calpestare l\u2019Obl\u00eco, Canto Blues alla deriva, Superba \u00e8 la notte, Majanu, Il Mare deve vivere, Beneficio d\u2019inventario, Umane transumanze, Nostalgia di Itaca.<\/p>\n<p>Pubblicazioni: Sturm and Pulp (Lecce, 1998); Edoardo De Candia, considerazioni inattuali (Lecce, 1999); Se Hank avesse incontrato Anais (Lecce, 1999); Monologo (Copertino, 2001); Sliding Zone (Lecce, 2002); L\u2019Altro Novecento &#8211; giovane letteratura salentina dal 1992 al 2004 (San Cesario, 2004); Ieratico Poietico (Nard\u00f2, 2008); Dermica per versi (Faloppio, 2009); Mendica Historia (con Sandro Ciurlia, Lecce, 2010); Corpo Mistico (Roma, 2010); Prezzario della rinomata casa del piacere (con Anna Chiriatti, Martignano, 2011); A Sud del Sud dei Santi a cura di Michelangelo Zizzi (Faloppio, 2013), Nerocavo (Copertino, 2014), Breve commentario alla Tavola Smeraldina di Ermete Trismegisto (Lecce, 2017).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/il-mito-dell-immortalita-da-trismegisto-e-tolkien-in-un-incontro-sabato-8-a-milano-con-gli-autori-dei-saggi-dell-editore-salentino-stefano-donoo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/il-mito-dell-immortalita-da-trismegisto-e-tolkien-in-un-incontro-sabato-8-a-milano-con-gli-autori-dei-saggi-dell-editore-salentino-stefano-donoo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Da Trismegisto, mitico filosofo iniziatico dell&#8217; et\u00e0 ellenistica, a Tolkien (nella foto), mitico romanziere della letteratura fantasy contemporanea. Sabato 8 aprile evento culturale unico nel suo genere,\u00a0per affrontare dall\u2019antichit\u00e0 nella tradizione filosofica, alla modernit\u00e0 nella letteratura, la problematica legata al desiderio ancestrale dell\u2019uomo di essere immortale e dunque onnipotente. L&#8217; incontro, dal titolo \u00a0\u201cMito, Alchimia, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":114438,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114437"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=114437"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114437\/revisions"}],"predecessor-version":[{"id":114442,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114437\/revisions\/114442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/114438"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=114437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=114437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=114437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}