{"id":114462,"date":"2017-04-04T18:53:50","date_gmt":"2017-04-04T16:53:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=114462"},"modified":"2017-04-04T19:09:27","modified_gmt":"2017-04-04T17:09:27","slug":"presentata-oggi-a-surbo-lopera-di-agostino-gurascio-e-armida-mele-la-pala-daltare-della-chiesa-di-san-pantaleo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/presentata-oggi-a-surbo-lopera-di-agostino-gurascio-e-armida-mele-la-pala-daltare-della-chiesa-di-san-pantaleo\/","title":{"rendered":"PRESENTATA OGGI A SURBO L&#8217;OPERA DI AGOSTINO GURASCIO E ARMIDA MELE: LA PALA D&#8217;ALTARE DELLA CHIESA DI SAN PANTALEO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"857\" title=\"pala altare san pantaleo surbo\" class=\"aligncenter size-full wp-image-114463\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/pala-altare-san-pantaleo-surbo.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/pala-altare-san-pantaleo-surbo.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/pala-altare-san-pantaleo-surbo-300x257.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/pala-altare-san-pantaleo-surbo-768x658.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>di <strong>Antonella Elefante<\/strong>______ Quella di oggi, <strong>4 aprile,<\/strong> \u00e8 una giornata importante per <strong>Surbo<\/strong>, piccola cittadina\u00a0alle porte\u00a0di Lecce. Non si tratta di cronaca nera, ma di un evento di notevole importanza artistica; sar\u00e0, infatti, presentata ai cittadini la <strong>Pala d&#8217;altare della Chiesa di San Pantaleo<\/strong>, sita in via Cirillo, progettata dall&#8217;architetto Agostino Gurascio e sua madre Armida Mele, nonch\u00e9 importante pittrice della piccola cittadina.<\/p>\n<p>L&#8217;opera, di 350 cm x 300 cm,<strong> \u00e8 una delle pi\u00f9 grandi tra quelle ospitate da altri edifici religiosi del paese<\/strong>. Proprio per la sua notevole dimensione, ha richiesto una lunga collaborazione tra madre e figlio, durata due mesi.<\/p>\n<p>La scena rappresentata nel quadro (in foto), \u00e8<strong> ambientata nella campagna\u00a0salentina<\/strong> e racconta alcuni momenti cruciali della vita del Santo, dai suoi primi miracoli al suo martirio.<br \/>\nAnalizzando attentamente la tela, \u00e8 possibile notare<strong> molteplici significati simbolici<\/strong> della stessa: dalla strada che richiama il percorso verso Cristo alla luce Divina che squarcia il buio della cecit\u00e0. Ci\u00f2 che viene messo in evidente rilievo, \u00e8 il <strong>continuo contrasto tra le forze opposte<\/strong>: male e bene, oscurit\u00e0 e luce, morte e vita, corpo e spirito, fuoco e acqua, peccato e perdono. Vengono, inoltre,\u00a0<strong>rappresentati tutti gli elementi naturali<\/strong> da cui trae origine ogni sostanza di cui \u00e8 composta la materia: il fuoco, elemento purificatore e vivificatore; l&#8217;aria, energia vitale che rappresenta il respiro cosmico; l&#8217;acqua, fonte della vita; la terra, solida e rigogliosa, che accoglie la vita e la nutre.<\/p>\n<p>Pi\u00f9 esperto di noi di leccecronaca.it \u00e8 sicuramente il <strong>Professor Damiano Lupo<\/strong> che ha elaborato una lettura<strong> critica dell&#8217;opera<\/strong>.<\/p>\n<p>&#8220;<em>La figura dominante di San Pantaleo determina il valore pittorico della profondit\u00e0 e dello spazio sino alla rappresentazione di un infinito che si fa cos\u00ec vicino attraverso l&#8217;immagine del Cristo. La riflessione sulla progressione creativa porta a pensare come in un lavoro pittorico i colori diventano un mondo narrato visibile, che lascia via via sulla tela le tracce di un mondo nascosto, quello dell\u2019autore, costruito dai propri sentimenti, emozioni, istinti e conflitti, senza tralasciare tutto ci\u00f2 che ha circondato la sua vita, l&#8217;ambiente, gli affetti, gli studi e le ricerche stilistiche. Pertanto s&#8217;intravedono in questo lavoro due configurazioni che polarizzano l&#8217;attenzione,<strong> il paesaggio e le figure<\/strong>, in una coesistenza di espressioni distinte provenienti da due diversi temperamenti, ma pur tanto consoni<\/em>&#8220;.<\/p>\n<p>A proposito degli <strong>autori<\/strong>, dice:<em> &#8220;<strong>La pittrice<\/strong> ha segnato la rappresentazione della figura umana su tre piani diversi di profondit\u00e0, con uno studio attento della prospettiva. In primo piano ha curato la descrizione del miracolo della vista donata ad un cieco con la figura dominante del Santo medico che, per intercessione di Cristo, supera i limiti della scienza. Descrive con molta cura di particolari le figure del Santo, attraverso le quali si scopre la memoria formativa dell&#8217;artista, dall&#8217;arte bizantina a quella rinascimentale. Veste San Pantaleo di una calma cristiana nel momento del miracolo e durante la tortura col fuoco, un&#8217;espressione di fede e rassegnazione alla volont\u00e0 suprema.<\/em><br \/>\n<em> La mano di <strong>Agostino Guarascio<\/strong>, figlio della pittrice, si riconosce soprattutto nella rappresentazione del paesaggio naturalistico. I tratti incisivi di Agostino non disegnano le immagini, ma le scolpiscono, i muri non sono costruiti solo con le pietre ma anche con la tenacia corrosiva delle ombre. Rappresenta gli ulivi come protagonisti sofferenti alla ricerca del loro significato simbolico di Pace, rende evidente il conflitto tra il bene e il male attraverso la metamorfosi dei rami in corona di spine. Le luci, le ombre, sono quelle prodotte da un sole che tra gli ulivi e tea i muri di pietre diventa un sole salentino&#8221;.<\/em><\/p>\n<p>Nell&#8217;insieme, il professor Lupo definisce quest&#8217;opera come &#8220;<em>una preghiera a San Pantaleo, protettore di tanti popoli, affinch\u00e9 possa vegliare sulla terra salentina&#8221;.<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/presentata-oggi-a-surbo-lopera-di-agostino-gurascio-e-armida-mele-la-pala-daltare-della-chiesa-di-san-pantaleo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/04\/presentata-oggi-a-surbo-lopera-di-agostino-gurascio-e-armida-mele-la-pala-daltare-della-chiesa-di-san-pantaleo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Antonella Elefante______ Quella di oggi, 4 aprile, \u00e8 una giornata importante per Surbo, piccola cittadina\u00a0alle porte\u00a0di Lecce. Non si tratta di cronaca nera, ma di un evento di notevole importanza artistica; sar\u00e0, infatti, presentata ai cittadini la Pala d&#8217;altare della Chiesa di San Pantaleo, sita in via Cirillo, progettata dall&#8217;architetto Agostino Gurascio e sua [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114462"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=114462"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114462\/revisions"}],"predecessor-version":[{"id":114467,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/114462\/revisions\/114467"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=114462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=114462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=114462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}