{"id":11500,"date":"2013-02-23T13:12:24","date_gmt":"2013-02-23T13:12:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11500"},"modified":"2013-02-23T13:12:41","modified_gmt":"2013-02-23T13:12:41","slug":"topo-dauto-arrestato-a-surbo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/topo-dauto-arrestato-a-surbo\/","title":{"rendered":"TOPO D&#8217;AUTO SBADATO, ARRESTATO A SURBO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/topo-dauto-arrestato-a-surbo\/topoauto\/\" rel=\"attachment wp-att-11501\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/topoauto.jpg\" alt=\"\" width=\"600\" height=\"448\" class=\"alignleft size-full wp-image-11501\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/topoauto.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/topoauto-300x224.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>Nella nottata, durante un consueto giro di ispezione nell\u2019abitato di Surbo, in via Tagliamento, una pattuglia dei Carabinieri \u00a0ha proceduto al controllo di un\u2019autovettura sospetta, una Fiat Punto condotta da\u00a0<strong>Antonio Cal\u00f2<\/strong>. A poche centinaia di metri di distanza, veniva rinvenuta una BMW serie 5 con i vetri infranti, oggetto di una segnalazione telefonica di un solerte cittadino. Avvertita la proprietaria, era constatata la mancanza di vari effetti personali, tra i quali un navigatore satellitare, carte di credito e tessera bancomat. La perquisizione eseguita dall\u2019altra pattuglia sulla persona del Cal\u00f2 permetteva di rinvenire la refurtiva in questione. Una piccola nota di colore: sul sedile anteriore della BMW derubata il \u201cladro sbadato\u201d aveva dimenticato addirittura il proprio telefono cellulare: non avrebbe fatto molta strada. Il magistrato di turno, Sost. Proc. Dott.ssa Francesca Miglietta, ha disposto anche per Cal\u00f2 la sottoposizione agli arresti domiciliari. Saranno giudicati entrambi col rito direttissimo questa mattina in Tribunale.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/topo-dauto-arrestato-a-surbo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/topo-dauto-arrestato-a-surbo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nella nottata, durante un consueto giro di ispezione nell\u2019abitato di Surbo, in via Tagliamento, una pattuglia dei Carabinieri \u00a0ha proceduto al controllo di un\u2019autovettura sospetta, una Fiat Punto condotta da\u00a0Antonio Cal\u00f2. A poche centinaia di metri di distanza, veniva rinvenuta una BMW serie 5 con i vetri infranti, oggetto di una segnalazione telefonica di un [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11500"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11500"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11500\/revisions"}],"predecessor-version":[{"id":11505,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11500\/revisions\/11505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11501"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}