{"id":115085,"date":"2017-04-13T17:31:18","date_gmt":"2017-04-13T15:31:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=115085"},"modified":"2017-04-13T17:33:54","modified_gmt":"2017-04-13T15:33:54","slug":"una-barriera-che-crea-disservizi-le-proposte-di-imprenditori-e-commercianti-per-il-parcheggio-a-gallipoli","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/13\/una-barriera-che-crea-disservizi-le-proposte-di-imprenditori-e-commercianti-per-il-parcheggio-a-gallipoli\/","title":{"rendered":"UNA BARRIERA CHE CREA DISSERVIZI \/ LE PROPOSTE DEGLI IMPRENDITORI PER IL PARCHEGGIO A GALLIPOLI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1016\" height=\"1024\" title=\"A\" class=\"aligncenter size-large wp-image-115086\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/04\/A-1016x1024.jpg\" \/>Riceviamo e volentieri pubblichiamo. Da Gallipoli, Matteo Spada ci scrive______<\/p>\n<p>Nuova riunione nei giorni scorsi, \u00a0tra i soci dell\u2019Associazione Commercianti e Imprenditori di Gallipoli, \u00a0per individuare \u00a0una serie di proposte risolutive \u00a0riguardanti il \u201cnodo\u201d parcheggi. Idee da sottoporre poi all\u2019attenzione dell\u2019Amministrazione Comunale, nell\u2019ottica di una proficua collaborazione per il bene della citt\u00e0 e dei suoi cittadini.<\/p>\n<p>Di seguito il resoconto:<\/p>\n<p>\u201cParcheggiare nell\u2019area portuale di Gallipoli \u00e8 sempre pi\u00f9 difficile perch\u00e9 i posti sono pochi e l\u2019accesso con la barra elettronica comporta una serie di disservizi.<\/p>\n<p>Abbiamo raccolto il malcontento degli operatori commerciali, in particolar modo di quelli che si trovano nel centro storico, riguardo la gestione del parcheggio con la \u201cbarriera\u201d elettronica e la riduzione dei posti nell\u2019area portuale.<\/p>\n<p>Sono proprio gli operatori economici che si trovano nel borgo antico a risentire maggiormente della mancanza di posti auto e che non vorrebbero si ripetesse quanto accaduto lo scorso anno: caos e disagi. Meno parcheggi e meno presenze nel centro storico, per questo ogni giorno riceviamo lamentele di albergatori, ristoratori, commercianti e imprenditori (anche non associati) che sono sul piede di guerra e ci chiedono di sollecitare l\u2019Amministrazione per trovare una soluzione.<\/p>\n<p>A nostro avviso, che ci facciamo portavoce del tessuto economico della citt\u00e0, la barra elettronica non fa altro che creare ulteriori disagi.<\/p>\n<p>Davanti a questo accesso dovrebbe essere presente sempre un addetto alla sicurezza poich\u00e9 si sono verificati episodi in cui gli automobilisti sono rimasti intrappolati all\u2019interno del parcheggio, senza poter uscire. La barriera infatti si era bloccata e sono stati costretti a chiamare i carabinieri. Questa figura \u00e8 presente nel capitolato di spesa dell\u2019Amministrazione Comunale ma non vi \u00e8 nessun addetto. In altri casi ci sono stati dei problemi per l\u2019emissione del ticket di uscita: al momento del pagamento che non prevede l\u2019utilizzo delle carte di credito e solo monete di alcuni tagli specifici, ci sono stati dei guasti con il conseguente blocco dell\u2019emissione del biglietto.<\/p>\n<p>Inoltre la barriera non si solleva nel momento in cui il parcheggio risulta pieno: il problema \u00e8 che l\u2019automobilista giunto fino all\u2019area portuale deve poi tornare indietro e trovare un\u2019altra soluzione, perch\u00e9 non vi sono segnali, a debita distanza, che avvisino riguardo la disponibilit\u00e0 di posti auto e che invece andrebbero installati. Ci\u00f2 non crea solo un disagio all\u2019automobilista, ma porta soprattutto ad un\u2019ulteriore incidenza di traffico.<\/p>\n<p>Crediamo sia necessario potenziare, in vista della stagione estiva, le corse dei mezzi pubblici (Chiffi) e i collegamenti con le aree parcheggio della citt\u00e0, che si trovano in periferia. Per chi decide di venire con la propria auto, si potrebbe istituire un ticket giornaliero, settimanale o mensile: il turista che viene a visitare Gallipoli paga una cifra stabilita, con la quale, poi, ha diritto di parcheggiare su tutte le strisce blu della citt\u00e0.<\/p>\n<p>Sarebbe auspicabile, qualora non fosse possibile la realizzazione di quanto detto, pensare ad una riduzione graduale del costo del ticket in base al numero delle ore di sosta dell\u2019auto e prevedere uno sconto per il lavoratori e i residenti. Invitiamo l\u2019Amministrazione Comunale a valutare un sistema alternativo alla sbarra elettronica e, ad esempio, regolare il pagamento del parcheggio tramite i tradizionali parcometri che potrebbero essere installati nell\u2019area portuale ed essere gestisti da una cooperativa di giovani gallipolini, come avviene in paesi limitrofi\u201d.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/13\/una-barriera-che-crea-disservizi-le-proposte-di-imprenditori-e-commercianti-per-il-parcheggio-a-gallipoli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/13\/una-barriera-che-crea-disservizi-le-proposte-di-imprenditori-e-commercianti-per-il-parcheggio-a-gallipoli\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Da Gallipoli, Matteo Spada ci scrive______ Nuova riunione nei giorni scorsi, \u00a0tra i soci dell\u2019Associazione Commercianti e Imprenditori di Gallipoli, \u00a0per individuare \u00a0una serie di proposte risolutive \u00a0riguardanti il \u201cnodo\u201d parcheggi. Idee da sottoporre poi all\u2019attenzione dell\u2019Amministrazione Comunale, nell\u2019ottica di una proficua collaborazione per il bene della citt\u00e0 e dei suoi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":115086,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/115085"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=115085"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/115085\/revisions"}],"predecessor-version":[{"id":115088,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/115085\/revisions\/115088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/115086"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=115085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=115085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=115085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}