{"id":11548,"date":"2013-02-23T16:17:37","date_gmt":"2013-02-23T16:17:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11548"},"modified":"2013-02-23T20:00:18","modified_gmt":"2013-02-23T20:00:18","slug":"grillo-messaggio-agli-italiani","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/grillo-messaggio-agli-italiani\/","title":{"rendered":"GRILLO: MESSAGGIO AGLI ITALIANI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/grillo-messaggio-agli-italiani\/beppe-grillo-a-napoli-1\/\" rel=\"attachment wp-att-11549\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/Beppe-Grillo-a-Napoli-1.jpg\" alt=\"\" width=\"933\" height=\"660\" class=\"alignleft size-full wp-image-11549\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/Beppe-Grillo-a-Napoli-1.jpg 933w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/Beppe-Grillo-a-Napoli-1-300x212.jpg 300w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/a>La campagna elettorale \u00e8 terminata, tutti leader e leaderini hanno fatto l&#8217;appello al voto, chi parlando di voto utile, chi lo ha fatto con richiami all&#8217;ideologia, chi alla tasca, il messaggio di Grillo invece, ci pare che si possa sintetizzare con l&#8217;immagine a lato riportata.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/grillo-messaggio-agli-italiani\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/grillo-messaggio-agli-italiani\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La campagna elettorale \u00e8 terminata, tutti leader e leaderini hanno fatto l&#8217;appello al voto, chi parlando di voto utile, chi lo ha fatto con richiami all&#8217;ideologia, chi alla tasca, il messaggio di Grillo invece, ci pare che si possa sintetizzare con l&#8217;immagine a lato riportata. &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":11549,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11548"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11548"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11548\/revisions"}],"predecessor-version":[{"id":11552,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11548\/revisions\/11552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11549"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}