{"id":11559,"date":"2013-02-23T20:14:02","date_gmt":"2013-02-23T20:14:02","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11559"},"modified":"2013-02-23T20:14:02","modified_gmt":"2013-02-23T20:14:02","slug":"cane-o-gatto-per-me-pari-sono","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/cane-o-gatto-per-me-pari-sono\/","title":{"rendered":"CANE O GATTO PER ME PARI SONO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><em>\u00a0<a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/cane-o-gatto-per-me-pari-sono\/cane-e-gatto-copia\/\" rel=\"attachment wp-att-11560\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/cane-e-gatto-copia.jpg\" alt=\"\" width=\"282\" height=\"348\" class=\"alignleft size-full wp-image-11560\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/cane-e-gatto-copia.jpg 282w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/cane-e-gatto-copia-243x300.jpg 243w\" sizes=\"(max-width: 282px) 100vw, 282px\" \/><\/a><\/em><em>\u201cSar\u00e0 il Servizio Veterinario dell\u2019Asl.<\/em> &#8211; fa sapere con una nota l\u2019assessore alle Politiche Ambientali, Andrea Guido<em> &#8211; a dover procedere con le operazioni di riconoscimento, cura e sterilizzazione delle colonie feline presenti sul territorio\u201d. <\/em>\u00a0<em>\u201cL\u2019Amministrazione Comunale &#8211;<\/em> spiega Guido &#8211;<em> ha gi\u00e0 fatto ci\u00f2 che era in suo potere per tutelare e preservare la salute di questi animali; \u00a0\u00e8 compito del Servizio Sanitario contenere il fenomeno del randagismo con una stabilizzazione del numero di gatti presenti. Lo scorso novembre abbiamo dato il via libera all\u2019avviso pubblico rivolto alla cittadinanza e, in particolare alle Associazioni animaliste, per avviare il censimento di tutte le colonie feline della citt\u00e0 con l\u2019obiettivo di preservarne la salute e garantire al contempo la salubrit\u00e0 dei luoghi in cui sono stanziate. L\u2019iniziativa ha gi\u00e0 dato i suoi frutti: siamo in possesso della mappatura di tutte le colonie sul territorio comunale, 36, per l\u2019esattezza. Sar\u00e0 mia cura, adesso, fare tutto il possibile per coadiuvare il lavoro del Dipartimento di Prevenzione del \u00a0Servizio Veterinario della Asl sollecitando e verificandone, all\u2019occorrenza, l\u2019operato\u201d.<\/em><\/p>\n<p>In riferimento alla segnalazione pervenuta in questi giorni dal Comitato Consultivo Difesa Animali e alla denuncia presentata da Antonio Menduni, responsabile locale dell&#8217;Ente Nazionale Protezione Animali (Enpa), secondo cui l\u2019Amministrazione &#8211; e l\u2019Assessorato alle Politiche\u00a0 Ambientali\u00a0 in particolare &#8211; avrebbe\u00a0 trascurato i 300 gatti, distribuiti tra la colonia del Cimitero, quella dell&#8217;ex sperimentale Tabacchi, del Vecchio ospedale Galateo, del museo civico e dell&#8217;Universit\u00e0 (notizia, peraltro diffusa da alcune testate giornalistiche) l\u2019assessore Andrea Guido tiene a precisare che<em> \u201c\u00e8 stato gi\u00e0 fatto tutto ci\u00f2 che rientrava nelle competenze e nel potere del Comune ma, che, in ogni caso, non verr\u00e0 certo abbassata la guardia\u201d . <\/em><\/p>\n<p><em>\u00a0\u201cSono convinto &#8211; <\/em>conclude Andrea Guido &#8211;<em> che, cos\u00ec come \u00e8 avvenuto per il canile sanitario comunale, a breve riusciremo a trovare una soluzione definitiva al problema, magari attraverso un piano d\u2019intervento ad hoc del Servizio Veterinario. Oggi, grazie al trasferimento di 30 cani presso altra struttura, di concerto con l\u2019Asl, \u00a0l\u2019ambulatorio veterinario presso la sede del canile sanitario \u00e8 stato ripristinato. Inoltre, con il nuovo bando per l\u2019individuazione di una nuova e pi\u00f9 adeguata struttura &#8211; pubblicato proprio in questi giorni \u00a0&#8211; riusciremo ad avviare l\u2019intervento definitivo che in poco tempo porter\u00e0 ad una totale soluzione del problema\u201d. <\/em><\/p>\n<p><em>\u201cIn passato &#8211;<\/em> ricorda Guido &#8211;<em> questa Amministrazione si \u00e8 prodigata a dovere per garantire il benessere e il sostentamento dei gatti. Dopo la mappatura delle colonie feline presenti sul territorio comunale la competenza \u00e8 passata nelle mani della Asl. Ad ogni buon conto personalmente \u2013 attraverso l\u2019associazione Veri Amici \u2013 sono pronto a dare il mio contributo fattivo, cos\u00ec come ho fatto oggi acquistando a mie spese il cibo per metterlo a disposizione dei 300 gatti che si trovano in citt\u00e0. Intendo rassicurare, dunque, \u00a0tutti i leccesi amanti dei gatti che, cos\u00ec come \u00e8 stato affrontato e risolto il problema dei cani derivante dal sovraffollamento della struttura sanitaria comunale, faremo di tutto per assicurare il benessere delle colonie feline in citt\u00e0\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/cane-o-gatto-per-me-pari-sono\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/cane-o-gatto-per-me-pari-sono\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a0\u201cSar\u00e0 il Servizio Veterinario dell\u2019Asl. &#8211; fa sapere con una nota l\u2019assessore alle Politiche Ambientali, Andrea Guido &#8211; a dover procedere con le operazioni di riconoscimento, cura e sterilizzazione delle colonie feline presenti sul territorio\u201d. \u00a0\u201cL\u2019Amministrazione Comunale &#8211; spiega Guido &#8211; ha gi\u00e0 fatto ci\u00f2 che era in suo potere per tutelare e preservare la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11560,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11559"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11559"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11559\/revisions"}],"predecessor-version":[{"id":11562,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11559\/revisions\/11562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11560"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}