{"id":11568,"date":"2013-02-23T20:27:25","date_gmt":"2013-02-23T20:27:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11568"},"modified":"2013-02-23T20:27:25","modified_gmt":"2013-02-23T20:27:25","slug":"sequestrato-il-villaggio-turistico-riva-degli-angeli","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/sequestrato-il-villaggio-turistico-riva-degli-angeli\/","title":{"rendered":"SEQUESTRATO IL VILLAGGIO TURISTICO \u201cRIVA DEGLI ANGELI\u201d"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/sequestrato-il-villaggio-turistico-riva-degli-angeli\/4-3\/\" rel=\"attachment wp-att-11569\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/41.jpg\" alt=\"\" width=\"1024\" height=\"678\" class=\"alignleft size-full wp-image-11569\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/41.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/41-300x198.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>Una grande e nota struttura ricettiva di Porto Cesareo, il villaggio \u201cRiva degli Angeli\u201d, \u00e8 da stamattina sottoposta a sequestro probatorio.<\/p>\n<p>I Carabinieri del Nucleo Operativo \u2013 Aliquota Operativa della Compagnia di Campi Salentina, infatti, hanno apposto i sigilli agli immobili che compongono il complesso, esteso su una vasta area della frazione cesarina di Torre Lapillo e la cui propriet\u00e0 \u00e8 riconducibile all\u2019imprenditore\u00a0<strong>Giuseppe DURANTE<\/strong>, che ricopre attualmente anche la carica di Consigliere comunale presso il Comune di Porto Cesareo.<\/p>\n<p>Il tutto, in esecuzione di un decreto di sequestro emesso dalla Procura della Repubblica presso il Tribunale di Lecce e firmato dal Sostituto Procuratore dott.ssa\u00a0<strong>Carmen Ruggiero<\/strong>, adottato alla luce di accertamenti preliminari effettuati nei giorni scorsi presso quel villaggio.<\/p>\n<p>I militari del Nucleo Operativo di Campi Salentina, infatti, sono notoriamente impegnanti da mesi in indagini serrate relative agli attentati dinamitardi perpetrati nella localit\u00e0 ionica tra il 17 maggio e il 15 novembre dello scorso anno.<\/p>\n<p>L\u2019attivit\u00e0 informativa svolta a tappeto ha per\u00f2 consentito di estendere lo sguardo degli investigatori anche su altri fronti che poi stanno sfociando in altrettante indagini.<\/p>\n<p>In una di queste occasioni \u00e8 emersa la notizia secondo cui presso il \u201cRiva degli Angeli\u201d alcune costruzioni potessero essere state realizzate in difformit\u00e0 da autorizzazioni o, comunque, dalla disciplina edilizia o ambientale in vigore.<\/p>\n<p>Di qui l\u2019iniziativa gi\u00e0 assunta il 19 febbraio, quando \u2013 su delega sempre del Pubblico Ministero dott.ssa Ruggiero &#8211; i Carabinieri si sono presentati presso l\u2019Ufficio Tecnico del Comune di Porto Cesareo per acquisire tutta la documentazione amministrativa utile agli accertamenti.<\/p>\n<p>Passo successivo, l\u2019essersi presentati ai cancelli del villaggio, ove effettuare un sopralluogo preliminare e verificare l\u2019eventuale fondamento di quelle voci.<\/p>\n<p>Insieme a loro, un architetto li ha accompagnati in qualit\u00e0 di \u201causiliario di polizia giudiziaria\u201d.<\/p>\n<p>L\u2019esito di quel sopralluogo ha lasciato pochi dubbi nei controllori, sfociati in un\u2019apposita formale segnalazione all\u2019Autorit\u00e0 giudiziaria.<\/p>\n<p>In sostanza, il complesso edilizio (che sorge in zona sottoposta a vincolo paesaggistico ed archeologico) appare costituito in parte da opere eseguite in \u201c<em>macroscopica difformit\u00e0<\/em>\u201d rispetto ai permessi di costruire rilasciati, oltre che, in altra parte, da opere \u201c<em>realizzate in totale assenza di permesso di costruire e di autorizzazione paesaggistica<\/em>\u201d.<\/p>\n<p>Una simile situazione richiede per\u00f2 un\u2019indagine ancora pi\u00f9 approfondita, da affidarsi a un consulente tecnico che determini consistenza e natura delle opere realizzate, nonch\u00e9 la loro legittimit\u00e0 alla luce di provvedimenti amministrativi e degli strumenti urbanistici vigenti a Porto Cesareo.<\/p>\n<p>Nell\u2019attesa, le esigenze probatorie hanno imposto l\u2019emissione di un decreto di sequestro, notificato stamane proprio a\u00a0<strong>Giuseppe DURANTE<\/strong>\u00a0dai Carabinieri della Compagnia di Campi Salentina che poi, nell\u2019arco di durante una sessione di operazioni durate circa due ore, hanno apposto materialmente i sigilli alla struttura.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\"><br \/>\n<\/span><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/sequestrato-il-villaggio-turistico-riva-degli-angeli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/23\/sequestrato-il-villaggio-turistico-riva-degli-angeli\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Una grande e nota struttura ricettiva di Porto Cesareo, il villaggio \u201cRiva degli Angeli\u201d, \u00e8 da stamattina sottoposta a sequestro probatorio. I Carabinieri del Nucleo Operativo \u2013 Aliquota Operativa della Compagnia di Campi Salentina, infatti, hanno apposto i sigilli agli immobili che compongono il complesso, esteso su una vasta area della frazione cesarina di Torre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11569,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11568"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11568"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11568\/revisions"}],"predecessor-version":[{"id":11571,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11568\/revisions\/11571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11569"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}