{"id":11855,"date":"2013-02-28T08:21:48","date_gmt":"2013-02-28T08:21:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11855"},"modified":"2013-02-28T08:22:03","modified_gmt":"2013-02-28T08:22:03","slug":"lassessore-luigi-coclite-e-le-sue-donne","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/lassessore-luigi-coclite-e-le-sue-donne\/","title":{"rendered":"L&#8217;ASSESSORE LUIGI COCLITE E LE &#8220;SUE DONNE&#8221;"},"content":{"rendered":"<p><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/lassessore-luigi-coclite-e-le-sue-donne\/coclite-gigi\/\" rel=\"attachment wp-att-11856\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/coclite-gigi.jpg\" alt=\"\" width=\"121\" height=\"150\" class=\"alignleft size-full wp-image-11856\" \/><\/a>Presentata oggi a Palazzo Carafa la quindicesima edizione della rassegna culturale che vede come protagonista la donna.<\/em>E\u2019 stata presentata questa mattina all\u2019Open Space di Palazzo Carafa, la quindicesima edizione di <strong><em>Itinerario Rosa<\/em><\/strong>, la rassegna culturale che guarda con attenzione al ruolo esercitato dalla donna nella societ\u00e0 moderna.<\/p>\n<p>Numerosissimi gli appuntamenti inseriti nel cartellone tra concerti, mostre di pittura e di fotografia, poesie, recital, performances teatrali e musicali, installazioni, laboratori d\u2019arte, di ricamo, di scrittura e letteratura, esposizioni artigianali, rassegne, conferenze, convegni, tavole rotonde. Protagoniste \u00e8 la donna nelle sue mille sfaccettature.\u00a0 <em>\u201cDonne come quella <\/em>\u2013\u00a0 spiega l\u2019assessore agli Spettacoli e agli Eventi,<em> <\/em><strong>Luigi Coclite<\/strong> &#8211;<em> ritratta in una foto che risale a 57 anni fa: una casalinga di colore che un bel giorno, mentre era in un autobus, decise di non alzarsi per lasciare il suo posto ad un uomo bianco. Sono donne che con piccoli grandi gesti quotidiani hanno cambiato il mondo. A loro abbiamo voluto dedicare il manifesto realizzato quest\u2019anno per la quindicesima edizione di Itinerario Rosa\u201d. <\/em><\/p>\n<p>L\u2019assessore Coclite ha poi ringraziato tutte le associazioni che hanno voluto prendere parte a questa rassegna pur i mancanza di risorse economiche da parte dell\u2019Amministrazione Comunale<em>. \u201cUna rassegna <\/em>\u2013 ha concluso \u2013<em> che assume maggiore valenza alla luce del fatto che il nuovo Parlamento italiano, appena eletto, sar\u00e0 costituito per un terzo da donne\u201d.<\/em><\/p>\n<p><strong><em>Itinerario Rosa<\/em><\/strong><em> <\/em>\u00e8 stato organizzato dall\u2019Assessorato alla Cultura del Comune di Lecce.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/lassessore-luigi-coclite-e-le-sue-donne\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/lassessore-luigi-coclite-e-le-sue-donne\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Presentata oggi a Palazzo Carafa la quindicesima edizione della rassegna culturale che vede come protagonista la donna.E\u2019 stata presentata questa mattina all\u2019Open Space di Palazzo Carafa, la quindicesima edizione di Itinerario Rosa, la rassegna culturale che guarda con attenzione al ruolo esercitato dalla donna nella societ\u00e0 moderna. Numerosissimi gli appuntamenti inseriti nel cartellone tra concerti, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11856,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11855"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11855"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11855\/revisions"}],"predecessor-version":[{"id":11860,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11855\/revisions\/11860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11856"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}