{"id":118865,"date":"2017-05-25T00:11:15","date_gmt":"2017-05-24T22:11:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=118865"},"modified":"2017-05-24T21:23:48","modified_gmt":"2017-05-24T19:23:48","slug":"una-vita-a-sud-est","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/05\/25\/una-vita-a-sud-est\/","title":{"rendered":"UNA VITA A SUD EST &#8216;STASERA A LECCE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" title=\"13094398_10208249708112625_2805969922427697574_n\" class=\"alignleft size-medium wp-image-118867\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/13094398_10208249708112625_2805969922427697574_n-300x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/13094398_10208249708112625_2805969922427697574_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/13094398_10208249708112625_2805969922427697574_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/13094398_10208249708112625_2805969922427697574_n-768x770.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/13094398_10208249708112625_2805969922427697574_n-60x60.jpg 60w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/13094398_10208249708112625_2805969922427697574_n.jpg 957w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(s.d.)______Verr\u00e0 presentato presso il Fondo Verri di Lecce, gioved\u00ec 25 maggio 2017, alle ore 19.30, il libro \u2018Frammenti di vita pendolare\u2019 di <strong>Annatonia Margiotta <\/strong>(nella foto). Il volume, edito dalla casa editrice leccese Edizioni Citt\u00e0 Futura, racconta uno spaccato di vita quotidiana in cui molta gente si ritrova a viaggiare ogni giorno per motivi di lavoro, studio o altro.<\/p>\n<p>La scrittrice mette nero su bianco tutto ci\u00f2 che lei stessa ha potuto osservare e vivere direttamente da pendolare su quel treno che ogni mattina la porta dal Salento a Bari. Un\u2019 esperienza comune, dalla quale per\u00f2 nascono diverse situazioni come la battaglia contro i disagi ferroviari fatti di scioperi del personale, di grandi ritardi, di treni spesso poco curati nell\u2019igiene e scomodi, di corse per accaparrarsi un posto libero e non rischiare di viaggiare in piedi.<\/p>\n<p>Tante le diverse tipologie di pendolari che si possono incontrare su un treno, tra questi c\u2019\u00e8 chi ama conversare sui temi attuali e seri o su questioni personali, chi preferisce ridere e scherzare in maniera goliardica e chi si immerge nel mondo virtuale di tablet e smartphone o in libri e giornali. Nel saggio emergono soprattutto gli aspetti sociali della vita pendolare, ponendo risalto ai rapporti umani che ne possono nascere, amicizie che giorno dopo giorno crescono tra persone che condividono ore importanti della loro esistenza. Una vera e propria comunit\u00e0 di viaggiatori per i quali il treno diventa quasi una seconda casa e i compagni di viaggio si trasformano in individui la cui presenza aiuta a alleggerire la fatica di quel percorso a volte interminabile dopo una giornata di lavoro o studio.<\/p>\n<p>Durante l\u2019incontro legger\u00e0 alcuni passi tratti dal libro l\u2019attore Simone Franco, dialogher\u00e0 con l\u2019autrice Mauro Marino.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/05\/25\/una-vita-a-sud-est\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/05\/25\/una-vita-a-sud-est\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(s.d.)______Verr\u00e0 presentato presso il Fondo Verri di Lecce, gioved\u00ec 25 maggio 2017, alle ore 19.30, il libro \u2018Frammenti di vita pendolare\u2019 di Annatonia Margiotta (nella foto). Il volume, edito dalla casa editrice leccese Edizioni Citt\u00e0 Futura, racconta uno spaccato di vita quotidiana in cui molta gente si ritrova a viaggiare ogni giorno per motivi di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":118867,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/118865"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=118865"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/118865\/revisions"}],"predecessor-version":[{"id":118872,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/118865\/revisions\/118872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/118867"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=118865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=118865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=118865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}