{"id":119049,"date":"2017-05-26T06:03:51","date_gmt":"2017-05-26T04:03:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=119049"},"modified":"2017-05-26T19:15:24","modified_gmt":"2017-05-26T17:15:24","slug":"iniziativa-del-candidato-sindaco-del-movimento-5-stelle-fabio-valente-per-gli-assessori-cittadini","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/05\/26\/iniziativa-del-candidato-sindaco-del-movimento-5-stelle-fabio-valente-per-gli-assessori-cittadini\/","title":{"rendered":"INIZIATIVA DEL CANDIDATO SINDACO DEL MOVIMENTO 5 STELLE FABIO VALENTE PER GLI ASSESSORI &#8211; CITTADINI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"678\" height=\"381\" title=\"18155416_1044392072371095_1151716286_n\" class=\"alignleft size-full wp-image-119050\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/18155416_1044392072371095_1151716286_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/18155416_1044392072371095_1151716286_n.jpg 678w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/05\/18155416_1044392072371095_1151716286_n-300x169.jpg 300w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/>Riceviamo e volentieri pubblichiamo. Il candidato a sindaco del M5S Fabio Valente (al centro, nella foto)\u00a0ci manda il seguente comunicato______<\/p>\n<p>Assessori nominati con Bando pubblico: &#8220;Decine i curricula pervenuti, la citt\u00e0 vuole cambiare&#8221;.\u00a0Sono decine i curricula dei cittadini che riceviamo in questi giorni e che chiedono di partecipare al nostro &#8220;Bando pubblico per gli assessori&#8221;. L&#8217;entusiasmo che riscontriamo nei leccesi ci conferma che siamo nella giusta direzione: la citt\u00e0 vuole partecipare attivamente alla vita amministrativa. Inoltre, abbiamo gi\u00e0 ricevuto diverse candidature che ambiscono alla delega alla Legalit\u00e0.<\/p>\n<p>Quest&#8217;ultima, anche alla luce delle note vicende giudiziarie che hanno coinvolto personaggi di spicco della politica leccese, \u00e8 per noi la garanzia che la macchina amministrativa dovr\u00e0 essere gestita nella pi\u00f9 totale trasparenza e rispetto delle regole. Il futuro Assessore alla Legalit\u00e0 sar\u00e0 emblema di quella rigenerazione politica che il Movimento 5 Stelle attua in ogni citt\u00e0 in cui \u00e8 chiamata a governare.<\/p>\n<p>Siamo l&#8217;unica forza in campo, oggi, a non assegnare deleghe sulla scorta degli accordi elettorali di coalizione: votare per il Movimento 5 Stelle significa lasciare aperta a chiunque la possibilit\u00e0 di ricoprire un ruolo importante all&#8217;interno dell&#8217;amministrazione.<\/p>\n<p>Da citt\u00e0 a 5 Stelle, Lecce cambier\u00e0. Conoscer\u00e0 finalmente la partecipazione democratica. Torner\u00e0 ad essere di tutti.______<\/p>\n<p>LA RICERCA nel nostro articolo del 24 aprile scorso<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/24\/inedita-iniziativa-del-candidato-a-sindaco-del-m5s-rivolta-a-tutti-i-cittadini-lecesi-fabio-valente-mandatemi-subito-il-vostro-curriculum-gli-assessori-li-scegliero-cosi-fra-di-voi\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/24\/inedita-iniziativa-del-candidato-a-sindaco-del-m5s-rivolta-a-tutti-i-cittadini-lecesi-fabio-valente-mandatemi-subito-il-vostro-curriculum-gli-assessori-li-scegliero-cosi-fra-di-voi\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/05\/26\/iniziativa-del-candidato-sindaco-del-movimento-5-stelle-fabio-valente-per-gli-assessori-cittadini\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/05\/26\/iniziativa-del-candidato-sindaco-del-movimento-5-stelle-fabio-valente-per-gli-assessori-cittadini\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il candidato a sindaco del M5S Fabio Valente (al centro, nella foto)\u00a0ci manda il seguente comunicato______ Assessori nominati con Bando pubblico: &#8220;Decine i curricula pervenuti, la citt\u00e0 vuole cambiare&#8221;.\u00a0Sono decine i curricula dei cittadini che riceviamo in questi giorni e che chiedono di partecipare al nostro &#8220;Bando pubblico per gli assessori&#8221;. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":119050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/119049"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=119049"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/119049\/revisions"}],"predecessor-version":[{"id":119055,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/119049\/revisions\/119055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/119050"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=119049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=119049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=119049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}