{"id":11970,"date":"2013-03-01T08:24:23","date_gmt":"2013-03-01T08:24:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11970"},"modified":"2013-03-01T08:24:23","modified_gmt":"2013-03-01T08:24:23","slug":"sicurezza-stradale-e-piani-di-segnalamento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/01\/sicurezza-stradale-e-piani-di-segnalamento\/","title":{"rendered":"\u201cSICUREZZA STRADALE E PIANI DI SEGNALAMENTO\u201d"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">OGGI AL \u201cCASTROMEDIANO\u201d A LECCE\u00a0UNA GIORNATA CON DOCENTI UNIVESITARI IL DIRIGENTE DEL MIT MAZZIOTTA<br \/>\n<span style=\"text-decoration: underline\">Oggi, venerd\u00ec 1 marzo, a partire dalle ore 9.30<\/span>, nell\u2019auditorium del Museo provinciale \u201cSigismondo Castromediano\u201d, la Provincia di Lecce, insieme all\u2019Associazione Italiana Ingegneria del Traffico e dei Trasporti Puglia e Basilicata, ha organizzato e promosso una giornata di studio<strong> <\/strong>su<strong> <\/strong>\u201c<strong>Sicurezza stradale e piani di segnalamento<\/strong>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Si tratta di un\u2019opportunit\u00e0 offerta ai tecnici degli enti locali, agli operatori della progettazione e della manutenzione delle strade e della segnaletica, alle forze di polizia municipale, sui temi sempre attuali dell\u2019applicazione del Codice della Strada, che vedr\u00e0 la partecipazione di docenti di varie universit\u00e0 italiane e del dirigente del Ministero delle Infrastrutture e trasporti, gi\u00e0 componente del Consiglio nazionale dei Lavori Pubblici, ingegnere <strong>Francesco Mazziotta<\/strong>.<\/p>\n<p>I lavori saranno aperti dall\u2019indirizzo di saluto del presidente della Provincia di Lecce <strong>Antonio Gabellone<\/strong>.<\/p>\n<p>Seguiranno gli interventi di <strong>Stefano Zampino<\/strong>, dirigente Provincia di Lecce e presidente Associazione Italiana Ingegneria del Traffico e dei Trasporti Puglia e Basilicata (\u201c<em>Sicurezza stradale e segnaletica: dalla gestione al progetto<\/em>\u201d), di <strong>Felice Giuliani<\/strong>, dell\u2019Universit\u00e0 agli Studi di Parma e direttore del Centro Studi e Ricerche Aiit (\u201c<em>I materiali per la segnaletica stradale: costituzione e caratteristiche prestazionali<\/em>\u201d), di <strong>Giuseppe Cantisani<\/strong>, ricercatore di strade, ferrovie e aeroporti Universit\u00e0 La Sapienza di Roma (\u201c<em>I Piani di segnalamento: criteri di progetto e contenuti<\/em>\u201d) e di <strong>Francesco Mazziotta<\/strong>, dirigente del Ministero delle Infrastrutture e trasporti, gi\u00e0 componente del Consiglio nazionale dei Lavori Pubblici (\u201c<em>La normativa sulla segnaletica<\/em>\u201d). I lavori saranno coordinati dal docente universitario e ingegnere <strong>Giulio Maternini<\/strong>.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/01\/sicurezza-stradale-e-piani-di-segnalamento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/01\/sicurezza-stradale-e-piani-di-segnalamento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>OGGI AL \u201cCASTROMEDIANO\u201d A LECCE\u00a0UNA GIORNATA CON DOCENTI UNIVESITARI IL DIRIGENTE DEL MIT MAZZIOTTA Oggi, venerd\u00ec 1 marzo, a partire dalle ore 9.30, nell\u2019auditorium del Museo provinciale \u201cSigismondo Castromediano\u201d, la Provincia di Lecce, insieme all\u2019Associazione Italiana Ingegneria del Traffico e dei Trasporti Puglia e Basilicata, ha organizzato e promosso una giornata di studio su \u201cSicurezza [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11970"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11970"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11970\/revisions"}],"predecessor-version":[{"id":11971,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11970\/revisions\/11971"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}