{"id":119815,"date":"2017-06-06T00:02:15","date_gmt":"2017-06-05T22:02:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=119815"},"modified":"2017-06-06T09:01:44","modified_gmt":"2017-06-06T07:01:44","slug":"diario-del-giorno-prima-il-tam-tam-di-annibale-436","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/06\/06\/diario-del-giorno-prima-il-tam-tam-di-annibale-436\/","title":{"rendered":"DIARIO DEL GIORNO PRIMA \/ IL TAM TAM DI ANNIBALE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"493\" height=\"271\" title=\"ITALY-MAFIA-TOTO RIINA\" class=\"aligncenter size-full wp-image-119826\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/06\/riina1.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/06\/riina1.jpg 493w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/06\/riina1-300x165.jpg 300w\" sizes=\"(max-width: 493px) 100vw, 493px\" \/>ITALIA______<\/p>\n<div><strong>BOLOGNA &#8211; <\/strong>In nome del diritto ad una &#8216;morte dignitosa&#8217;, la prima sezione penale della Corte di cassazione, con la sentenza 27766 di oggi, ha annullato l&#8217;ordinanza con la quale il tribunale di sorveglianza di Bologna (il 20 maggio del 2016) aveva rigettato la richiesta di differimento dell&#8217;esecuzione della pena o, in subordine, di detenzione domiciliare presentata da Salvatore Riina a causa delle gravissime condizioni di salute del boss di Cosa nostra. Il tribunale, in sede di rinvio, dovr\u00e0 dunque condurre il nuovo esame attenendosi ai criteri fissati dalla Suprema corte. In particolare il collegio, nel motivare la bocciatura, afferma che dall&#8217;ordinanza impugnata non emerge in che modo &#8216;si \u00e8 giunti a ritenere compatibile con le molteplici funzioni della pena e con il senso di umanit\u00e0 che la nostra costituzione e la convenzione E.d.u. impongono nell&#8217;esecuzione della stessa, il mantenimento in carcere in luogo della detenzione domiciliare, di un soggetto ultraottantenne, affetto da duplice neoplasia renale, con una situazione neurologica altamente compromessa, tanto da essere allettato con materasso antidecubito e non autonomo nell&#8217;assumere una posizione seduta, esposto, in ragione di una grave cardiopatia ad eventi cardiovascolari infausti e non prevedibili&#8217;.<\/div>\n<p>&nbsp;<\/p>\n<p>ITALIA______<\/p>\n<div><strong>TARANTO &#8211; <\/strong>Il ministro dello Sviluppo Economico Carlo Calenda ha firmato il decreto di aggiudicazione del Gruppo Ilva ad Am Investco, la joint-venture composta da ArcelorMittal e Marcegaglia. Il decreto autorizza infatti i Commissari straordinari del Gruppo Ilva, in amministrazione straordinaria, a procedere alla aggiudicazione dei complessi aziendali del gruppo Ilva S.p.A ad Am Investco Italy, il cui capitale sociale risulta detenuto da ArcelorMittal Italy Holding (51%), ArcelorMittal S.A. (34%) e Marcegaglia Carbon Steel S.p.A. (15%). E&#8217; quanto si legge in una nota del ministero.<\/div>\n<div><\/div>\n<p>MONDO______<\/p>\n<div><strong>LONDRA &#8211; <\/strong>La polizia britannica ha diffuso le generalit\u00e0 di due dei tre responsabili degli attacchi terroristici di sabato a Londra, rivendicati dall&#8217;Isis. Gli assalitori sono stati uccisi dalla polizia dopo avere causato la morte di sette persone e il ferimento di altre 48, prima investendo passanti sul London Bridge e poi compiendo un attacco con coltelli al Borough Market. Si tratta di Khuram Butt, nome anticipato dalla Bbc, e di Rachid Redouane. Butt aveva 27 anni, era sposato con figli, viveva a Barking, zona Est di Londra, in un&#8217;abitazione perquisita ieri. Di origini pachistane, considerato capo della cellula, era apparso in un documentario dell&#8217;emittente Channel 4 sui fondamentalisti islamici legati ad Anjem Choudary, un predicatore in carcere. Butt era conosciuto dai servizi di sicurezza britannici, ma non c&#8217;era nessuna prova che stesse pianificando un attentato.<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/06\/06\/diario-del-giorno-prima-il-tam-tam-di-annibale-436\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/06\/06\/diario-del-giorno-prima-il-tam-tam-di-annibale-436\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ITALIA______ BOLOGNA &#8211; In nome del diritto ad una &#8216;morte dignitosa&#8217;, la prima sezione penale della Corte di cassazione, con la sentenza 27766 di oggi, ha annullato l&#8217;ordinanza con la quale il tribunale di sorveglianza di Bologna (il 20 maggio del 2016) aveva rigettato la richiesta di differimento dell&#8217;esecuzione della pena o, in subordine, di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":119826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/119815"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=119815"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/119815\/revisions"}],"predecessor-version":[{"id":119825,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/119815\/revisions\/119825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/119826"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=119815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=119815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=119815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}