{"id":12088,"date":"2013-03-03T11:19:51","date_gmt":"2013-03-03T11:19:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12088"},"modified":"2013-03-03T11:19:52","modified_gmt":"2013-03-03T11:19:52","slug":"il-comune-ci-ripensa-circo-orfei-lattivita-proseguira-fino-al-3-marzo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/03\/il-comune-ci-ripensa-circo-orfei-lattivita-proseguira-fino-al-3-marzo\/","title":{"rendered":"IL COMUNE CI RIPENSA. CIRCO ORFEI, L\u2019ATTIVITA\u2019 PROSEGUIRA\u2019 FINO AL 3 MARZO"},"content":{"rendered":"<p><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/03\/il-comune-ci-ripensa-circo-orfei-lattivita-proseguira-fino-al-3-marzo\/guido-circo\/\" rel=\"attachment wp-att-12090\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/guido-CIRCO-684x1024.jpg\" alt=\"\" width=\"684\" height=\"1024\" class=\"alignleft size-large wp-image-12090\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/guido-CIRCO-684x1024.jpg 684w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/guido-CIRCO-200x300.jpg 200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/guido-CIRCO.jpg 1000w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/a>Il provvedimento dell\u2019Amministrazione Comunale \u00e8 stato adottato in seguito all\u2019avvenuta integrazione da parte dei gestori della struttura della documentazione presentata. Ma gli illeciti riscontrati saranno al vaglio dell\u2019autorit\u00e0 giudiziaria<\/em><\/p>\n<p>L\u2019Amministrazione Comunale intende dare agli operatori circensi attendati a Lecce la possibilit\u00e0 di continuare l\u2019attivit\u00e0 fino alla data fissata del 3 marzo. Resta ferma, tuttavia,\u00a0 l\u2019impossibilit\u00e0 ad ignorare gli illeciti riscontrati, di natura amministrativa e penale, che saranno al vaglio degli organi preposti.<\/p>\n<p>La decisione \u00e8 stata adottata nella tarda mattinata di oggi dall\u2019assessore <strong>Andrea Guido<\/strong>, di concerto con il sindaco Paolo Perrone, al termine della conferenza stampa tenutasi oggi nella sala giunta di Palazzo Carafa durante la quale \u00e8 stata ampiamente discussa e motivata l\u2019ordinanza firmata dal dirigente del settore Attivit\u00e0 Economiche e Produttive-Ufficio Polizia Amministrativa del Comune di Lecce con la quale era stata disposta l\u2019immediata sospensione degli spettacoli\u00a0 del circo di Marina Orfei e la conseguente immediata operazione di smontaggio della struttura<\/p>\n<p>Il nuovo provvedimento dell\u2019Amministrazione Comunale \u00e8 stato adottato, in particolare, in seguito all\u2019avvenuta integrazione da parte dei gestori del Circo della documentazione presentata a corredo dell\u2019istanza originaria ai fini l\u2019ottenimento dell\u2019autorizzazione Comunale allo svolgimento dell\u2019attivit\u00e0 e in seguito anche alla soluzione delle problematiche ambientali causate dalla struttura e dalla compagine circense nell\u2019area destinata agli spettacoli.<\/p>\n<p><em>\u201cDi concerto con il sindaco &#8211; <\/em>afferma l\u2019assessore <strong>Andrea Guido<\/strong> &#8211; <em>ho deciso, viste le immediate iniziative poste in essere dalla societ\u00e0 che gestisce il Circo di Marina Orfei per risolvere e porre rimedio alle problematiche riscontrate e che hanno determinato l\u2019adozione del provvedimento del dirigente Paolo Rollo e l\u2019informativa inviata alla Magistratura da parte del Comando della Polizia Municipale,\u00a0 di concedere un\u2019ulteriore chance alla compagine della signora Marina Monti Condesnitt \u201d. <\/em><\/p>\n<p><em>\u201cPer evitare il rischio <\/em>&#8211; spiega <strong>Guido<\/strong> &#8211;<em> di procurare un grave danno economico alla famiglie degli operatori a seguito del circo, situazione che, a quanto pare, non \u00e8 tra le pi\u00f9 floride, ho preferito ammorbidire la mia posizione. Peraltro, sono venuto a conoscenza anche di vicende che sul piano umano mi hanno rattristato imponendomi una profonda riflessione. Per queste ragioni ho messo da parte anche gli attacchi rivolti in pubbliche sedi alla mia persona e al ruolo istituzionale che rivesto optando per una soluzione pi\u00f9 accomodante della vicenda anche se le\u00a0 responsabilit\u00e0 della cattiva condotta degli operatori circensi verranno valutate in altre e pi\u00f9 opportune sedi. Non avrei mai sopportato di arrecare danno a persone che nulla hanno a che vedere con gli illeciti riscontrati, per i quali saranno solo i responsabili a pagare\u201d.<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/03\/il-comune-ci-ripensa-circo-orfei-lattivita-proseguira-fino-al-3-marzo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/03\/il-comune-ci-ripensa-circo-orfei-lattivita-proseguira-fino-al-3-marzo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il provvedimento dell\u2019Amministrazione Comunale \u00e8 stato adottato in seguito all\u2019avvenuta integrazione da parte dei gestori della struttura della documentazione presentata. Ma gli illeciti riscontrati saranno al vaglio dell\u2019autorit\u00e0 giudiziaria L\u2019Amministrazione Comunale intende dare agli operatori circensi attendati a Lecce la possibilit\u00e0 di continuare l\u2019attivit\u00e0 fino alla data fissata del 3 marzo. Resta ferma, tuttavia,\u00a0 l\u2019impossibilit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12090,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12088"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12088"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12088\/revisions"}],"predecessor-version":[{"id":12093,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12088\/revisions\/12093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12090"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}