{"id":121321,"date":"2017-07-06T11:22:16","date_gmt":"2017-07-06T09:22:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=121321"},"modified":"2017-07-06T11:25:12","modified_gmt":"2017-07-06T09:25:12","slug":"addio-a-mohamed-e-a-karim","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/06\/addio-a-mohamed-e-a-karim\/","title":{"rendered":"ADDIO A MOHAMED E A KARIM"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"587\" title=\"images_Cronaca_2015_ambulanza_118_notte-3\" class=\"alignleft size-full wp-image-121322\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/images_Cronaca_2015_ambulanza_118_notte-3.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/images_Cronaca_2015_ambulanza_118_notte-3.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/images_Cronaca_2015_ambulanza_118_notte-3-300x183.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/images_Cronaca_2015_ambulanza_118_notte-3-768x470.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>(e.l.)_____A poche ore di distanza da quello che \u00e8 costato la vita a una ragazza di 20 anni, come abbiamo riferito ieri, un altro drammatico incidente sulle sempre pi\u00f9 funestate strade del Salento ha provocato due morti.<\/p>\n<p>Si tratta di Mohamed Harbaqui, 37 anni\u00a0e di Karim Haj Hassen, 26 anni, entrambi di nazionalit\u00e0 tunisina. Ieri sera l&#8217; auto su cui viaggiavano, una Fiat Silo, in compagnia di altri due giovani connazionali, rimasti feriti, sulla\u00a0provinciale che da Nard\u00f2 porta ad Avetrana, per cause ancora da accertare, \u00e8 finita nei campi, ribaltandosi pi\u00f9 volte.<\/p>\n<p>Sul posto, sono intervenuti i sanitari del 118, i Vigili del Fuoco e i Carabinieri.<\/p>\n<p>U due feriti sono stati portati in gravi condizioni all&#8217; ospedale &#8216;Vito Fazzi&#8217; di Lecce.<\/p>\n<p>Le indagini sull&#8217; accaduto sono ancora in corso.<\/p>\n<p>I quattro tornavano a casa dopo una dura giornata di lavoro nelle campagne della zona.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/06\/addio-a-mohamed-e-a-karim\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/06\/addio-a-mohamed-e-a-karim\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)_____A poche ore di distanza da quello che \u00e8 costato la vita a una ragazza di 20 anni, come abbiamo riferito ieri, un altro drammatico incidente sulle sempre pi\u00f9 funestate strade del Salento ha provocato due morti. Si tratta di Mohamed Harbaqui, 37 anni\u00a0e di Karim Haj Hassen, 26 anni, entrambi di nazionalit\u00e0 tunisina. Ieri [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":121322,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/121321"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=121321"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/121321\/revisions"}],"predecessor-version":[{"id":121324,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/121321\/revisions\/121324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/121322"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=121321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=121321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=121321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}