{"id":121363,"date":"2017-07-07T12:21:11","date_gmt":"2017-07-07T10:21:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=121363"},"modified":"2017-07-08T13:51:53","modified_gmt":"2017-07-08T11:51:53","slug":"brevi-di-nera-9","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/07\/brevi-di-nera-9\/","title":{"rendered":"BREVI DI NERA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"737\" title=\"PO-1024x737\" class=\"alignleft size-full wp-image-121364\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/PO-1024x737.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/PO-1024x737.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/PO-1024x737-300x216.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/PO-1024x737-768x553.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>(g.m.)______Nard\u00f2. Attentato, incendio doloso. Uno dei tanti che ogni notte avvengono nel grande Salento, per minaccia, vendetta, o avvertimento mafioso del racket. Questa notte in grande stile. Presa di mira la concessionaria di auto &#8220;PF Automobili&#8221;.<\/p>\n<p>Non ci sono dubbi sulla natura del gesto: le immagini delle telecamere di video sorveglianza hanno immortalano l&#8217; autore all&#8217; opera, un uomo mascherato che cosparge di benzina.<\/p>\n<p>Con il\u00a0fuoco, ne sono andate distrutte otto.<\/p>\n<p>Indagano gli agenti del Commissariato della Polizia di Stato.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/07\/brevi-di-nera-9\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/07\/brevi-di-nera-9\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Nard\u00f2. Attentato, incendio doloso. Uno dei tanti che ogni notte avvengono nel grande Salento, per minaccia, vendetta, o avvertimento mafioso del racket. Questa notte in grande stile. Presa di mira la concessionaria di auto &#8220;PF Automobili&#8221;. Non ci sono dubbi sulla natura del gesto: le immagini delle telecamere di video sorveglianza hanno immortalano l&#8217; autore [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":121364,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/121363"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=121363"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/121363\/revisions"}],"predecessor-version":[{"id":121438,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/121363\/revisions\/121438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/121364"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=121363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=121363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=121363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}