{"id":122086,"date":"2017-07-19T17:21:08","date_gmt":"2017-07-19T15:21:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=122086"},"modified":"2017-07-19T17:21:08","modified_gmt":"2017-07-19T15:21:08","slug":"come-nelle-fiction-ecco-come-venivano-riciclati-davvero-i-soldi-sporchi-della-mafia-in-attivita-nel-salento-che-producevano-denaro-pulito","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/19\/come-nelle-fiction-ecco-come-venivano-riciclati-davvero-i-soldi-sporchi-della-mafia-in-attivita-nel-salento-che-producevano-denaro-pulito\/","title":{"rendered":"COME NELLE FICTION, ECCO COME VENIVANO RICICLATI (DAVVERO) I SOLDI &#8216;SPORCHI&#8217; DELLA MAFIA, IN ATTIVITA&#8217;  NEL SALENTO CHE PRODUCEVANO DENARO &#8216;PULITO&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"336\" title=\"SanPancrazio\" class=\"alignleft size-full wp-image-122106\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/SanPancrazio.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/SanPancrazio.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/07\/SanPancrazio-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>(Rdl)______L&#8217; allarme era stato chiaro: la mafia investe nel Salento. Magistratura, Procure e Commissione Parlamentare avevano denunciato il fenomeno, oltre alle infiltrazioni nelle Istituzioni, e ai rapporti con la politica.<\/p>\n<p>Si pensava, si sapeva, della Sacra Corona Unita. Qualcosa, di &#8216;Ndrangheta e Camorra. Nulla della Mafia principale, la siciliana. Oggi ne sappiamo di pi\u00f9. Sappiamo che la famiglia del boss nel Salento riciclava denaro cos\u00ec detto &#8216;sporco&#8217; attraverso societ\u00e0 fittizie.<\/p>\n<p>C&#8217; \u00e8 stata all&#8217; alba di questa mattina un&#8217; operazione che ha portato al sequestro di beni mobili e immobili\u00a0alla famiglia del\u00a0boss mafioso Tot\u00f2 Riina, in Sicilia, ma pure, la clamorosa novit\u00e0,\u00a0nelle \u00a0province di Lecce e Brindisi.<\/p>\n<p>Vediamo.<\/p>\n<p>Indagini di anni del reparto Operativo Speciale dei Carabinieri hanno consentito di individuare e colpire il patrimonio occulto riconducibile a Salvatore Riina, alla moglie Ninetta Bagarella e ai figli, Giuseppe Salvatore, Maria Concetta e Lucia.<\/p>\n<p>I beni sequestrati sono localizzati prevalentemente nelle province di Palermo e Trapani, e sono costituiti da\u00a0societ\u00e0, una villa,\u00a0conti correnti bancari e terreni.<\/p>\n<p>Secondo gli inquirenti <em>&#8220;\u00e8 emersa la significativa e continuativa disponibilit\u00e0 di denaro contante della famiglia, ed in particolar modo della moglie la quale, malgrado i molteplici sequestri di beni mobili subiti nel tempo ed a fronte dell\u2019assenza di redditi ufficiali, \u00e8 riuscita a emettere nel periodo 2007-2013 assegni per un valore di oltre 42.000 mila euro a favore dei congiunti detenuti&#8221;.<\/em><\/p>\n<p><em><\/em>Nel Salento sono stati localizzati i beni aziendali formalmente intestati a Antonino, detto Tony\u00a0Ciavarello, genero di Riina, marito della figlia primogenita del boss di Corleone, Maria Concetta Riina, che da anni abitano a San Pancrazio Salentino.<\/p>\n<p>Si tratta delle societ\u00e0 a responsabilit\u00e0 limitata Rigenertek, AC Service e Clawstek, tutte operanti nella vendita al dettaglio di ricambi, forniture\u00a0e componenti automobilistici, con sedi legali e punti operativi fra Lecce e Brindisi.<\/p>\n<p>Stando agli esiti delle indagini patrimoniali, sono state costituite con proventi di presunta derivazione illecita. Infatti, l\u2019esame incrociato della contabilit\u00e0 di queste aziende ha evidenziato una sperequazione di ben 480 mila euro, immessi per lo pi\u00f9 in contanti ed in numerose tranches nei patrimoni sociali senza alcuna giustificazione legale.<\/p>\n<p>Oltre alle\u00a0societ\u00e0, i militari hanno\u00a0sequestrato\u00a0sedici conti correnti bancari, un conto postale, due depositi titoli e due depositi al Ciavarello, e\u00a0tre conti alle Poste e uno in banca alla Riina.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/19\/come-nelle-fiction-ecco-come-venivano-riciclati-davvero-i-soldi-sporchi-della-mafia-in-attivita-nel-salento-che-producevano-denaro-pulito\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/07\/19\/come-nelle-fiction-ecco-come-venivano-riciclati-davvero-i-soldi-sporchi-della-mafia-in-attivita-nel-salento-che-producevano-denaro-pulito\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______L&#8217; allarme era stato chiaro: la mafia investe nel Salento. Magistratura, Procure e Commissione Parlamentare avevano denunciato il fenomeno, oltre alle infiltrazioni nelle Istituzioni, e ai rapporti con la politica. Si pensava, si sapeva, della Sacra Corona Unita. Qualcosa, di &#8216;Ndrangheta e Camorra. Nulla della Mafia principale, la siciliana. Oggi ne sappiamo di pi\u00f9. Sappiamo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":122106,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/122086"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=122086"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/122086\/revisions"}],"predecessor-version":[{"id":122108,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/122086\/revisions\/122108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/122106"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=122086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=122086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=122086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}