{"id":123119,"date":"2017-08-04T15:12:33","date_gmt":"2017-08-04T13:12:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=123119"},"modified":"2017-08-04T15:19:11","modified_gmt":"2017-08-04T13:19:11","slug":"il-via-libera-del-comune-di-nardo-a-sarparea-il-resort-di-lusso-fra-gli-ulivi-monumentali-si-puo-fara","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/04\/il-via-libera-del-comune-di-nardo-a-sarparea-il-resort-di-lusso-fra-gli-ulivi-monumentali-si-puo-fara\/","title":{"rendered":"IL VIA LIBERA DEL COMUNE DI NARDO&#8217; A SARPAREA. IL RESORT DI LUSSO FRA GLI ULIVI MONUMENTALI SI FARA&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"725\" height=\"528\" title=\"ta1\" class=\"alignleft size-full wp-image-123120\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/ta1.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/ta1.jpg 725w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/ta1-300x218.jpg 300w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/>Riceviamo e volentieri pubblichiamo. L&#8217; ufficio stampa del comune di Nard\u00f2 ci manda il seguente comunicato______<\/p>\n<p>La Giunta comunale ha approvato oggi il piano di lottizzazione del comparto 65 del Piano Regolatore Generale relativo, com\u2019\u00e8 noto, al progetto della societ\u00e0 Oasi Sarparea s.r.l. di un complesso residenziale nell\u2019area Sarparea di localit\u00e0 Sant\u2019Isidoro. Si tratta di un piano approvato a seguito di un lungo iter amministrativo, che ha indotto la societ\u00e0 proponente a profonde modifiche dello stesso piano.<\/p>\n<p>Infatti, nella sua conformazione originaria, che il Consiglio comunale approv\u00f2 nel 2009, il piano ha ricevuto il parere negativo della Soprintendenza per i Beni Architettonici e Paesaggistici per le provincie di Lecce, Brindisi e Taranto e non ha ottenuto il parere paesaggistico di conformit\u00e0 al Putt da parte della Giunta regionale. Essenzialmente la modifica consiste nella riduzione del 30% dell\u2019originario programma costruttivo, che adesso interessa 2 ettari dei 16 residuali della superficie del comparto 65. Trattandosi di una zona con una destinazione urbanistica di tipo C5 (zone residenziali di espansione), infatti, il comparto (in totale 21,5 ettari) era stato gi\u00e0 interessato in una sua parte da una precedente lottizzazione, quella della societ\u00e0 Soviva.<\/p>\n<p>Il nuovo Piano quindi ha ottenuto nel 2015 il parere favorevole della Soprintendenza e nel 2016 il parere paesaggistico di compatibilit\u00e0 rispetto al Pptr (che nel frattempo ha sostituito il Putt) da parte della Giunta regionale, oltre a contenere gli adeguamenti necessari alle prescrizioni nell\u2019ambito della procedura di Vas.<\/p>\n<p>Le composizione edilizie che appaiono oggi nel piano di lottizzazione sono naturalmente mere esemplificazioni delle opere e non sono vincolanti. Anche perch\u00e9 il Comune di Nard\u00f2 ha previsto una serie di prescrizioni alla societ\u00e0 proponente che dovranno necessariamente essere rispettate nel successivo progetto esecutivo delle opere e quindi nella prospettiva del permesso a costruire. Tra queste, il fatto che qualsiasi intervento debba essere preceduto da rilievi georeferenziati del perimetro dell\u2019ulivo monumentale, delle alberature monumentali isolate e dei manufatti che testimoniano l\u2019antica attivit\u00e0 rurale. Ci\u00f2 al fine di verificare eventuali interferenze tra le infrastrutture e gli alberi di ulivo, il cui espianto o spostamento, se necessario, dovr\u00e0 in ogni caso essere autorizzato secondo la normativa vigente. Peraltro, lo schema edilizio del piano ha un andamento variabile in funzione proprio della presenza degli ulivi, che rappresentano una componente fondamentale nella logica dell\u2019esistenza stessa del complesso residenziale.<\/p>\n<p>Infine, il Comune si riserver\u00e0 di stabilire la quantificazione e le modalit\u00e0 di partecipazione della societ\u00e0 ai costi di realizzazione delle opere e degli interventi migliorativi richiesti per la viabilit\u00e0 e le infrastrutture sportive di quartiere.<\/p>\n<p><em>\u201cLa questione Sarparea<\/em> &#8211; spiega il sindaco Pippi Mellone &#8211; <em>implica un primo e pi\u00f9 urgente ordine di considerazioni che riguarda la tutela dell\u2019area e dell\u2019uliveto monumentale. Il lungo iter amministrativo, i pareri della Soprintendenza, della Regione e le prescrizioni imposte alla societ\u00e0 dalle varie procedure previste, non ultime quelle che il Comune di Nard\u00f2 ha individuato e che dovranno essere rispettate in fase esecutiva, sono una garanzia assoluta. <\/em><\/p>\n<p><em>Il progetto non \u00e8 quello originario, ha recepito in toto le osservazioni anche del mondo ambientalista, \u00e8 molto meno impattante e ad oggi non \u00e8 nemmeno quello esecutivo, su cui vigileremo in maniera attenta. La questione degli ulivi \u00e8 un falso problema, perch\u00e9 la presenza degli ulivi \u00e8 il \u201ccuore\u201d della filosofia costruttiva del complesso residenziale. I primi a non voler mettere mano agli ulivi sono proprio quelli di Oasi Sarparea e se dovessero toccare anche un solo albero, dovranno comunque essere autorizzati. Per cui, noi, come amministrazione comunale, dal punto di vista del rispetto del territorio, siamo assolutamente tranquilli e con la coscienza a posto.<\/em><\/p>\n<p><em>L\u2019altro ordine di considerazioni, successivo, ma non trascurabile<\/em> &#8211; continua &#8211; <em>\u00e8 che si tratta di un investimento sul territorio di 60 milioni di euro, che Oasi Sarparea ha diritto di fare su un\u2019area di propriet\u00e0 che ha una destinazione urbanistica di tipo C5. Strutture ricettive di cui il nostro territorio \u00e8 notoriamente carente. Anche se in questo caso parliamo s\u00ec di una struttura ricettiva, ma anche di un parco monumentale pubblico di 3 ettari e che quindi rappresenter\u00e0 un valore aggiunto per tutto il territorio. Nel momento in cui quindi siamo certi di tutelare tutto quello di cui la natura ci ha circondati, premessa assolutamente indispensabile, possiamo legittimamente lavorare in altre direzioni, che sono quelle del turismo, dello sviluppo e della crescita. <\/em><\/p>\n<p><em>Capisco tutti i dubbi e le perplessit\u00e0, a meno che non siano quelli di chi nel 2009 ha approvato il progetto originario e dopo lo ha difeso pubblicamente a pi\u00f9 riprese, ipotesi pi\u00f9 \u201cpesante\u201d ed inevitabilmente censurata. Ritengo la decisione assunta in Giunta e la direzione che abbiamo intrapreso, impeccabili sia nella sostanza che nella forma, perch\u00e9 fanno gli interessi della citt\u00e0 e dei cittadini\u201d.______<\/em><\/p>\n<p>LA RICERCA nei nostri articoli di quest&#8217; anno<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/09\/la-lady-degli-ulivi-e-andata-avanti-col-suo-progetto-di-resort-per-milionari-fra-gli-ulivi-monumentali-di-nardo-anzi-e-andata-oltre\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/09\/la-lady-degli-ulivi-e-andata-avanti-col-suo-progetto-di-resort-per-milionari-fra-gli-ulivi-monumentali-di-nardo-anzi-e-andata-oltre\/<\/a><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/11\/cristian-casili-contro-i-progetti-della-lady-del-resort-fra-gli-ulivi-luliveto-di-sarparea-non-si-tocca\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/11\/cristian-casili-contro-i-progetti-della-lady-del-resort-fra-gli-ulivi-luliveto-di-sarparea-non-si-tocca\/<\/a><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/27\/la-giunta-regionale-organo-incompetente-su-sarparea-il-consigliere-regionale-cristian-casili-in-conferenza-stampa-emerse-gravi-illegittimita-amministrative-su-resort-sarparea-emiliano-fermi-lope\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/27\/la-giunta-regionale-organo-incompetente-su-sarparea-il-consigliere-regionale-cristian-casili-in-conferenza-stampa-emerse-gravi-illegittimita-amministrative-su-resort-sarparea-emiliano-fermi-lope\/<\/a><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/28\/sarparea-la-foresta-degli-ulivi-monumentali-il-progetto-di-un-resort-e-larticolo-9-della-costituzione\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/28\/sarparea-la-foresta-degli-ulivi-monumentali-il-progetto-di-un-resort-e-larticolo-9-della-costituzione\/<\/a><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/29\/lettere-un-bivacco-per-turisti-irrispettosi-del-paesaggio\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/01\/29\/lettere-un-bivacco-per-turisti-irrispettosi-del-paesaggio\/<\/a><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/04\/il-significato-del-termine-sarparea\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/04\/il-significato-del-termine-sarparea\/<\/a><\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/02\/casili-m5s-su-ulivi-monumentali-e-sarparea-con-la-legge-sulla-xylella-spetta-ai-comuni-censire-gli-ulivi-monumentali-lamministrazione-mellone-non-ha-piu-alibi-sul-caso-sarparea\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/04\/02\/casili-m5s-su-ulivi-monumentali-e-sarparea-con-la-legge-sulla-xylella-spetta-ai-comuni-censire-gli-ulivi-monumentali-lamministrazione-mellone-non-ha-piu-alibi-sul-caso-sarparea\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/04\/il-via-libera-del-comune-di-nardo-a-sarparea-il-resort-di-lusso-fra-gli-ulivi-monumentali-si-puo-fara\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/04\/il-via-libera-del-comune-di-nardo-a-sarparea-il-resort-di-lusso-fra-gli-ulivi-monumentali-si-puo-fara\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L&#8217; ufficio stampa del comune di Nard\u00f2 ci manda il seguente comunicato______ La Giunta comunale ha approvato oggi il piano di lottizzazione del comparto 65 del Piano Regolatore Generale relativo, com\u2019\u00e8 noto, al progetto della societ\u00e0 Oasi Sarparea s.r.l. di un complesso residenziale nell\u2019area Sarparea di localit\u00e0 Sant\u2019Isidoro. Si tratta di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":123120,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123119"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=123119"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123119\/revisions"}],"predecessor-version":[{"id":123122,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123119\/revisions\/123122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/123120"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=123119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=123119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=123119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}