{"id":12320,"date":"2013-03-06T15:42:22","date_gmt":"2013-03-06T15:42:22","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12320"},"modified":"2013-03-06T15:43:29","modified_gmt":"2013-03-06T15:43:29","slug":"olimpiadi-dellamicizia-2013","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/06\/olimpiadi-dellamicizia-2013\/","title":{"rendered":"OLIMPIADI DELL\u2019AMICIZIA 2013"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/06\/olimpiadi-dellamicizia-2013\/14685-1-il-logo-delle-olimpiadi-dellamicizia\/\" rel=\"attachment wp-att-12322\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/14685-1-il-logo-delle-olimpiadi-dellamicizia.jpg\" alt=\"\" width=\"580\" height=\"390\" class=\"alignleft size-full wp-image-12322\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/14685-1-il-logo-delle-olimpiadi-dellamicizia.jpg 580w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/14685-1-il-logo-delle-olimpiadi-dellamicizia-300x201.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/a>DOMANI A PALAZZO ADORNO LA PRESENTAZIONE\u00a0DEL BANDO PER PARTECIPARE<br \/>\n<span style=\"text-decoration: underline\">Domani, gioved\u00ec 7 marzo, alle ore 11, nella sala conferenze\u00a0 di Palazzo Adorno, a Lecce,<\/span> sar\u00e0 presentato il Bando di partecipazione alle \u201cOlimpiadi dell\u2019amicizia 2013\u201d.<\/p>\n<p>L\u2019iniziativa, alla sua seconda edizione, \u00e8 promossa dai\u00a0 40 Consigli Comunali dei Ragazzi (CCR) che hanno partecipato al 4\u00b0 Raduno Provinciale dei CCR, dall\u2019Unicef, Comitato Provinciale di Lecce e dalla Provincia di Lecce.<\/p>\n<p>In particolare, verranno illustrate le modalit\u00e0, i temi, le date delle iniziative e \u00a0tutte le informazioni utili per partecipare agli eventi ludici e sportivi, che saranno l\u2019occasione per far incontrare ragazze e ragazzi dei Comuni del Salento, in otto diversi paesi della provincia.<\/p>\n<p>Interverranno Antonio Gabellone, presidente\u00a0 della Provincia di Lecce, Giovanna Perrella, presidente Comitato provinciale Unicef, i sindaci adulti e i sindaci dei ragazzi degli 8 Comuni organizzatori: Acquarica del Capo, Carmiano, Lequile, Matino, Melpignano, Poggiardo, San Pietro in Lama, Spongano.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/06\/olimpiadi-dellamicizia-2013\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/06\/olimpiadi-dellamicizia-2013\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>DOMANI A PALAZZO ADORNO LA PRESENTAZIONE\u00a0DEL BANDO PER PARTECIPARE Domani, gioved\u00ec 7 marzo, alle ore 11, nella sala conferenze\u00a0 di Palazzo Adorno, a Lecce, sar\u00e0 presentato il Bando di partecipazione alle \u201cOlimpiadi dell\u2019amicizia 2013\u201d. L\u2019iniziativa, alla sua seconda edizione, \u00e8 promossa dai\u00a0 40 Consigli Comunali dei Ragazzi (CCR) che hanno partecipato al 4\u00b0 Raduno Provinciale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12322,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12320"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12320"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12320\/revisions"}],"predecessor-version":[{"id":12325,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12320\/revisions\/12325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12322"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}