{"id":123244,"date":"2017-08-06T09:05:44","date_gmt":"2017-08-06T07:05:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=123244"},"modified":"2017-08-06T09:38:24","modified_gmt":"2017-08-06T07:38:24","slug":"unaltra-donna-violentata-da-uno-straniero","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/06\/unaltra-donna-violentata-da-uno-straniero\/","title":{"rendered":"AUMENTANO IN PUGLIA LE DONNE VIOLENTATE DA STRANIERI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/violenza-donne-300x173.jpg\" alt=\"\" title=\"violenza-donne\" width=\"300\" height=\"173\" class=\"alignleft size-medium wp-image-97324\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/violenza-donne-300x173.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/violenza-donne-768x443.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/violenza-donne.jpg 896w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(v.m.)_______E&#8217; l&#8217;ennesimo atto di violenza sessuale che nel giro di pochi giorni, \u00a0siamo costretti a raccontare, di donne che nella nostra regione, vengono malmenate e violentate da stranieri.<br \/>\nUn uomo di 35 anni, Ndaye Doumbia, del Ghana, senza fissa dimora, accusato di lesioni aggravate e resistenza a pubblico ufficiale, \u00a0\u00e8 stato arrestato dalla polizia a Bari per violenza sessuale nei confronti di una donna che \u00e8 stata aggredita per strada mentre passeggiava nel centro cittadino.<br \/>\nLa donna \u00e8 stata salvata prima da alcuni passanti che sono intervenuti bloccando l&#8217;aggressore e poi da due pattuglie volanti che, avvertite da una segnalazione al 113, sono intervenute sul posto. La vittima, che stava tornando a casa dopo il lavoro, era stata rincorsa e aggredita violentemente, bloccata e palpeggiata dall&#8217;uomo. Quando sul luogo sono giunti gli agenti, l&#8217;uomo ha anche aggredito un poliziotto con un pugno ed \u00e8 stato neutralizzato con un dissuasore spray al peperoncino. Poi, nonostante fosse ammanettato, ha continuato a reagire aggredendo a pugni anche un altro poliziotto. I due agenti sono stati medicati e giudicati guaribili in dieci e venti giorni.<br \/>\nCi domandiamo sino a quando questo paese sar\u00e0 \u00a0disposto a subire la violenza di questi balordi, che sono giunti in Italia solo perch\u00e9 qualche idiota ha deciso che questo \u00e8 il paese dell&#8217;accoglienza?<br \/>\nL&#8217;Italia si pu\u00f2 permettere il lusso di tenere sul proprio territorio decine di migliaia di sbandati senza fissa dimora, senza documenti, senza permessi di soggiorno, senza sopratutto che siano sottoposti a qualsivoglia controllo?<br \/>\nMentre il popolo italiano \u00a0tutti i giorni fa i conti con queste realt\u00e0, in televisione c&#8217;\u00e8 la passerella di chi pontifica su quanto sia bello l&#8217;accoglienza e come l&#8217;ingresso incontrollato di stranieri siano una risorsa per il nostro paese.<br \/>\nUna risorsa sicuramente lo sono, ma solo per le Cooperative vicine al Governo o alla Chiesa, che si arricchiscono grazie ai migranti, non certo per i cittadini o i poliziotti costretti a subire violenze di tutti i generi.<br \/>\nGli italiani sono un popolo che ha sempre generosamente aperto le porte a chi chiedeva aiuto, ma oggi \u00e8 chiaro a tutti che dietro le belle dichiarazioni sull&#8217;accoglienza si nascondono gli interessi di Organizzazioni umanitarie che fanno affari con gli scafisti, con i mercanti di schiavi.<br \/>\nCos\u00ec non si pu\u00f2 pi\u00f9 andare avanti, il nostro paese ospiti quegli stranieri che sono persone per bene e mandi via i delinquenti.<br \/>\nE a quegli idioti che sistematicamente ripetono che siccome anche gli italiani delinquono, quindi ci dobbiamo tenere i delinquenti di tutto il mondo, vorrei far notare che gli italiani non li possiamo dargli il foglio di via, \u00a0agli altri invece si . Caso mai ci sarebbe da studiare come fare per mandare via dall&#8217;Italia gli italiani che delinquono e non viceversa.<br \/>\nAnche su questo dovrebbero riflettere coloro che ci spiegano quanto sia giusto lo Ius soli.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/06\/unaltra-donna-violentata-da-uno-straniero\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/06\/unaltra-donna-violentata-da-uno-straniero\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(v.m.)_______E&#8217; l&#8217;ennesimo atto di violenza sessuale che nel giro di pochi giorni, \u00a0siamo costretti a raccontare, di donne che nella nostra regione, vengono malmenate e violentate da stranieri. Un uomo di 35 anni, Ndaye Doumbia, del Ghana, senza fissa dimora, accusato di lesioni aggravate e resistenza a pubblico ufficiale, \u00a0\u00e8 stato arrestato dalla polizia a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":97324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123244"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=123244"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123244\/revisions"}],"predecessor-version":[{"id":123250,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123244\/revisions\/123250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/97324"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=123244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=123244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=123244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}