{"id":123269,"date":"2025-08-06T00:01:00","date_gmt":"2025-08-05T22:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=123269"},"modified":"2025-08-05T10:01:51","modified_gmt":"2025-08-05T08:01:51","slug":"hiroshima-6-agosto-1945-arriva-la-vile-bomba-atomica","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/06\/hiroshima-6-agosto-1945-arriva-la-vile-bomba-atomica\/","title":{"rendered":"DIARIO DEL GIORNO \/ MERCOLEDI\u2019 6 AGOSTO 2025"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-123271\" title=\"hiroshima\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/hiroshima.png\" alt=\"\" width=\"528\" height=\"700\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/hiroshima.png 528w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/hiroshima-226x300.png 226w\" sizes=\"(max-width: 528px) 100vw, 528px\" \/>Buongiorno!<\/p>\n<p>Oggi \u00e8 mercoled\u00ec 6 agosto 2025.<\/p>\n<p>Trasfigurazione di Ges\u00f9.<\/p>\n<p>Buon onomastico a chi ha il nome di Salvatore.<\/p>\n<p>Il nostro amico Lorenzo Emmanuele Vantaggiato compie 55\u00a0 anni: auguri!<\/p>\n<p>6 agosto 1945. Gli Stati Uniti uccidono di colpo pi\u00f9 di 140.000 civili, donne, bambini, persone innocenti.<\/p>\n<p>Il Giappone sub\u00ec l&#8217;attacco atomico da parte dell&#8217;esercito americano durante le fasi finali della Seconda Guerra mondiale.<\/p>\n<p>L&#8217;America per quel massacro non ha mai chiesto scusa, \u00a0altre nazioni lo hanno fatto per molto meno.<br \/>\nCome si vede ai vincitori tutto \u00e8 concesso.<\/p>\n<p>Gli altri uccidevano perch\u00e9 erano cattivi, gli americani uccidevano perch\u00e9 erano buoni, tanto \u00e8 vero che dopo le atomiche, arriv\u00f2 la pace&#8230;o meglio arrivarono una serie di altre guerre, sempre contro i cattivi.<br \/>\nBuona parte della storiografia \u00e8 propensa a credere che le atomiche sul Giappone furono sganciate per dare una prova della potenza americana a quel che da l\u00ec a breve saranno in competitor degli Stati Uniti, l&#8217;Unione Sovietica. Gli americani invece sostengono che lo fecero per salvare molte vite americane e giapponesi grazie alla fine della guerra.<\/p>\n<p>Presentiamo uno stralcio del libro: &#8220;<strong>Appuntamento ad Hiroshima<\/strong>&#8221; di Stephen Walker. Bastano queste poche parole per capire l&#8217;entit\u00e0 dell&#8217;<strong>evento omicida<\/strong>.<\/p>\n<p><em>\u201cNel primo miliardesimo di secondo la temperatura nel punto di esplosione raggiunse i\u00a0<strong>sessanta milioni di gradi centigradi,<\/strong>\u00a0diventando dieci volte pi\u00f9 calda della superficie del sole\u201d.\u00a0<strong>Migliaia di esseri umani si ridussero in cenere\u00a0<\/strong>o semplicemente scomparvero,\u00a0<strong>gli uccelli furono incendiati in volo,\u00a0<\/strong>i tondini di acciaio degli edifici di cemento armato si liquefecero.\u00a0<\/em><\/p>\n<p><em>Poi arriv\u00f2 l\u2019onda d\u2019urto, alla velocit\u00e0 di 3.000 metri al secondo, con una forza iniziale di sette tonnellate per metro quadrato, e rase al suolo tutto ci\u00f2 che era sopravvissuto al calore nel raggio di ottocento metri dal punto dello scoppio (pi\u00f9 o meno 60 mila edifici),\u00a0<strong>uccidendo almeno altre 50 mila persone.<\/strong>Secondo alcune stime, nei primissimi secondi dopo l\u2019esplosione persero la vita circa 80 mila esseri umani.\u00a0<strong>Ma l\u2019orrore non era solo in questi numeri:<\/strong>\u00a0perch\u00e9 per la prima volta nella storia della guerra, un ordigno bellico aveva creato intorno a s\u00e9 un anello di morte invisibile, sotto forma di raggi gamma e di neutroni veloci, che avrebbe continuato a uccidere nei mesi e negli anni a venire (<strong>alla fine le vittime collegabili in qualche modo all\u2019esplosione sono state stimate in 200 mila)<\/strong>.<\/em><\/p>\n<p>Proverbio salentino:\u00a0<strong>Ciuveddhri nasce mparatu<\/strong><\/p>\n<p>Nessuno nasce &#8216;imparato&#8217;. Qualunque cosa necessita di studio, costanza, applicazione, pratica e pazienza.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/06\/hiroshima-6-agosto-1945-arriva-la-vile-bomba-atomica\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/06\/hiroshima-6-agosto-1945-arriva-la-vile-bomba-atomica\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 mercoled\u00ec 6 agosto 2025. Trasfigurazione di Ges\u00f9. Buon onomastico a chi ha il nome di Salvatore. Il nostro amico Lorenzo Emmanuele Vantaggiato compie 55\u00a0 anni: auguri! 6 agosto 1945. Gli Stati Uniti uccidono di colpo pi\u00f9 di 140.000 civili, donne, bambini, persone innocenti. Il Giappone sub\u00ec l&#8217;attacco atomico da parte dell&#8217;esercito americano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":123271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123269"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=123269"}],"version-history":[{"count":14,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123269\/revisions"}],"predecessor-version":[{"id":247056,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123269\/revisions\/247056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/123271"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=123269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=123269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=123269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}