{"id":123283,"date":"2017-08-08T00:23:52","date_gmt":"2017-08-07T22:23:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=123283"},"modified":"2017-08-08T00:23:52","modified_gmt":"2017-08-07T22:23:52","slug":"sulla-costa-ionica-schiudono-le-uova-di-tartarughe","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/08\/sulla-costa-ionica-schiudono-le-uova-di-tartarughe\/","title":{"rendered":"SULLA COSTA IONICA SCHIUDONO LE UOVA DI TARTARUGHE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/tartarughe.jpg\" alt=\"\" title=\"A Castellaneta prima schiusa da nido tartarughe Wwf\" width=\"457\" height=\"257\" class=\"alignleft size-full wp-image-123284\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/tartarughe.jpg 457w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/tartarughe-300x169.jpg 300w\" sizes=\"(max-width: 457px) 100vw, 457px\" \/>8gm)_______Dopo 52 giorni di incubazione da un nido di tartarughe sorvegliato giorno e notte da volontari del Wwf si sono schiuse la scorsa notte le prime 16 uova.<br \/>\nLe uova erano state deposte lo scorso 14 giugno che gli esperti del Wwf \u00a0avevano subito provveduto a &#8216;traslocare&#8217; le 86 uova in una zona sicura della spiaggia di Policoro. Questa notte hanno fatto capolino dalla sabbia le prime 16 tartarughine Caretta Caretta che, accompagnate dai volontari e dagli operatori WWF dell&#8217;Oasi di Policoro, si sono dirette verso il mare. Il nido gi\u00e0 dalla fine di luglio era sorvegliato ventiquattro ore su ventiquattro dai volontari WWF, dai ragazzi di Greenrope e dalle Guardie Ecozoofile di Anpana onlus con l&#8217;aiuto del Comune di Castellaneta che si \u00e8 impegnato nella protezione del nido e degli arenili circostanti emettendo, primo comune della Puglia, un&#8217;ordinanza restrittiva. Si attende ora la nascita a breve dei piccoli ritardatari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/08\/sulla-costa-ionica-schiudono-le-uova-di-tartarughe\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/08\/sulla-costa-ionica-schiudono-le-uova-di-tartarughe\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>8gm)_______Dopo 52 giorni di incubazione da un nido di tartarughe sorvegliato giorno e notte da volontari del Wwf si sono schiuse la scorsa notte le prime 16 uova. Le uova erano state deposte lo scorso 14 giugno che gli esperti del Wwf \u00a0avevano subito provveduto a &#8216;traslocare&#8217; le 86 uova in una zona sicura della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":123284,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[78],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123283"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=123283"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123283\/revisions"}],"predecessor-version":[{"id":123286,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123283\/revisions\/123286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/123284"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=123283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=123283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=123283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}