{"id":123460,"date":"2017-08-11T11:44:49","date_gmt":"2017-08-11T09:44:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=123460"},"modified":"2017-08-12T10:34:39","modified_gmt":"2017-08-12T08:34:39","slug":"m5s-censurare-la-storia-sul-genocidio-delle-genti-del-sud-da-parte-di-garibaldi-e-dellesercito-piemontese","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/11\/m5s-censurare-la-storia-sul-genocidio-delle-genti-del-sud-da-parte-di-garibaldi-e-dellesercito-piemontese\/","title":{"rendered":"LARICCHIA M5S: NO ALLA CENSURA SUL GENOCIDIO DELLE GENTI DEL SUD DA PARTE DI GARIBALDI E DELL&#8217;ESERCITO PIEMONTESE"},"content":{"rendered":"<p dir=\"ltr\"><em><img decoding=\"async\" loading=\"lazy\" width=\"699\" height=\"1024\" title=\"bronte\" class=\"alignleft size-large wp-image-123461\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/08\/bronte-699x1024.jpg\" \/>(mv)<\/em>_____E&#8217; notorio che in Italia \u00a0la storia \u00e8 stata strumentalizzata a fini politici. Il Partito Comunista \u00e8 stato in prima linea in quest&#8217;operazione, giungendo a &#8220;dotarsi&#8221; di una storia a suo uso e consumo, distorcendo episodi, falsificandone altri, dimenticano alcuni ed amplificandone altri. Anche la storia dell&#8217;unificazione d&#8217;Italia ci \u00e8 stata raccontata nello tesso modo, c&#8217;erano gli eroi del nord: Mazzini, Garibaldi, Cavour e company da una parte, e poi c&#8217;erano i briganti, i cafoni, il re aguzzino dall&#8217;altra.<br \/>\nOggi anche grazie ad internet ed all&#8217;opera meritoria di scrittori meridionali, che, documenti alla mano, hanno raccontato la verit\u00e0 sul genocidio avvenuto al sud ad opera di Garibaldi prima e dell&#8217;esercito piemontese dopo, una verit\u00e0 che come l&#8217;acqua che scorre sottoterra, dopo oltre 150 anni, ora sgorga in superficie e pu\u00f2 essere vista da tutti.<br \/>\nO meglio da quasi tutti, perch\u00e9 alcuni insistono, nel non voler vedere nell&#8217;Unita d&#8217;Italia, l&#8217;aggressione di uno stato sovrano ad opera di un&#8217;altro stato senza che neppure fosse consegnata la dichiarazione di guerra alla nazione aggredita. Ormai \u00e8 notorio che il Regno di Piemonte invase il Regno delle Due Sicilia, grazie agli enormi finanziamento avuti dall&#8217;Inghilterra, all&#8217;epoca potenza mondiale che aveva colonie in tutti i continenti.<br \/>\nE pech\u00e8 l&#8217;Inghilterra \u00a0doveva parteggiare per il Nord a scapito del Sud Italia, per motivi ideologici, per portare la modernit\u00e0, il progresso, la democrazia? No! \u00a0ieri come oggi le guerre si dichiarano e si finanziano per interesse.<br \/>\nIl Regno di Piemonte era sull&#8217;orlo della bancarotta, e l&#8217;Inghilterra \u00a0che voleva avere una base in Sicilia per ottimizzare i commerci con le sue colonie, finanzi\u00f2 la guerra contro il Sud.<br \/>\nComunque al di l\u00e0 delle motivazioni, pi\u00f9 o meno nobili, la storia si sa la scrivono i vincitori, resta per\u00f2 un dato inconfutabile, il genocidio delle genti del Sud, le tasse, le leggi ingiustizie che il nord imporr\u00e0 al sud Italia, e che lo ridurr\u00e0 ad essere la parte povera del paese da cui attingere manodopera a buon prezzo, mentre prima era una delle potenze mondiali. Il Regno delle Due Sicilia non conosceva il fenomeno dell&#8217;emigrazione, e per quanto riguardava la presunta arretratezza del paese, basti pensare che la prima ferrovia in Europa fu costruita nella capitale del sud, la Napoli &#8211; Portici, cos\u00ec come andrebbe ricordato che le industrie del Sud furono smontate e trasferite a Torino.<\/p>\n<p>Ecco il comunicato che la Consigliera Regionale del M5S Antonella Laricchia ci ha inviato:<\/p>\n<div>\u00a0Abbiamo seguito con immenso interesse gli interventi di <a>questo mese<\/a> sulla &#8220;Giornata della memoria per le vittime meridionali dell&#8217;Unit\u00e0 d&#8217;Italia\u201d. Un <strong>dibattito quasi sempre corretto nei toni nonostante i punti di vista divergenti.<\/strong><\/div>\n<p>Tuttavia <strong><a>oggi<\/a> dispiace dover leggere in una nota ufficiale dei promotori di una petizione contro questa Giornata<\/strong>, frasi fuorvianti come \u201c<em>a cura di movimenti neoborbonici appoggiati dal Movimento 5 Stelle<\/em>&#8221; pronunciate dagli stessi che hanno organizzato una conferenza stampa chiedendo, giustamente, che<strong> non si facesse un uso strumentale della storia<\/strong>.<\/p>\n<p>L&#8217;impegno contenuto nella nostra mozione era gi\u00e0 inserito nel programma elettorale M5S delle elezioni regionali 2015, che \u00e8 stato supportato da oltre 310.000 persone; la stessa mozione \u00e8 stata poi appoggiata da quasi tutto il Consiglio Regionale e non solo dal M5S, ed aveva ed ha ancora come principale obiettivo l&#8217;apertura di un dibattito su un argomento al quale fino ad <a>oggi<\/a> nessuno aveva dato spazio e nel quale ognuno \u00e8 libero di dare il proprio contributo. E l&#8217;obiettivo \u00e8 stato certamente raggiunto.<\/p>\n<p>Vorremmo dunque invitare tutti, soprattutto coloro che hanno compiti pedagogici nei confronti delle future generazioni, a <strong>non temere il dialogo ed il confronto che sono il sale della democrazia; le censure, quelle s\u00ed, ricordano davvero periodi fin troppo bui della nostra storia.<\/strong> \u00c8 una problematica che riscontriamo purtroppo su tutta una serie di argomenti: \u00e8 come se in Italia esistesse un gruppo di detentori di verit\u00e0 assolute che non solo non intendono mettere in discussione alcune tematiche, il che sarebbe anche legittimo, ma pretendono che non se ne parli neppure. Credete fosse davvero questa quella democrazia per la quale i nostri antenati, di cui parlate in convegni e nelle vostre aule universitarie, si sono battuti? In ultimo non si pu\u00f2 non notare come sia <strong>un po&#8217; imbarazzante la richiesta di finanziamenti al presidente della Regione<\/strong> perpetrata da una parte di questa scarna \u00e9lite contraria a questa Giornata della Memoria. <strong>Dunque l\u2019alternativa a una Giornata della Memoria a costo zero che vuole dare dignit\u00e0 a tutte le voci sarebbe la richiesta di finanziamento di una visione unilaterale del racconto storico con i soldi di tutti?<\/strong><\/p>\n<p>D\u2019altro canto <strong>desideriamo ringraziare di cuore tutti coloro, giornalisti, professionisti, docenti e semplici cittadini che si stanno interessando e che stanno intervenendo<\/strong>, contribuendo a dare finalmente il giusto spazio ad un dibattito talmente importante e delicato.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell&#8217;<a href=\"https:\/\/www.youtube.com\/watch?v=LX15Xb9RarA\">intervento<\/a>\u00a0al Senato, il parlamentare Cinque Stelle Sergio Puglia cita tra gli altri, Gramsci, Montanelli e Pino Aprile: &#8220;Non sapevo che durante l&#8217;annessione fecero al Sud quello che i nazisti fecero a Marzabotto. [&#8230;] ma lo scrittore Aprile mi ha preceduto. Se fossi di sinistra direi che si tratt\u00f2 di una dittatura feroce che ha messo a ferro e fuoco l&#8217;Italia meridionale, crocifiggendo, squartando contadini poveri che scrittori salariati chiamarono briganti, ma Antonio Gramsci mi ha preceduto. Se fossi di destra direi che la guerra contro il brigantaggio cost\u00f2 pi\u00f9 morti che tutti quelli del Risorgimento, ma Montanelli mi ha preceduto&#8221;. E ha concluso cos\u00ec: &#8220;Il tempo \u00e8 maturo per fare una riflessione e analizzare cosa accadde alle popolazioni civili meridionali. E quanto ancora ci costa nel presente. Chiediamo solo la verit\u00e0&#8221;.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/11\/m5s-censurare-la-storia-sul-genocidio-delle-genti-del-sud-da-parte-di-garibaldi-e-dellesercito-piemontese\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/08\/11\/m5s-censurare-la-storia-sul-genocidio-delle-genti-del-sud-da-parte-di-garibaldi-e-dellesercito-piemontese\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(mv)_____E&#8217; notorio che in Italia \u00a0la storia \u00e8 stata strumentalizzata a fini politici. Il Partito Comunista \u00e8 stato in prima linea in quest&#8217;operazione, giungendo a &#8220;dotarsi&#8221; di una storia a suo uso e consumo, distorcendo episodi, falsificandone altri, dimenticano alcuni ed amplificandone altri. Anche la storia dell&#8217;unificazione d&#8217;Italia ci \u00e8 stata raccontata nello tesso modo, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":123461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123460"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=123460"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123460\/revisions"}],"predecessor-version":[{"id":123522,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/123460\/revisions\/123522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/123461"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=123460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=123460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=123460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}