{"id":12374,"date":"2013-03-08T08:56:43","date_gmt":"2013-03-08T08:56:43","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12374"},"modified":"2013-03-08T08:56:43","modified_gmt":"2013-03-08T08:56:43","slug":"differenze-da-valorizzare","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/differenze-da-valorizzare\/","title":{"rendered":"DIFFERENZE DA VALORIZZARE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">\u00a08 marzo, alle ore 9, alle Officine Cantelmo, la giornata di informazione e educazione sulle differenze di genere. L\u2019iniziativa \u00e8 stata presentata ieri a Palazzo Carafa.<\/p>\n<p>\u00a0E\u2019 stata presentata ieri a Palazzo Carafa <strong>Il valore della differenza di genere,<\/strong> la giornata di informazione e formazione dedicata\u00a0 alla famiglia e al valore della differenza di genere organizzata dall\u2019Associazione Strada Facendo\u2026 in collaborazione con l\u2019Assessorato alle Politiche di genere del Comune di Lecce. L\u2019appuntamento \u00e8 in programma domani, <strong>venerd\u00ec 8 marzo, a partire dalle ore 9, alle<\/strong> <strong>Officine Cantelmo.<\/strong>\u00a0 Dopo gli incontri mattutini i lavori riprenderanno alle ore 15.30 con il corso di formazione su <em>Azioni di contrasto, di prevenzione e di tutela.<\/em><\/p>\n<p>Numerosi gli ospiti che si alterneranno per offrire il\u00a0 proprio contributo, tra testimonianze e performance sul tema, fra cui la scrittrice e conduttrice televisiva <strong>Catena Fiorello<\/strong>, il presidente Nazionale del Movimento per La Vita, l\u2019europarlamentare e magistrato <strong>Carlo Casini<\/strong>, il Procuratore Capo della Repubblica presso il Tribunale per i Minorenni, <strong>Maria Cristina Rizzo<\/strong> e <strong>Alessandra Borgia, <\/strong>giornalista di Quarto Grado, Rete4.<\/p>\n<p><em>\u201cIntendiamo promuovere &#8211;<\/em> ha sottolineato la vicesindaco e assessore ai Servizi Sociali, <strong>Carmen Tessitore &#8211;<em> <\/em><\/strong><em>la cultura della parit\u00e0 che si ottiene attraverso la valorizzazione delle differenze di genere. Abbiamo coinvolto bambini e ragazzi per cercare di educarli al rispetto delle donne e alla valorizzazione delle loro potenzialit\u00e0\u201d. <\/em><\/p>\n<p><em>\u201cE\u2019 necessario <\/em>&#8211; ha spiegato <strong>Alessandra Lezzi, <\/strong>presidente dell\u2019Associazione Strada Facendo &#8211;<em> guardare il mondo con occhi differenti, con un occhi maschile e uno femminile. Non a caso abbiamo voluto puntare su questa immagine nel nostro invito.\u00a0 \u201cVogliamo continuare a camminare unendoci, strada facendo, ad altre realt\u00e0 associative\u201d. <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Alla conferenza stampa erano presenti la vicesindaco,<strong> Carmen<\/strong> <strong>Tessitore, <\/strong>la<strong> <\/strong>dirigente del settore Servizi Sociali,<strong> Anna Maria Perulli <\/strong>e <strong>Alessandra Lezzi<\/strong>, Presidente Associazione Strada Facendo\u2026<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/differenze-da-valorizzare\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/differenze-da-valorizzare\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a08 marzo, alle ore 9, alle Officine Cantelmo, la giornata di informazione e educazione sulle differenze di genere. L\u2019iniziativa \u00e8 stata presentata ieri a Palazzo Carafa. \u00a0E\u2019 stata presentata ieri a Palazzo Carafa Il valore della differenza di genere, la giornata di informazione e formazione dedicata\u00a0 alla famiglia e al valore della differenza di genere [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12374"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12374"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12374\/revisions"}],"predecessor-version":[{"id":12375,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12374\/revisions\/12375"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}