{"id":12394,"date":"2013-03-08T09:06:17","date_gmt":"2013-03-08T09:06:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12394"},"modified":"2013-03-08T09:07:17","modified_gmt":"2013-03-08T09:07:17","slug":"al-via-i-percorsi-di-marzo-dautrice","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/al-via-i-percorsi-di-marzo-dautrice\/","title":{"rendered":"AL VIA I PERCORSI DI \u201cMARZO D\u2019AUTRICE\u201d"},"content":{"rendered":"<p><strong>DOMENICA 10 MARZO IL PRIMO APPUNTAMENTO\u00a0<\/strong><strong>DELLA RASSEGNA IDEATA DALLA CONSIGLIERA DI PARITA\u2019<br \/>\n<\/strong>Dopo i consensi registrati nella prima edizione, torna per il secondo anno consecutivo <strong>\u201cMarzo d\u2019autrice\u201d<\/strong>, la rassegna letteraria nata da un\u2019idea della consigliera di Parit\u00e0 della Provincia di Lecce <strong>Alessia Ferreri<\/strong>, con l\u2019intento \u201cdi valorizzare e avvicinare le autrici e scrittrici locali ai cittadini, promuovendo la cultura della differenza di genere\u201d.Realizzata in collaborazione con la Commissione Provinciale Pari Opportunit\u00e0 e l\u2019Assessorato alla Cultura della Provincia di Lecce, la seconda edizione della rassegna si snoder\u00e0\u00a0 lungo il mese di marzo in tre appuntamenti domenicali.<\/p>\n<p>Si parte <span style=\"text-decoration: underline\">domenica 10 marzo, alle ore 18, nel prestigioso Teatrino Palmieri di Piazzetta Carducci, a Lecce,<\/span> con la presentazione del libro <strong>\u201cVolti di Carta\u201d<\/strong> di <strong>Raffaella Verdesca<\/strong>, edito da Albatros.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019incontro con l\u2019autrice sar\u00e0 introdotto dalla consigliera provinciale di Parit\u00e0 <strong>Alessia Ferreri<\/strong>. Seguiranno i saluti della vicepresidente della Provincia di Lecce <strong>Simona Manca<\/strong>, della presidente della Commissione provinciale Pari Opportunit\u00e0 <strong>Maria Teresa Maglio<\/strong> e delle presidenti delle associazioni Soroptimist Lecce, Associazione Ex Marcelline e UDI Macare Salento. Saranno presenti, inoltre,\u00a0 <strong>Rossella Martini, Cristina Cirillo, Enza Miceli, Milena Carone <\/strong>e <strong>Paolo Pellegrino<\/strong>, che curer\u00e0 il commento del volume.<\/p>\n<p>&nbsp;<\/p>\n<p>Questo incontro, come tutti gli altri in programma, sar\u00e0 accompagnato dalla voce critica di <strong>Pompea Vergaro<\/strong>, la voce narrante di <strong>Elisabetta Opasich<\/strong> e gli intermezzi musicali di flauto con\u00a0 <strong>Elena Borlizzi<\/strong>\u00a0 e\u00a0 di arpa con\u00a0 <strong>Francesca Cavallo<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Il secondo appuntamento in calendario con \u201cMarzo d\u2019Autrice\u201d \u00e8 per <span style=\"text-decoration: underline\">domenica 17 marzo alle 18, sempre nel Teatrino Palmieri<\/span>, con la presentazione del libro \u201cRieducare. Eros e costumi in Terra d\u2019Otranto\u201d di Annamaria Colaci (Milella edizioni), con le Associazione Unicel e Aede, alla presenza di Lucia Cillo, Giusy Negro e con il commento di\u00a0 Carlo Alberto Augeri.<\/p>\n<p>&nbsp;<\/p>\n<p>La rassegna si concluder\u00e0 <span style=\"text-decoration: underline\">domenica 24 marzo alle <\/span><span style=\"text-decoration: underline\">18 <\/span>con la presentazione del libro \u201cPensiero politico e genere dall\u2019Ottocento al Novecento\u201d di Fiorenza Taricone e Rossella Bufano (Amaltea edizioni), con le Associazione Fidapa Lecce e Ande Lecce, alla\u00a0 presenza di\u00a0 Cristina Caiulo, Teresa Romano, Maria Lucia Seracca e il commento di\u00a0 Antonio Facchini.<\/p>\n<p>&nbsp;<\/p>\n<p>La consigliera provinciale di Parit\u00e0 <strong>Alessia Ferreri<\/strong> spiega il senso dell\u2019iniziativa: \u201cQuesta rassegna letteraria nasce da quel profondo bisogno di sottolineare di quanto la scrittura al femminile, nell\u2019era del web, non \u00e8 pi\u00f9 un\u2019eccezione e che la biblioteca sognata, fatta di scaffali vuoti, di cui si lamentava la scrittrice inglese Virginia Woolf, considerata la madre spirituale di tutte le scrittrici, oggi sia colma di libri scritti da donne: biografie e romanzi, racconti, lettere, saggi. Inoltre, questi appuntamenti dovranno costituire un momento di riflessione di quanto\u00a0 le donne del passato in relazione alla scrittura siano finite nel dimenticatoio, e come oggi\u00a0 siano le stesse donne a recuperarle, per darle voce\u00a0 e consegnarle quel posto che le spetta di diritto nella storia letteraria\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSe volgiamo lo sguardo al passato la storia della scrittura delle donne si arresta alla seconda met\u00e0 dell\u2019800, perch\u00e9 fino ad allora erano vissute nel buio, \u201cemblema della famiglia ma anche del peccato originale; lodate dall\u2019Amor Cortese nel Dolce Stil Novo, ma tacciate di stregoneria dopo neanche un secolo\u201d, continua la consigliera di Parit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c\u00c8 solo a partire dal \u2018900, dunque, che le tante appassionate di scrittura hanno cominciato ad acquisire consapevolezza, sono diventate portatrici di diritti e doveri al pari dell\u2019altro genere, hanno assunto visibilit\u00e0 come soggetto sociale e nel mondo letterario non sono pi\u00f9 state considerate come una mosca bianca, ma una realt\u00e0 forte e ricca di consapevolezza del proprio ruolo innovativo, senza per\u00f2 con non poche difficolt\u00e0\u201d, evidenzia ancora <strong>Alessia Ferreri<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cE la stessa Virginia Woolf, non immaginava di quanto le donne si impegnavano nel proprio ambito domestico a leggere e a scrivere e, in quello sociale cercando sostegno nelle amicizie maschili o divenendo compagne di\u00a0 scrittori\u00a0 affermati come Anais Nin con Henry Millere e Dacia Maraini con Moravia, per citare solo qualche esempio. \u00c8 sorto addirittura un dibattito, intorno alla prima met\u00e0 del secolo scorso e che ancora continua,ma con interesse minore, se esista il fenomeno di una scrittura al femminile riguardo proprio ai contenuti, poich\u00e9 le donne hanno uno sguardo differente di rapportarsi alla realt\u00e0 e una naturale propensione a raccontare, a intessere storie (lo fa anche quando chiacchiera con le amiche sul pianerottolo o in salotto\u2026)\u201d, prosegue <strong>Alessia Ferreri<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDa qui, con Marzo d\u2019Autrice, la necessit\u00e0 di coinvolgere pi\u00f9 soggetti, dalle Istituzioni, alle donne impegnate nel mondo della cultura, alle Associazioni femminili locali, ognuna per la propria specificit\u00e0, a dare voce e sostegno, perch\u00e9 solo conquistando la parit\u00e0 di genere tanto agognata, anche nel mondo culturale, potr\u00e0\u00a0 migliorare la qualit\u00e0 della vita sia delle donne sia degli uomini\u201d, conclude la consigliera provinciale di parit\u00e0 <strong>Alessia Ferreri<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/al-via-i-percorsi-di-marzo-dautrice\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/al-via-i-percorsi-di-marzo-dautrice\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>DOMENICA 10 MARZO IL PRIMO APPUNTAMENTO\u00a0DELLA RASSEGNA IDEATA DALLA CONSIGLIERA DI PARITA\u2019 Dopo i consensi registrati nella prima edizione, torna per il secondo anno consecutivo \u201cMarzo d\u2019autrice\u201d, la rassegna letteraria nata da un\u2019idea della consigliera di Parit\u00e0 della Provincia di Lecce Alessia Ferreri, con l\u2019intento \u201cdi valorizzare e avvicinare le autrici e scrittrici locali ai [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12394"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12394"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12394\/revisions"}],"predecessor-version":[{"id":12396,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12394\/revisions\/12396"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}