{"id":12428,"date":"2013-03-08T17:03:53","date_gmt":"2013-03-08T17:03:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12428"},"modified":"2013-03-08T17:03:53","modified_gmt":"2013-03-08T17:03:53","slug":"ex-trahere-extra-here","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/ex-trahere-extra-here\/","title":{"rendered":"EX TRAHERE &#8211; EXTRA HERE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong><em>Domenica 10 marzo, alle ore 18, nuovo appuntamento nell\u2019ambito di MustinTime con la mostra di Vito Leone e Paola Mancinelli curata da CO.61<br \/>\n<\/em><\/strong>Prosegue la programmazione di MUSTinTIME, l\u2019articolata mostra che si muove dal 30 novembre e sino al 19 marzo, ideata e organizzata dall\u2019Associazione id&amp;a e dal Must \u2013 Museo Storico di Lecce, curata dall\u2019artista creativa Monica Righi e dall\u2019architetto Andrea Novembre e promossa dal Comune di Lecce con il Patrocinio dell\u2019Assessore al Mediterraneo, Cultura e Turismo della Regione Puglia e con il sostegno di Leo Constructions.<\/p>\n<p>Il prossimo appuntamento \u00e8 fissato per <strong>domenica 10 marzo, alle ore 18,<\/strong> quando all\u2019interno del Must verr\u00e0 inaugurata la mostra <strong><em>EX TRAHERE &#8211; EXTRA HERE<\/em><\/strong> di <strong>Vito Leone<\/strong> e <strong>Paola<\/strong> <strong>Mancinelli<\/strong> a cura di CO.61.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<strong>Estrarre: dal latino Extrahere, tirare fuori<\/strong>. Un verbo dinamico, un moto necessario, una tensione della mente e del corpo che parte da una volont\u00e0 di ricerca, da un desiderio di scoperta, da una possibilit\u00e0 di condivisione. Il progetto nasce da questa tendenza e si snoda, nelle sale del Museo Storico di Lecce per Mustintime, attraverso i due percorsi artistici \u201cEx trahere\u201d di Vito Leone e \u201cExtra Here\u201d di Paola Mancinelli. Per entrambi la materia diviene protagonista, si offre generosamente, mostra la sua potenza e al tempo stesso il suo potenziale. Attende di essere lavorata, plasmata e raccontata. L\u2019opera \u00e8 il risultato di un\u2019estrazione, di un lavoro manuale e intellettivo insieme. Il suo dinamismo tende a cavare fuori un senso nuovo da un senso originario, senza stravolgerlo, n\u00e9 modificarlo, ma dotandolo di una forma nuova, ricavando da questo processo ulteriori possibilit\u00e0 di lettura. In quest\u2019ottica il lavoro fotografico di Vito Leone si veste di segni e geometrie, linee e intersezioni che si alternano come in un mosaico. Un quadro unico, naturale, nel quale ogni piccola sezione occupa un suo posto stabilito, recita una parte per il tutto. Sono solchi nella terra madre, come tante trame di un passato che ridisegna energicamente un suo equilibrio, un suo riscatto nei confronti del tempo e dell\u2019ambiente. Il suo lavoro racconta l\u2019arte creata dalla mano inconsapevole della natura che disegna la trama di ci\u00f2 che \u00e8 stato, ma anche i segni della mano dell\u2019uomo nella pietra e sulla terra, ferite che nel tempo hanno trovato una forma nuova e una sintesi con l\u2019ambiente circostante. Pareti nude, sulle quali ci sono il sudore dell\u2019uomo e le tracce lasciate nel tempo dall\u2019acqua e dal vento. Il risultato \u00e8 un mondo surreale, un non luogo, fatto di essenzialit\u00e0 e rigore geometrico. Una serialit\u00e0 non banale, alternata a vuoti, che d\u00e0 il senso del tempo e dello spazio. L\u2019arte diventa un viaggio verso le proprie strutture primarie, forme, spazi, linee e superfici. Nel lavoro installativo di Paola Mancinelli la parola mantiene il suo autentico dinamismo e gioca letteralmente con un fuori inteso come fuori dall\u2019ordinario. Un processo che porta l\u2019io a tirare fuori da s\u00e9 ci\u00f2 che di extra-ordinario ha gi\u00e0 dentro. Il mondo \u00e8 il riflesso del suo cosmo interiore, l\u2019Here, la sua sfera intima e personale, egli \u00e8 il fuori e il dentro. In questo viaggio sapere e saper fare coincidono e dialogano tra loro, passando dal concetto all\u2019azione, dall\u2019idea originaria all\u2019opera. C\u2019\u00e8 una conoscenza che chiede di essere estratta, tirata fuori, esplicitata, resa fruibile e riproposta in altri contesti. Un percorso attraverso il quale l\u2019intelletto coglie l\u2019essenza, il concetto e lo fa passare attraverso la propria esperienza, lo ripropone, dandogli una forma nuova. Cos\u00ec come per \u201cEx trahere\u201d \u00e8 stata una geometria di linee alternate a raffigurare il suolo che generosamente si offre per la necessit\u00e0 umana, cos\u00ec per \u201cExtra Here\u201d sono le linee di pensiero a tracciare una sorta di mappa concettuale, un tracciato logico. L\u2019intento \u00e8 quello di rappresentare l\u2019estrazione anche dal punto di vista dei concetti portanti, per una loro costruzione logica, una loro acquisizione, interiorizzazione e rappresentazione. L\u2019interazione \u00e8 quella della parola con il fruitore. Nella sua videoproiezione si susseguono in ordine di senso i termini che mantengono la radice stessa di Estrazione. Il lavoro di posizionamento dei neon a terra vuole indicare che questo \u00e8 un percorso esperibile, vicino all\u2019umano, un cammino visibile, perch\u00e9 illuminato, che si snoda sottile tra lastre di cristallo. Un sentiero che guarda all\u2019idea originaria, alla sua proiezione e alla sua realizzazione.<br \/>\nMUSTinTIME<br \/>\nnasce come nuovo concept museale, con lo scopo di promuovere le produzioni artistiche innovative legate alla tradizione, alle risorse e alla cultura locale. Gli artisti coinvolti nella mostra permanente sono: Andrea Epifani, Amekasa, Antonio Corineo, Antonio Malecore, Antonio Surdo, Azzurra Cecchini, Bruno Maggio, Daniele Papuli, Elena Petrucci, Fabio Novembre, Federico Primiceri, Francesca Carallo, Giovanni Lamorgese, Lara Bobbio, Ludovica Polito, Marcello Moscara, Monica Righi, Pino e Carol Cordella, Renzo Buttazzo, Sandro Greco, Valeria Crasto.<\/p>\n<p>L\u2019Associazione id&amp;a (imprese design &amp; affini) \u00e8 un progetto nato a Lecce, nel 2006, dalla volont\u00e0 di un gruppo di imprenditori, professionisti e designer salentini, con l\u2019intento di promuovere il design come leva di sviluppo territoriale. Il suo obiettivo \u00e8 quello di creare un sistema integrato, volto a realizzare produzioni personalizzate e innovative, di alta qualit\u00e0 e \u201cidentitarie\u201d, legate alle tradizioni, alle risorse e alla cultura locale. Quale motore di aggregazione, incentiva il confronto, affinch\u00e9 le idee, una volta condivise, possano prendere forma.<\/p>\n<p>Il MUST \u2013 Museo storico della citt\u00e0 di Lecce \u00e8 uno di quei luoghi in cui la memoria del tempo viene custodita, i cui tesori sono oggi fruibili al pubblico dopo una lunga opera di restauro. Un complesso monumentale, un tempo antico monastero di Santa Chiara, oggi un museo destinato a raccontare la storia della citt\u00e0 di Lecce, e l&#8217;arte moderna e contemporanea, negli ariosi spazi della galleria al piano terra. Dopo la duplice mostra inaugurale dello scorso aprile dedicata alla scultura e alla fotografia d\u2019architettura, il MUST esordisce con un programma culturale originale, ricco e variegato che, in coerenza con le linee d\u2019indirizzo museale, vuole raccontare un altro capitolo della storia della nostra citt\u00e0 ancora una volta partendo dal contemporaneo.<\/p>\n<p>Orari di apertura del museo 10 -13.30 \/ 14.30 &#8211; 19.30 (chiuso il luned\u00ec<em><\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/ex-trahere-extra-here\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/ex-trahere-extra-here\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Domenica 10 marzo, alle ore 18, nuovo appuntamento nell\u2019ambito di MustinTime con la mostra di Vito Leone e Paola Mancinelli curata da CO.61 Prosegue la programmazione di MUSTinTIME, l\u2019articolata mostra che si muove dal 30 novembre e sino al 19 marzo, ideata e organizzata dall\u2019Associazione id&amp;a e dal Must \u2013 Museo Storico di Lecce, curata [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12428"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12428"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12428\/revisions"}],"predecessor-version":[{"id":12429,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12428\/revisions\/12429"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}