{"id":12441,"date":"2013-03-08T17:13:34","date_gmt":"2013-03-08T17:13:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12441"},"modified":"2013-03-08T17:13:34","modified_gmt":"2013-03-08T17:13:34","slug":"ancora-sulle-province","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/ancora-sulle-province\/","title":{"rendered":"ANCORA SULLE PROVINCE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong>DICHIARAZIONE DELL\u2019ASSESSORE ERNESTO TOMA:\u00a0<\/strong><strong>\u201cTECNICHE DI MAGIA PER LO PSEUDO GOVERNO REGIONALE\u201d<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">\u201cIl tema dell\u2019abolizione delle Province ritorna centrale nella convulsa fase post-elettorale e il governatore Vendola coglie l\u2019occasione per dar sfogo alla sua delusione per la evidente bocciatura da lui ricevuta in Puglia, riscontro evidente dell\u2019isolamento politico che si \u00e8 costruito da solo. Amareggiato per il risultato, pensa bene di mirare ai cittadini che non l\u2019hanno votato, utilizzando le sei province pugliesi\u201d. Cos\u00ec dichiara l\u2019assessore alla Formazione professionale e Politiche del lavoro della Provincia di Lecce <strong>Ernesto Toma.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u201cL\u2019attacco si concretizza argomentando circa l\u2019utilit\u00e0 di un\u2019eventuale abolizione delle province e scende a fondo, il Governatore, sino ad arrivare a segnalare potenziali disservizi nei Centri per l\u2019impiego territoriali. Ottima mossa, per chi ha abilmente governato con doti di prestigiatore, facendo comparire e scomparire, all\u2019occorrenza, presunte occasioni di coinvolgimento delle province pugliesi. Province che, nonostante il totale abbandono da parte della Regione, affrontano con coraggio (perch\u00e9 di coraggio si tratta) le numerose istanze dettate dal periodo di difficolt\u00e0 economica ma, soprattutto, di crisi sociale. In questi anni la Regione ha coinvolto le province solo quando aveva la necessit\u00e0 di vedere convalidare proprie decisioni e orientamenti che richiedevano ulteriori sforzi e mettevano a disposizione risorse finanziarie sempre minori, per gestire le competenze proprie o per delega alle province\u201d, prosegue.<\/p>\n<p>&nbsp;<\/p>\n<p>Ed incalza: \u201cVerrebbe da chiedere al Presidente Vendola il senso della presentazione del progetto di rafforzamento dell\u2019attivit\u00e0 dei CPI, avvenuta il 6 marzo, dopo ben otto anni di governo regionale, se poi egli stesso auspica una chiusura delle province e delle sue funzioni\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIl monito di Vendola: si aboliscano le realt\u00e0 che quotidianamente chiedono con forza, al governo regionale, l\u2019attenzione verso problemi che solo una gestione a livello locale riesce a indagare e rilevare; tanto che senso avrebbe offrire servizi vicini al cittadino, a quel cittadino che ha manifestamente invitato Vendola a cambiare strada e liberare la Puglia da trascuratezza e lungaggini inutili?\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cResta in Puglia il Governatore, concede il suo pseudo governo a tutti noi, dopo aver portato avanti una campagna elettorale per il Parlamento, promettendo di rappresentare la Puglia a Roma, mettendo al centro del suo operato i problemi della nostra regione\u201d, continua l\u2019assessore <strong>Toma<\/strong>. \u201cPertanto un \u201cgrazie\u201d al Governatore che, dopo aver alimentato i disservizi in Puglia, si propone come portavoce dei cittadini a Roma, ma poi decide di rimanere qui, a far precipitare ulteriormente la situazione fortemente logorata\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cCompare e scompare, compare e scompare. E noi amministratori locali ci interfacciamo con le urgenze del territorio e troviamo un muro creato dal mago e dai suoi assistenti, solo per il malcontento di una competizione elettorale chiusasi negativamente per Vendola\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIl risparmio non si ha abolendo le Province o rinviando, come \u00e8 stato fatto in questi anni, per affrontare problematiche di cui le province pugliesi si fanno portavoce. Il risparmio si ottiene governando adeguatamente, come giornalmente le amministrazioni provinciali fanno, gestendo le competenze attribuite\u201d, conclude l\u2019assessore <strong>Ernesto Toma<\/strong>.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/ancora-sulle-province\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/ancora-sulle-province\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>DICHIARAZIONE DELL\u2019ASSESSORE ERNESTO TOMA:\u00a0\u201cTECNICHE DI MAGIA PER LO PSEUDO GOVERNO REGIONALE\u201d \u201cIl tema dell\u2019abolizione delle Province ritorna centrale nella convulsa fase post-elettorale e il governatore Vendola coglie l\u2019occasione per dar sfogo alla sua delusione per la evidente bocciatura da lui ricevuta in Puglia, riscontro evidente dell\u2019isolamento politico che si \u00e8 costruito da solo. Amareggiato per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12441"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12441"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12441\/revisions"}],"predecessor-version":[{"id":12443,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12441\/revisions\/12443"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}