{"id":12463,"date":"2013-03-09T08:42:45","date_gmt":"2013-03-09T08:42:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12463"},"modified":"2013-03-09T08:43:21","modified_gmt":"2013-03-09T08:43:21","slug":"treno-dei-misteri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/09\/treno-dei-misteri\/","title":{"rendered":"\u201cTreno dei Misteri\u201d"},"content":{"rendered":"<p><strong>Viaggio in treno storico alla scoperta dei riti\u00a0<\/strong><strong>del Venerdi Santo nella citt\u00e0 vecchia di Gallipoli<\/strong><\/p>\n<p>Dopo il successo dei due treni verso il Presepe Vivente di Tricase, torna a viaggiare il Treno Storico<\/p>\n<p>&#8220;Salento Express&#8221; con l&#8217;iniziativa &#8220;IL TRENO DEI MISTERI&#8221;.<\/p>\n<p>L&#8217;evento, creato dall&#8217;Associazione AISAF Onlus, proprietaria del convoglio d&#8217;epoca, in collaborazione<\/p>\n<p>con le Ferrovie Sud Est, con il Comune di Gallipoli e con la locale Pro Loco, ha l\u2019obiettivo di condurre i<\/p>\n<p>propri viaggiatori, nel pomeriggio del Venerd\u00ec Santo, ad ammirare i riti religiosi che tradizionalmente da<\/p>\n<p>secoli, si svolgono nella citt\u00e0 vecchia di Gallipoli, in particolare la grande e suggestiva processione dei<\/p>\n<p>Misteri della Passione di Cristo che alle 18.00 parte dalla Chiesa del SS. Crocifisso con l\u2019omonima<\/p>\n<p>confraternita, accompagnata da quella di S.Maria degli Angeli incaricata quest\u2019ultima nel condurre Maria<\/p>\n<p>Addolorata nelle strade gallipoline.<\/p>\n<p>Prima di assistere alla processione per\u00f2 sar\u00e0 possibile ammirare una mostra fotografica sul Venerd\u00ec Santo<\/p>\n<p>gallipolino, in particolare sulla preparazione della bara del Cristo, la cosiddetta <em>Urnia<\/em>, relativa agli ultimi<\/p>\n<p>cinquant\u2019anni, allestita nel Museo Diocesano; tra un vicolo e l&#8217;altro si potr\u00e0 poi ammirare l&#8217;arte dei<\/p>\n<p>tradizionali <em>Sepolcri <\/em>allestiti nelle numerose chiese incastonate nella Gallipoli Vecchia.<\/p>\n<p>Per l&#8217;occasione, dopo 17 anni dalla chiusura del tronco ferroviario, il Treno Storico &#8220;Salento Express&#8221;<\/p>\n<p>riaprir\u00e0 il tratto di linea che conduce alla stazione del PORTO DI GALLIPOLI, cosi da accompagnare i<\/p>\n<p>viaggiatori direttamente sotto alle mura della citt\u00e0 vecchia gallipolina a pochissimi metri dalle tipiche<\/p>\n<p><em>Paranze<\/em>. Oltre all&#8217;arrivo al Porto di Gallipoli, il Treno dei Misteri offrir\u00e0 un altro debutto ovvero quello<\/p>\n<p>relativo alla fermata per servizio viaggiatori nella stazioni di Galatina e Nard\u00f2 Centrale.<\/p>\n<p>ORARI DI VIAGGIO<\/p>\n<p>Lecce 14.40<\/p>\n<p>Galatina 15.13<\/p>\n<p>Nard\u00f2 Centrale 15.25<\/p>\n<p>Gallipoli Citt\u00e0 15.48<\/p>\n<p>Gallipoli Porto 15.55<\/p>\n<p>Gallipoli Porto 20.00<\/p>\n<p>Gallipoli Citt\u00e0 20.07<\/p>\n<p>Nard\u00f2 Centrale 20.24<\/p>\n<p>Galatina 20.35<\/p>\n<p>Lecce 21.16<\/p>\n<p>BIGLIETTI<\/p>\n<p>I biglietti di viaggio sono in distribuzione presso il Museo Ferroviario di Lecce, sito in Via G. Codacci<\/p>\n<p>Pisanelli 3. L&#8217;accesso al treno avviene dietro ad un contributo di \u20ac 12,00 grazie al quale sar\u00e0 rilasciato un<\/p>\n<p>biglietto di viaggio. I bambini fino a 6 anni non pagano; i bambini da 7 a 10 anni pagano la met\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/09\/treno-dei-misteri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/09\/treno-dei-misteri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Viaggio in treno storico alla scoperta dei riti\u00a0del Venerdi Santo nella citt\u00e0 vecchia di Gallipoli Dopo il successo dei due treni verso il Presepe Vivente di Tricase, torna a viaggiare il Treno Storico &#8220;Salento Express&#8221; con l&#8217;iniziativa &#8220;IL TRENO DEI MISTERI&#8221;. L&#8217;evento, creato dall&#8217;Associazione AISAF Onlus, proprietaria del convoglio d&#8217;epoca, in collaborazione con le Ferrovie [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12463"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12463"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12463\/revisions"}],"predecessor-version":[{"id":12465,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12463\/revisions\/12465"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}