{"id":125073,"date":"2017-09-02T15:39:20","date_gmt":"2017-09-02T13:39:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=125073"},"modified":"2017-09-02T17:52:48","modified_gmt":"2017-09-02T15:52:48","slug":"siciliano-contro-emiliano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/02\/siciliano-contro-emiliano\/","title":{"rendered":"SICILIANO CONTRO EMILIANO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"950\" title=\"20663960_10212486590952944_8929115118013153290_n\" class=\"alignleft size-full wp-image-125074\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/20663960_10212486590952944_8929115118013153290_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/20663960_10212486590952944_8929115118013153290_n.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/20663960_10212486590952944_8929115118013153290_n-300x297.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/20663960_10212486590952944_8929115118013153290_n-768x760.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/20663960_10212486590952944_8929115118013153290_n-60x60.jpg 60w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>Riceviamo e volentieri pubblichiamo. Il dirigente regionale, e consigliere comunale a Nard\u00f2, del Pd Lorenzo Siciliano ci manda il seguente comunicato______<\/p>\n<p>Michele Emiliano sta svendendo la storia del Partito Democratico. In Puglia dovrebbe crescere maggiormente la voce e l&#8217;azione di chi non resta a guardare uno svuotamento culturale, storico e politico del principale partito del centro sinistra. L&#8217; obiettivo \u00e8 pi\u00f9 chiaro che mai: Emiliano sta utilizzando il PD, dalla capitanata al capo di Leuca, come un limone da spremere fino all&#8217;esaurimento anche dell&#8217;ultima goccia. Ogni giorno assistiamo ad endorsment vergognosi da parte del Presidente della Regione nei confronti di Sindaci di centro destra e di estrema destra. Questo atteggiamento non \u00e8 pi\u00f9 tollerabile, \u00e8 uno schiaffo a chi quotidianamente si spende e difende il nostro Partito credendo nei valori pi\u00f9 veri che hanno fatto s\u00ec che il PD nascesse.<\/p>\n<p>La formazione del gruppo consiliare denominato &#8220;Fronte Democratico&#8221; (la componente del PD che fa capo a Michele Emiliano) a Nard\u00f2, nella maggioranza del Sindaco di casapound palesa, ora in maniera chiara ed inequivocabile, un&#8217;alleanza politica tra Emiliano e Mellone che il primo ha sempre cercato di far passare come rapporto istituzionale.<\/p>\n<p>Mi chiedo perch\u00e9 il centro sinistra, il Partito Democratico debba subire queste umiliazioni. Emiliano dimentica che ad eleggerlo \u00e8 stato il PD e non qualche Sindaco della destra pi\u00f9 becera con la quale oggi va a braccetto al punto di osannarne le qualit\u00e0. La Puglia sta vivendo un tempo in cui diviene famosa non pi\u00f9 per essere un attrattore turistico capofila per il Mezzogiorno, una fucina di giovani talenti, un angolo di paradiso in cui le principali case cinematografiche intendono girare i propri film, ma per nomine di personaggi discutibili in Cda al costo di migliaia di euro all&#8217;anno.<\/p>\n<p>Il mio appello \u00e8 rivolto a tutti i dirigenti, militanti, amministratori ed elettori del Partito Democratico e del centro sinistra tutto: mobilitiamoci, perch\u00e9 continuare ad assistere a queste vergognose alleanze di potere non lede semplicemente la credibilit\u00e0 del nostro Partito, ma dell&#8217;intera classe dirigente del centro sinistra che oggi, nostro malgrado, viene vista rappresentata dal Presidente della Puglia. Noi abbiamo il dovere di crederci e di combattere questa battaglia fondamentale per il futuro di questa terra.&#8221;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/02\/siciliano-contro-emiliano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/02\/siciliano-contro-emiliano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il dirigente regionale, e consigliere comunale a Nard\u00f2, del Pd Lorenzo Siciliano ci manda il seguente comunicato______ Michele Emiliano sta svendendo la storia del Partito Democratico. In Puglia dovrebbe crescere maggiormente la voce e l&#8217;azione di chi non resta a guardare uno svuotamento culturale, storico e politico del principale partito del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":125074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125073"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=125073"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125073\/revisions"}],"predecessor-version":[{"id":125079,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125073\/revisions\/125079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/125074"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=125073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=125073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=125073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}