{"id":125290,"date":"2017-09-05T16:15:19","date_gmt":"2017-09-05T14:15:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=125290"},"modified":"2017-09-05T16:15:19","modified_gmt":"2017-09-05T14:15:19","slug":"trentasette-arresti-sviluppi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/05\/trentasette-arresti-sviluppi\/","title":{"rendered":"TRENTASETTE ARRESTI \/ SVILUPPI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"796\" height=\"503\" title=\"elicottero cc casarano\" class=\"aligncenter size-full wp-image-125298\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/elicottero-cc-casarano.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/elicottero-cc-casarano.jpg 796w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/elicottero-cc-casarano-300x190.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/elicottero-cc-casarano-768x485.jpg 768w\" sizes=\"(max-width: 796px) 100vw, 796px\" \/>(g.m.)_______Ecco tutti\u00a0i particolari sul &#8216;blitz&#8217; anti mafia dei Carabinieri di questa mattina, di cui abbiamo gi\u00e0 riferito nel nostro precedente articolo delle 11.52<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/05\/trentasette-arresti-sgominato-il-clan-colucciadi-galatina-della-sacra-corona-unita\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/05\/trentasette-arresti-sgominato-il-clan-colucciadi-galatina-della-sacra-corona-unita\/<\/a><\/p>\n<p>Sono finiti in carcere<\/p>\n<p>1. ANTONACI Giuseppe inteso Castieddru o Castello, 1964 di Sogliano Cavour<\/p>\n<p>2. BALLARINO Alexsander, 1992 di Sogliano Cavour<\/p>\n<p>3. BLAGO Salvatore, 1978 di Sogliano Cavour<\/p>\n<p>4. CANDIDO Massimo, 1973 di Cutrofiano<\/p>\n<p>5. CIANCI Vincenzo Antonio, 1985 di Sogliano Cavour<\/p>\n<p>6. COSTA Leonardo inteso Musichedda, 1962 di Corigliano d\u2019Otranto<\/p>\n<p>7. DE MATTEIS Daniele inteso Panna e Fragola, 1984 di Lecce<\/p>\n<p>8. DE PAOLIS Gabriele Antonio, 1976 di Galatina Fraz. Noha<\/p>\n<p>9. DE PAOLIS Pantaleo, 1969 di Cursi<\/p>\n<p>10. DE SIMONE Paolo inteso Paulu de lu moru, 1970, di Sogliano Cavour<\/p>\n<p>11. EPIFANI Giordano, 1975, di Cutrofiano<\/p>\n<p>12. FRASSANITO Rosario inteso Pilone, 1969 di Sogliano Cavour<\/p>\n<p>13. GUGLIERSI Marco, 1977 di Galatina<\/p>\n<p>14. GUGLIERSI Pasquale inteso Zoppo, 1980 di Galatina<\/p>\n<p>15. LONGO Rocco, 1967 di Sogliano Cavour<\/p>\n<p>16. MENGOLI Paolo inteso zio Pati, 1963 di Cutrofiano<\/p>\n<p>17. PEPE Marco, 1985 di Surbo<\/p>\n<p>18. PISCOPO Danilo, 1980 di Cutrofiano<\/p>\n<p>19. SOLOMBRINO Salvatore inteso Schiattoddra, 1956 di Castrignano de\u2019 Greci<\/p>\n<p>20. STAMPETE Giuseppe, 1967, di Cursi.<\/p>\n<p>Si trovano invece ai domiciliari<\/p>\n<p>21. BOTRUGNO Simone, 1991 di Galatina<\/p>\n<p>22. CARECHINO Pierluigi, 1977 di Sogliano Cavour<\/p>\n<p>23. CARLUCCIO Cristian, 1987 di Lecce<\/p>\n<p>24. CASCIONE Ivano inteso Sciallone, 1980 di Sogliano Cavour<\/p>\n<p>25. DELL\u2019AVVOCATA Domenico, 1993 di Cutrofiano<\/p>\n<p>26. DE MATTEIS Giuseppe inteso trattorista grande, 1987 di Corigliano d\u2019Otranto<\/p>\n<p>27. DE MATTEIS Luigi inteso trattorista piccolo, 1983 di Galatina<\/p>\n<p>28. EPIFANI Francesco inteso Checco, 1973 di Galatina<\/p>\n<p>29. ICARO Andrea inteso Attila, 1980 di Cutrofiano<\/p>\n<p>30 LUBELLI Rudy, 1990 di Lecce<\/p>\n<p>31. MAGNOLO Luciano Biagio, 1979 di Sogliano Cavour<\/p>\n<p>32. MARZO Luca, 1975 di Corigliano d\u2019Otranto<\/p>\n<p>33. MENGOLI Arcangelo inteso Cutarino, 1988 di Scorrano, ma domiciliato a Milano<\/p>\n<p>34. MONREALE Andrea Ignazio, 1986 di Sogliano Cavour<\/p>\n<p>35. PAGLIALONGA Cosimo inteso Pallunaru, 1954 di Collepasso<\/p>\n<p>36. PEDONE Emiliano, 1976 di Sogliano Cavour<\/p>\n<p>37. VECCHIO Antonio inteso Capoccione, 1981 di Sogliano Cavour.<\/p>\n<p>Tra questi, c\u2019\u00e8 da aggiungere\u00a0che Luciano Biagio Magnolo, accusato di concorso esterno in associazione mafiosa,\u00a0\u00e8 stato ex assessore del suo paese, e attualmente ne\u00a0 \u00e8 consigliere comunale.<\/p>\n<p>Confermate le sette misure di obbligo di firma presso l&#8217; autorit\u00e0 giudiziaria,\u00a0adottate nei confronti di altre persone coinvolte nell&#8217; inchiesta. Infine, sono stati sospesi dal servizio\u00a0un agente della P0lizia Penitenziaria,\u00a0un Vigile Urbano del Comune di Sogliano Cavour e un sottufficiale dei Carabinieri.<\/p>\n<p>Le accuse nei confronti degli arrestati, a vario titolo, riguardano in generale: di ave fatto parte dell&#8217; associazione di tipo mafioso \u201cSacra Corona Unita\u201d,\u00a0&#8220;per acquisire il controllo del territorio nelle attivit\u00e0 illecite tra le quali innanzi tutto quella del traffico di sostanze stupefacenti, nonch\u00e9 quelle delle estorsioni, dell\u2019usura, dei furti, della detenzione di armi&#8221;;\u00a0di avere partecipato ad una organizzazione finalizzata al traffico di sostanze stupefacenti, di detenzione e spaccio;\u00a0di essere responsabili di estorsioni; rapine, possesso di armi.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/05\/trentasette-arresti-sviluppi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/05\/trentasette-arresti-sviluppi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)_______Ecco tutti\u00a0i particolari sul &#8216;blitz&#8217; anti mafia dei Carabinieri di questa mattina, di cui abbiamo gi\u00e0 riferito nel nostro precedente articolo delle 11.52 https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/05\/trentasette-arresti-sgominato-il-clan-colucciadi-galatina-della-sacra-corona-unita\/ Sono finiti in carcere 1. ANTONACI Giuseppe inteso Castieddru o Castello, 1964 di Sogliano Cavour 2. BALLARINO Alexsander, 1992 di Sogliano Cavour 3. BLAGO Salvatore, 1978 di Sogliano Cavour 4. CANDIDO [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":125298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125290"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=125290"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125290\/revisions"}],"predecessor-version":[{"id":125300,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125290\/revisions\/125300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/125298"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=125290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=125290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=125290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}