{"id":125527,"date":"2017-09-09T17:13:34","date_gmt":"2017-09-09T15:13:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=125527"},"modified":"2017-09-09T17:13:34","modified_gmt":"2017-09-09T15:13:34","slug":"breve-ma-intenso-maltempo-sul-salento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/09\/breve-ma-intenso-maltempo-sul-salento\/","title":{"rendered":"BREVE MA INTENSO MALTEMPO SUL SALENTO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"360\" title=\"maltempo-1-640x360\" class=\"alignleft size-full wp-image-125528\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/maltempo-1-640x360.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/maltempo-1-640x360.jpg 640w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/maltempo-1-640x360-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>(e.l.)______Violenta tromba d&#8217; aria questa mattina a Porto Cesareo, dove i fenomeni atmosferici di pioggia, vento\u00a0e grandine, che hanno colpito tutto quanto il Salento occidentale, toccando pure Lecce citt\u00e0, sia pure per poco, hanno assunto particolare intensit\u00e0. danni ad alcune auto e ad alcune barche.<\/p>\n<p>Paura poi per un areo ultraleggero che \u00e8 stato avvistato in cielo mentre si scatenava la tempesta, ed \u00e8 poi scomparso. Allarme poi rientrato: fortunatamente\u00a0\u00e8 riuscito ad atterrare nei pressi della pista di Melpignano.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/09\/breve-ma-intenso-maltempo-sul-salento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/09\/breve-ma-intenso-maltempo-sul-salento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Violenta tromba d&#8217; aria questa mattina a Porto Cesareo, dove i fenomeni atmosferici di pioggia, vento\u00a0e grandine, che hanno colpito tutto quanto il Salento occidentale, toccando pure Lecce citt\u00e0, sia pure per poco, hanno assunto particolare intensit\u00e0. danni ad alcune auto e ad alcune barche. Paura poi per un areo ultraleggero che \u00e8 stato avvistato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":125528,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125527"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=125527"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125527\/revisions"}],"predecessor-version":[{"id":125530,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125527\/revisions\/125530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/125528"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=125527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=125527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=125527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}