{"id":125531,"date":"2017-09-09T17:27:42","date_gmt":"2017-09-09T15:27:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=125531"},"modified":"2017-09-15T08:52:48","modified_gmt":"2017-09-15T06:52:48","slug":"paura-a-specchia-per-noemi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/09\/paura-a-specchia-per-noemi\/","title":{"rendered":"PAURA A SPECCHIA PER NOEMI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"955\" height=\"960\" title=\"16998924_742582702577633_5895129005903756848_n\" class=\"alignleft size-full wp-image-125532\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/16998924_742582702577633_5895129005903756848_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/16998924_742582702577633_5895129005903756848_n.jpg 955w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/16998924_742582702577633_5895129005903756848_n-298x300.jpg 298w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/16998924_742582702577633_5895129005903756848_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/16998924_742582702577633_5895129005903756848_n-768x772.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/16998924_742582702577633_5895129005903756848_n-60x60.jpg 60w\" sizes=\"(max-width: 955px) 100vw, 955px\" \/>(e.l.)______<\/p>\n<p><em>&#8220;Di fronte ad una situazione cos\u00ec delicata facciamo sentire la nostra vicinanza e supporto alla famiglia in modo valido, smettendo di divulgare false e infondate notizie, in quanto sono controproducenti alla sua ricerca e allo stato d&#8217;animo dei cari. Saranno i media e le forze dell&#8217;ordine a fornirci notizie attendibili al momento opportuno, anche per non intralciare le indagini. Piuttosto, possiamo aiutare la famiglia in modo molto pi\u00f9 efficace per esempio creando gruppi volontari di ricerca&#8221;.<\/em><\/p>\n<p>Cos\u00ec, poco fa, su &#8216;Facebook&#8217; una sua amica. Tutta Specchia, dove\u00a0Noemi Durini (nella foto), 16 anni, vive\u00a0con la madre e a due sorelle, \u00e8 in ansia.<\/p>\n<p>Ma la stanno gi\u00e0 cercando ovunque.\u00a0Presso la Prefettura \u00e8 stato attivato un apposito coordinamento delle ricerche.<\/p>\n<p>Noemi, manca da casa da domenica. In passato, altre volte si era allontanata per qualche giorno, ma questa volta la paura \u00e8 maggiore, perch\u00e9 nella sua stanza sono stati trovati effetti personali, e telefonino.<\/p>\n<p>E&#8217; ancora\u00a0in corso da questa mattina una vasta battuta da parte di Polizia, carabinieri e Volontari._______<\/p>\n<p>IN CODA TUTTI GLI AGGIORNMENTI SUCCESSIVI______<\/p>\n<p>L&#8217; ANALISI<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/12\/l-analisi-la-scomparsa-di-noemi-fragili-e-spavaldi-la-difficolta-di-diventare-quello-che-si-e\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/12\/l-analisi-la-scomparsa-di-noemi-fragili-e-spavaldi-la-difficolta-di-diventare-quello-che-si-e\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/09\/paura-a-specchia-per-noemi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/09\/paura-a-specchia-per-noemi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______ &#8220;Di fronte ad una situazione cos\u00ec delicata facciamo sentire la nostra vicinanza e supporto alla famiglia in modo valido, smettendo di divulgare false e infondate notizie, in quanto sono controproducenti alla sua ricerca e allo stato d&#8217;animo dei cari. Saranno i media e le forze dell&#8217;ordine a fornirci notizie attendibili al momento opportuno, anche [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":125532,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125531"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=125531"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125531\/revisions"}],"predecessor-version":[{"id":125534,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125531\/revisions\/125534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/125532"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=125531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=125531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=125531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}