{"id":125912,"date":"2017-09-15T13:53:07","date_gmt":"2017-09-15T11:53:07","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=125912"},"modified":"2017-09-15T15:13:13","modified_gmt":"2017-09-15T13:13:13","slug":"al-via-il-16-settembre-a-castri-di-lecce-la-mostra-darte-frantoio-ipogeo-incontri-di-scultura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/15\/al-via-il-16-settembre-a-castri-di-lecce-la-mostra-darte-frantoio-ipogeo-incontri-di-scultura\/","title":{"rendered":"AL VIA SABATO 16 A CASTRI&#8217; DI LECCE LA MOSTRA D\u2019ARTE &#8216;FRANTOIO IPOGEO &#8211; INCONTRI DI SCULTURA&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" width=\"720\" height=\"696\" title=\"SCUPOLA\" class=\"aligncenter size-full wp-image-125913\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/SCUPOLA.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/SCUPOLA.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/SCUPOLA-300x290.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>di <strong>Stefano Donno<\/strong>____ Accadono in provincia di Lecce interessanti iniziative che vale la pena seguire e consigliare- Come quella per l\u2019appunto di sabato 16 Settembre 2017 alle ore 18.30, negli spazi del Frantoio Ipogeo di Piazza dei Caduti a Castri di Lecce, si inaugura la mostra \u201cFrantoio Ipogeo &#8211; Incontri di Scultura\u201d, con Marcello Gennari, Vito Russo e Giovanni Scupola a cura di Massimo Guastella e Daniela Rollo, (catalogo in mostra Ed. Esperidi). La mostra \u00e8 promossa dal Comune di Castri di Lecce, con il patrocinio del Dipartimento dei Beni Culturali\u00a0dell\u2019Universit\u00e0 del Salento e del Laboratorio Territorio, Arti Visive e Storia dell\u2019Arte Contemporanea.<\/p>\n<p style=\"text-align: justify;\">Il Frantoio, oltre ad essere un bene culturale di indubbio valore storico culturale, si trasforma per l\u2019occasione in una zona temporaneamente autonoma d\u2019arte contemporanea. \u201cFrantoio Ipogeo \u2013 Incontri di Scultura \u2013 2017\u201d propone i maestri Marcello Gennari, Vito Russo e Giovanni Scupola, artisti che sono stati i punti di riferimento per molti altri artisti salentini circa la formazione di scultori nella scuola d\u2019arte di Lecce.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec commenta il Prof. Massimo Guastella curatore della mostra, nonch\u00e9 grande conoscitore ed esperto d\u2019arte:<em> &#8220;Quest\u2019anno ancora tre artisti, eterogenei per generazioni e stili. Sono Marcello Gennari (Manduria 1933), Vito Russo (Salve 1948) e Giovanni Scupola (Specchia 1953). Mi \u00e8 parso interessante rappresentarli con tre opere a testa (quatto per Gennari), per sostenere euritmicamente la dislocazione nell\u2019intero ambiente. Hanno scelto in autonomia opere molto diverse tra loro che trovano piena visione fra gli anfratti, lungo i ridotti circuiti, giocando sull\u2019effetto sorpresa o restando quasi nell\u2019ombra. Una collettiva che rende il Frantoio una sede espositiva da perlustrare alla scoperta del \u201ctra\u201d spazio e sculture&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Gli artisti sono stati uno maestro dell\u2019altro nell\u2019Istituto Statale d\u2019Arte \u201cG. Pellegrino\u201d di Lecce, a partire dal 1952 con il\u00a0professor Gennari, seguito dal professor Russo ed infine con il\u00a0proessor Scupola il quale vi insegna tuttora.<\/p>\n<p style=\"text-align: justify;\">La narrazione iconica in questo contesto specifico avviene con l\u2019esposizione delle opere che interagiscono con l\u2019ambiente muovendosi fra caverne, nicchie e sciave utilizzando un linguaggio ed un\u2019espressione artistica libera e individuale. Prosegue in questo modo il viaggio culturale del trappeto, iniziato nei primi anni del XVIII secolo, interrotto per l\u2019avvento dei nuovi sistemi di produzione olivicola e ricominciato nel nostro tempo con la riqualificazione dell\u2019architettura rupestre. Il frantoio ipogeo, attualmente, diventa testimonianza di continuit\u00e0 con la vita sotterranea nel territorio salentino tra passato e presente.<\/p>\n<p style=\"text-align: justify;\">Marcello Gennari (Manduria, Ta, 1933). Si forma nella citt\u00e0 di Lecce dove risiede e lavora. Nell\u2019Istituto Statale d\u2019Arte \u201cG. Pellegrino\u201d di Lecce, ha insegnato nei laboratori di scultura dal 1952 al 1992. Attraverso la sua grande operosit\u00e0 e sensibilit\u00e0 artistica ha realizzato numerose sculture in pietra Leccese. Le sue opere sono esposte in Musei di citt\u00e0 italiane e straniere. Per questa mostra presenta alcune sue opere quali \u201cNinna nanna prenatale\u201d, \u201cPanneggio \u2013 Omaggio a Sarajevo\u201d, \u201cAnnunciazione\u201d e \u201cPanneggio strozzato\u201d, propone i suoi lavori, unicamente in Pietra Leccese, ricchi di panneggi, fra ombre e luci, messe in risalto fra le aspre rocce del trappeto.<\/p>\n<p style=\"text-align: justify;\">Vito Russo (Salve, Le, 1948) \u00e8 stato titolare della cattedra di scultura presso l\u2019Istituto Statale d\u2019Arte \u201cG. Pellegrino\u201d di Lecce. Innumerevoli sue opere sono allocate in chiese, musei e in collezioni private, testimoni delle sue capacit\u00e0 artistiche. L\u2019artista salvese esegue le sue opere oltre che con materiali nobili come marmo e bronzo anche con materiali locali come pietre, legno e terracotta. Vive e lavora a Salve (LE) dove opera con sapienza e manualit\u00e0. Con le sculture \u201cCome Crisalide alla luce\u201d, \u201cFrammenti\u201d e \u201cApparizione\u201d rievoca i temi della cultura popolare che si manifesta nella fede e nelle visioni tipiche delle grotte. Usa materiali locali e li lavora fino ad esaltarne le caratteristiche intrinseche come la trasparenza.<\/p>\n<p style=\"text-align: justify;\">Gianni Scupola (Specchia, Le, 1953) da sempre ha insegnato in pi\u00f9 Istituti d\u2019 Arte in diverse citt\u00e0 italiane, arte della cartapesta, arte dell\u2019alabastro. arte della pietra e marmo. Attualmente insegna nel Liceo Artistico \u201cCiardo \u2013 Pellegrino\u201d di Lecce. Occupa una posizione di rilievo nel campo artistico contemporaneo con una ricca produzione di opere d\u2019arte. Esegue la prima opera pubblica nel suo paese d\u2019origine nel 1982. Attualmente vive e lavora a Specchia. nella mostra del Frantoio espone le opere \u201cSacro e profano\u201d, \u201cTorso femminile con corpetto\u201d e \u201cSenza titolo\u201d, realizzate con marmi policromi sapientemente levigati, esse sono poste in risalto fra la roccia scura e rugosa del Frantoio evidenziando l\u2019antica natura del luogo e la contemporaneit\u00e0 delle sue opere.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/15\/al-via-il-16-settembre-a-castri-di-lecce-la-mostra-darte-frantoio-ipogeo-incontri-di-scultura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/15\/al-via-il-16-settembre-a-castri-di-lecce-la-mostra-darte-frantoio-ipogeo-incontri-di-scultura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Stefano Donno____ Accadono in provincia di Lecce interessanti iniziative che vale la pena seguire e consigliare- Come quella per l\u2019appunto di sabato 16 Settembre 2017 alle ore 18.30, negli spazi del Frantoio Ipogeo di Piazza dei Caduti a Castri di Lecce, si inaugura la mostra \u201cFrantoio Ipogeo &#8211; Incontri di Scultura\u201d, con Marcello Gennari, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":125913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125912"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=125912"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125912\/revisions"}],"predecessor-version":[{"id":125926,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/125912\/revisions\/125926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/125913"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=125912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=125912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=125912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}