{"id":126276,"date":"2017-09-20T15:15:00","date_gmt":"2017-09-20T13:15:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=126276"},"modified":"2017-09-20T15:17:34","modified_gmt":"2017-09-20T13:17:34","slug":"san-donaci-cellino-san-marco-mesagne-san-pietro-vernotico-le-mani-sporche-di-micidiale-cocaina-sui-nostri-territori-della-sacra-corona-unita-con-la-forza-delle-armi-nuovo-blitz-oggi-della-direzi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/20\/san-donaci-cellino-san-marco-mesagne-san-pietro-vernotico-le-mani-sporche-di-micidiale-cocaina-sui-nostri-territori-della-sacra-corona-unita-con-la-forza-delle-armi-nuovo-blitz-oggi-della-direzi\/","title":{"rendered":"SAN DONACI, CELLINO SAN MARCO, MESAGNE, SAN PIETRO VERNOTICO, LE MANI SPORCHE DI MICIDIALE COCAINA, ROVINA DEI GIOVANI, SUI NOSTRI TERRITORI, DELLA SACRA CORONA UNITA, CON LA FORZA DELLE ARMI. NUOVO BLITZ OGGI DELLA DIREZIONE DISTRETTUALE ANTIMAFIA, 50 CUSTODIE CAUTELARI IN CARCERE. TUTTI I PARTICOLARI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" title=\"Dia\" class=\"aligncenter size-full wp-image-126280\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/Dia.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/Dia.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/Dia-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/Dia-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>di <strong>Emanuele Lezzi______<\/strong><\/p>\n<p><strong><\/strong>Il blitz dei Carabinieri di Brindisi\u00a0\u00e8 scattato prima dell&#8217; alba, cinquanta le\u00a0ordinanze di custodia cautelare in carcere, firmate dal gip del tribunale di Lecce, Vincenzo Brancato, su richiesta del sostituto procuratore della Direzione Distrettuale Antimafia, Alberto Santacatterina.\u00a0 da eseguire, nelle province di Lecce, Brindisi e Taranto, nei confronti di presunti mafiosi, affiliati alla Sacra Corona Unita, e, a vario titolo, accusati\u00a0di reati connessi ad armi, attentati\u00a0e droga.<\/p>\n<p>Rispunta ancora una volta\u00a0nell&#8217; occasione anche\u00a0l&#8217; omicidio di Antonio Presta, 29 anni, figlio di un ex boss poi diventato collaboratore di giustizia, avvenuto a\u00a0San Donaci il 6 settembre 2012, di cui \u00e8 accusato Carlo Solazzo. Rispunta, perch\u00e9 il blitz di oggi \u00e8 per tanti versi un po&#8217; la replica di quello scattato lo scorso 12 dicembre, i cui provvedimenti furono poi per la maggior parte annullati dal Tribunale del Riesame per difetto di motivazioni da parte del gip. A<\/p>\n<p>distanza di dieci mesi, i magistrati le hanno colmate, producendo indizi di colpevolezza tali da richiedere nuovi arresti e custodia in carcere:\u00a0<em>&#8220;\u00e8 concreto il pericolo di reiterazione delle condotte delittuose poste in essere, caratterizzate anche dall\u2019ulteriore requisito della violenza con uso delle armi e della finalit\u00e0 di agevolare l\u2019attivit\u00e0 dell\u2019associazione di tipo mafioso, a dimostrazione della stabilit\u00e0 del vincolo associativo e della fattiva partecipazione degli associati al sodalizio e al compimento dei singoli reati fine proprio dello stes<\/em>so\u201d, ha scritto il gip. E ancora, sempre nelle motivazioni odierne:<em>\u00a0&#8220;dalle indagini sia emerso in maniera evidente come gli indagati, privi di stabile o anche occasionale occupazione, abbiano tratto il loro sostentamento esclusivamente dalla commissione dei reati contestati, destinati a protrarsi con continuit\u00e0 nel tempo\u201d.<\/em><\/p>\n<p><em><\/em>All&#8217; origine, i due clan principali su cui si \u00e8 stretto i cerchio, operanti nei comuni di San Donaci e Cellino San Marco, facenti capo rispettivamente a Piero Soleti ed ai fratelli Carlo e Pietro Solazzo, detti cacafave, egemoni in forza alle loro armi, operanti nel settore del traffico e spaccio di sostanze stupefacenti.<\/p>\n<p>In seguito all&#8217; operazione scattata all&#8217; alba di questa mattina,\u00a0cinque persone non sono stati trovate:\u00a0Cosimo Vitale,\u00a0Francesco Giannotti, Matteo Moriero, Sergio Dell&#8217;Anna e Annunziato Cristian Vetrugno.<\/p>\n<p>Nel corso del blitz, a casa di Pietro Solazzo, in contrada Paoli, a Cellino San Marco, i carabinieri hanno trovato\u00a0trecento grammi di cocaina nascosta\u00a0ingirdino, oltre a\u00a0cinquanta grammi hascisc.<\/p>\n<p>A Ostuni, in casa di Antonio Brando Lutrino, sono stati recuperati altri cinquanta grammi di cocaina.<\/p>\n<p>Gli arrestati sono: Salvatore Arseni, 43 anni, Di San Pietro Vernotico; Claudio Bagordo, 44 anni, di San Pietro Vernotico; Vito Braccio, 35 anni, di Mesagne; Cristian Cagnazzo, 39 anni, di Copertino; Floriano Chiriv\u00ec, 36 anni, di Mesagne, Benito Clemente, 38 anni, di San Pietro Vernotico; Vito Conversano, 46 anni, di San Donaci; Antonio Corbascio, 44 anni, di San Donaci,;Onofrio Corbascio, 49 anni, di San Donaci; Daniele D\u2019Amato detto \u201cCacanachi\u201d, 39 anni, di San Donaci; Giuseppe D\u2019Errico, 35 anni, di Mesagne; Antonio Francesco De Luca, detto &#8220;ticitone&#8221;, 26 anni, San Pietro Vernotico; Sergio Dell\u2019Anna, 40 anni, di San Pietro Vernotico; Marco Ferulli, 44 anni, di Catania; Francesco Francavilla, 37 anni, di San Pietro Vernotico; Cosimo Fullone, 40 anni, di Mesagne; Cristian Gennari, 30 anni, di Mesagne; Francesco Giannotti, 30 anni, di Mesagne; Giuseppe Giordano, 46 anni, di San Pietro Vernotico; Hajdari Gennaro, 34 anni, di Palermo;\u00a0Davide Goffredo, 36 anni, di San Pietro Vernotico; Luca Goffredo, 38 anni, di San Pietro Vernotico; Paolo Gollia, 34 anni, di San Pietro Vernotico; Stefano Immorlano, 36 anni, di Campi Salentina; Gabriele Ingusci, 37 anni, di Nard\u00f2; Fausto Lamberti, 38 anni, di Campi Salentina; Gabriele Leuzzi, 38 ani, di Campi Salentina; Antonio Brando Lutrino, 39 anni, di Ostuni; Gionatan Manchisi, 36 anni, residente in Germania; Cosimo Mazzotta, 54 anni, di Cellino San Marco; Matteo Moriero, 24 anni, di San Pietro Vernotico; Umberto Nicoletti, 40 anni, di Lecce; Massimiliano Pagliara, 40 anni, di San Pietro Vernotico; Marco Pecoraro, 37 anni, residente in Germania; Cosimo Perrone, 34 anni, di San Pietro Vernotico; Giuseppe Perrone detto \u201cBarabba\u201d, 45 anni, di San Pietro Vernotico; Daniela Presta, 40 anni, di Mesagne; Raffaele Renna, 48 anni, di Mesagne; Daniele Rizzo, 40 anni, di San Pietro Vernotico; Saverio Rizzo, 51 anni, di Cellino San Marco; Giuseppe Saponaro, 35 anni, di Mennigen, Germania; Antonio Saracino, 41 anni, di Mesagne;, Valtere Scalinci, 42 anni, di Albstad-Ebingen, Germania; Carlo Solazzo, 41 anni, di San Pietro Vernotico; Pietro Solazzo, 38 anni, San Pietro Vernotico; Pietro Soleti, 52 anni, di San Pietro Vernotico; Nicola Taurino, 25 anni, di San Pietro Vernotico; Andrea Vacca, 42 anni, di San Pietro Vernotico; Annunziato Cristian Vedruccio, 39 anni, di Mesagne; Cosimo Vitale, 28 anni di Campi Salentina.<\/p>\n<h2><\/h2>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/20\/san-donaci-cellino-san-marco-mesagne-san-pietro-vernotico-le-mani-sporche-di-micidiale-cocaina-sui-nostri-territori-della-sacra-corona-unita-con-la-forza-delle-armi-nuovo-blitz-oggi-della-direzi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/20\/san-donaci-cellino-san-marco-mesagne-san-pietro-vernotico-le-mani-sporche-di-micidiale-cocaina-sui-nostri-territori-della-sacra-corona-unita-con-la-forza-delle-armi-nuovo-blitz-oggi-della-direzi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Emanuele Lezzi______ Il blitz dei Carabinieri di Brindisi\u00a0\u00e8 scattato prima dell&#8217; alba, cinquanta le\u00a0ordinanze di custodia cautelare in carcere, firmate dal gip del tribunale di Lecce, Vincenzo Brancato, su richiesta del sostituto procuratore della Direzione Distrettuale Antimafia, Alberto Santacatterina.\u00a0 da eseguire, nelle province di Lecce, Brindisi e Taranto, nei confronti di presunti mafiosi, affiliati [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":126280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126276"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=126276"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126276\/revisions"}],"predecessor-version":[{"id":126282,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126276\/revisions\/126282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/126280"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=126276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=126276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=126276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}