{"id":126813,"date":"2017-09-27T18:16:40","date_gmt":"2017-09-27T16:16:40","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=126813"},"modified":"2017-09-27T18:17:38","modified_gmt":"2017-09-27T16:17:38","slug":"cocaina-a-cavallino-un-arresto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/27\/cocaina-a-cavallino-un-arresto\/","title":{"rendered":"COCAINA A CAVALLINO, UN ARRESTO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"cavadro\" class=\"alignleft size-medium wp-image-126814\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/cavadro-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/cavadro-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/cavadro-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/cavadro.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(g.m.)______I Carabinieri hanno arrestato ieri sera a Cavallino, in piazza dei Domenicani, Antonio Manno (nella foto), 32 anni, trovato in possesso di sessantacinque grammi di cocaina, suddivisa in ventuno dosi, oltre a dieci grammi di hashish, uno di marijuana e un bilancino di precisione. Si trova ora ai\u00a0domiciliari.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"214\" height=\"300\" title=\"droga cavallino\" class=\"alignleft size-medium wp-image-126815\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/droga-cavallino-214x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/droga-cavallino-214x300.jpg 214w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/droga-cavallino-732x1024.jpg 732w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/droga-cavallino.jpg 742w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/27\/cocaina-a-cavallino-un-arresto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/27\/cocaina-a-cavallino-un-arresto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______I Carabinieri hanno arrestato ieri sera a Cavallino, in piazza dei Domenicani, Antonio Manno (nella foto), 32 anni, trovato in possesso di sessantacinque grammi di cocaina, suddivisa in ventuno dosi, oltre a dieci grammi di hashish, uno di marijuana e un bilancino di precisione. Si trova ora ai\u00a0domiciliari. &nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":126814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126813"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=126813"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126813\/revisions"}],"predecessor-version":[{"id":126819,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126813\/revisions\/126819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/126814"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=126813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=126813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=126813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}