{"id":126911,"date":"2017-09-28T18:01:08","date_gmt":"2017-09-28T16:01:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=126911"},"modified":"2017-09-28T18:04:38","modified_gmt":"2017-09-28T16:04:38","slug":"sindaci-associazioni-comitati-cittadini-insieme-mobilitazione-domenica-1-ottobre-contro-la-discarica-di-parachianca","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/28\/sindaci-associazioni-comitati-cittadini-insieme-mobilitazione-domenica-1-ottobre-contro-la-discarica-di-parachianca\/","title":{"rendered":"SINDACI, ASSOCIAZIONI, COMITATI, CITTADINI DEL NORD SALENTO TUTTI INSIEME. MOBILITAZIONE DOMENICA 1 OTTOBRE CONTRO LA DISCARICA DI &#8216;PARACHIANCA&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"538\" height=\"295\" title=\"PA2\" class=\"alignleft size-full wp-image-126913\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/PA2.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/PA2.jpg 538w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/09\/PA2-300x164.jpg 300w\" sizes=\"(max-width: 538px) 100vw, 538px\" \/>(Rdl)______Nuova mobilitazione di protesta contro i nuovo tentativo della &#8216;Geombiente s.r.l.&#8217; di aprire una discarica in localit\u00e0 Parachianca. Il Comitato dei Cittadini &#8220;NO discarica Parachianca&#8221;, assieme a &#8220;Terre di Cerrate&#8221;, rete d&#8217;impresa delle Masserie del Nord Salento, aderiranno all&#8217;iniziativa promossa dai sindaci dei Comuni di Lecce, Surbo, Trepuzzi e Squinzano di convergere domenica 1 ottobre in piazza Margherita a Trepuzzi alle ore 11.30 per respingere insieme e con fermezza il progetto di realizzazione di una discarica.<\/p>\n<p>Il Comitato, assieme alle associazioni e ai cittadini che credono nella valorizzazione del patrimonio storico e ambientale del Nord Salento, aveva organizzato per la stessa giornata un sit-in nei pressi di Masseria Ghietta, invitando i sindaci e i consiglieri dei Comuni di Lecce, Surbo, Trepuzzi e Squinzano e, chiedendo di fare fronte comune, in vista della conferenza di servizi del 5 ottobre, contro il progetto della discarica in localit\u00e0 Parachianca, presentato alla provincia dalla societ\u00e0 Geoambiente s.r.l. il 28 agosto 2017.<\/p>\n<p>Una delegazione di accoglienza ricever\u00e0 alle ore 10.30 il gruppo Fiab Lecce Cicloamici e una rappresentanza del WWF competente per il Parco di Rauccio presso Masseria Ghietta; da cui, proseguendo lungo la SP 246 in direzione Ovest, raggiunger\u00e0 il Sit-In previsto in piazza Margherita a Trepuzzi.<\/p>\n<p>Si invitano tutti i cittadini e le associazioni, a prescindere da qualsiasi colore politico, a partecipare all&#8217;iniziativa, per respingere in modo compatto e con fermezza il progetto di una discarica che non rispetta l&#8217;ambiente, il paesaggio, e le future generazioni.______<\/p>\n<p>LA RICERCA nel nostro articolo del 18 settembre<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/18\/geoambiente-s-r-l-ci-riprova-l-associazione-malachianta-al-fianco-dei-cittadini-del-nord-salento-che-tornano-a-mobilitarsi-contro-la-discarica-di-parachianca\/\">https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/18\/geoambiente-s-r-l-ci-riprova-l-associazione-malachianta-al-fianco-dei-cittadini-del-nord-salento-che-tornano-a-mobilitarsi-contro-la-discarica-di-parachianca\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/28\/sindaci-associazioni-comitati-cittadini-insieme-mobilitazione-domenica-1-ottobre-contro-la-discarica-di-parachianca\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/09\/28\/sindaci-associazioni-comitati-cittadini-insieme-mobilitazione-domenica-1-ottobre-contro-la-discarica-di-parachianca\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Nuova mobilitazione di protesta contro i nuovo tentativo della &#8216;Geombiente s.r.l.&#8217; di aprire una discarica in localit\u00e0 Parachianca. Il Comitato dei Cittadini &#8220;NO discarica Parachianca&#8221;, assieme a &#8220;Terre di Cerrate&#8221;, rete d&#8217;impresa delle Masserie del Nord Salento, aderiranno all&#8217;iniziativa promossa dai sindaci dei Comuni di Lecce, Surbo, Trepuzzi e Squinzano di convergere domenica 1 ottobre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":126913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126911"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=126911"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126911\/revisions"}],"predecessor-version":[{"id":126915,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/126911\/revisions\/126915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/126913"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=126911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=126911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=126911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}