{"id":127572,"date":"2017-10-10T15:56:09","date_gmt":"2017-10-10T13:56:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=127572"},"modified":"2017-10-10T16:09:33","modified_gmt":"2017-10-10T14:09:33","slug":"toh-rimuovere-i-filobus-non-si-puo-fare-per-davvero-o-meglio-bisognera-aspettare-il-2035-cosi-il-nuovo-sindaco-in-campagna-elettorale-permanente-e-capace-di-risolvere-i-problemi-solo-a-pa","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/10\/10\/toh-rimuovere-i-filobus-non-si-puo-fare-per-davvero-o-meglio-bisognera-aspettare-il-2035-cosi-il-nuovo-sindaco-in-campagna-elettorale-permanente-e-capace-di-risolvere-i-problemi-solo-a-pa\/","title":{"rendered":"TOH, RIMUOVERE I FILOBUS NON SI PUO&#8217; FARE PER DAVVERO! O MEGLIO: BISOGNERA&#8217; ASPETTARE IL 2035! COSI&#8217; IL NUOVO SINDACO IN CAMPAGNA ELETTORALE PERMANENTE E&#8217; CAPACE DI RISOLVERE I PROBLEMI, SOLO A PAROLE. I PRIMI CENTO GIORNI DI CARLO SALVEMINI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/10\/Carlo-salvemini1.jpg\" alt=\"\" title=\"Carlo-salvemini\" width=\"800\" height=\"423\" class=\"alignleft size-full wp-image-127573\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/10\/Carlo-salvemini1.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/10\/Carlo-salvemini1-300x159.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/10\/Carlo-salvemini1-768x406.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>(g.p.)______Votatemi, e riqualificher\u00f2 le marine! Per ora, lo ha fatto con la cos\u00ec detta &#8216;comunicazione&#8217;, affidata all&#8217; agenzia specializzata dei suoi amici, come si chiama adesso la propaganda, e con le passeggiate romantiche in riva al mare, come se non bastassero quelle infinite della campagna elettorale.<\/p>\n<p>Votatemi, e basta bancarelle dei partiti nel salotto buono della citt\u00e0. Infatti, tutta piazza sant&#8217; Oronzo, a parte il resto, data per tre giorni al Festival dell&#8217; Unit\u00e0\/Cgil.<\/p>\n<p>Votatemi, e nuovo piano per la circolazione, con chiusura al traffico! Salvo poi accorgersi che chiudere il centro al traffico senza un adeguato sistema di trasporto pubblico non si pu\u00f2.<\/p>\n<p>Confuso e contraddittorio, ancora, sul nodo cruciale del gasdotto, che dovrebbe attraversare e devastare il territorio comunale leccese.<\/p>\n<p>Una al giorno, insomma.<\/p>\n<p>Quella di oggi, vera e propria figuraccia, \u00e8 che si \u00e8 accorto che il filobus non si pu\u00f2 smantellare! Oggi. Dopo mesi di campagna elettorale in cui aveva promesso che lo avrebbe eliminato di brutto, se i Leccesi lo avessero votato. E sulla &#8216;rivoluzione dei trasporti&#8217; si era accreditato come il rottamatore, da un lato, e il creatore, dall&#8217; altro, sempre con tanto di codazzo di sodali e mestieranti compiacenti al seguito, in servizio permanente effettivo.<\/p>\n<p>Oggi, ha fatto marcia indietro. Anche se i filobus a marcia indietro non ci potevano andare!<\/p>\n<p>Insomma, primi cento giorni\u00a0 e passa, da dimenticare, un fallimento su tutti i fronti.______<\/p>\n<p>Ecco il testo del comunicato stampa di questa mattina diramato dal sindaco di Lecce Carlo Salvemini:<\/p>\n<p><em>&#8220;Oggi \u00e8 utile ribadire che la rimozione definitiva del filobus non sar\u00e0 una operazione semplice n\u00e9 breve, ma resta un obiettivo possibile per il quale \u00e8 necessario spendersi. Abbiamo infatti appreso che, a seguito di una rinegoziazione, il mutuo acceso dal Ministero dei Trasporti per la copertura della sua parte di finanziamento dell&#8217;opera presenta come scadenza il 2035.<\/em><\/p>\n<p><em>Fino alla scadenza del mutuo, dunque, il comune non dispone della propriet\u00e0 dell&#8217;opera e quindi non pu\u00f2 decidere liberamente cosa farne.\u00a0<\/em><\/p>\n<p><em>La notizia \u00e8 giunta da Roma dopo l&#8217;approfondimento richiesto dal ministro ai suoi uffici a seguito dell&#8217;incontro con il Sindaco Salvemini del 5 ottobre scorso. In quell&#8217;incontro il ministro Delrio ha fatto presente il pericolo di incorrere in una procedura per danno erariale nel caso si fosse proceduto a rimuovere pali e fili prima dell&#8217;estinzione del mutuo, aggiungendo anche che ci\u00f2 non impedisce, in ogni caso, di sospendere l&#8217;esercizio della filovia a fronte di una certificazione scientifica della sua insostenibilit\u00e0 economica, dell&#8217;impossibilit\u00e0 di migliorarne le performance per il raggiungimento degli obiettivi che i progettisti dell&#8217;opera si erano prefissi e del danno che essa provoca alle casse comunali.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Per ci\u00f2 che riguarda l&#8217;eventuale danno erariale che deriverebbe dalla rimozione dell&#8217;infrastruttura l&#8217;amministrazione si riserva di effettuare ulteriori verifiche. Del resto anche non procedere alla rimozione di un&#8217;opera che arreca nocumento alla citt\u00e0 dal punto di vista economico, ambientale e paesaggistico rappresenterebbe un comportamento irresponsabile da parte di chi oggi si trova ad amministrare la citt\u00e0.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cIl dilemma che siamo chiamati a gestire e risolvere &#8211; dichiara il sindaco Salvemini &#8211; riguarda il paventato rischio di danno erariale legato allo smantellamento, che pu\u00f2 eventualmente impedirci di interrompere e rimediare all&#8217;esistenza di un danno certo e continuato. Siamo dunque chiamati a verificare se e nei confronti di chi verrebbe disposta l&#8217;inchiesta da parte della magistratura contabile, considerando che, evidentemente, non vi \u00e8 alcuna intenzione di esporre al rischio di una condanna per procurato danno amministratori che non hanno responsabilit\u00e0 alcuna rispetto ad un&#8217;opera della quale sono chiamati a gestire le conseguenze e che intendono adoperarsi per rimuoverle. Occorre verificare se e a quali condizioni il filobus pu\u00f2 essere ripensato per garantire gli obiettivi per cui \u00e8 stato finanziato, progettato, eseguito e messo in funzione vale a dire 13.000 passeggeri al giorno, circa 1.000 negli orari di punta e 800.000 chilometri annui. I dati attuali, per\u00f2, ci parlano di una media di 650 passeggeri al giorno e di 250.000 chilometri. \u00c9 evidente che a fronte di questi numeri serve una expertise che metta nelle condizioni di accertare se, alle condizioni date, quei numeri \u2013 i soli che consentono di considerare l&#8217;opera al servizio della comunit\u00e0 \u2013 potranno mai essere raggiunti e come\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00c8 utile ribadire che il fatto che il filobus rappresenti un danno permanente per la citt\u00e0 \u00e8 oggi un&#8217;idea condivisa da tutte le componenti politiche cittadine. La passata giunta comunale defin\u00ec il filobus in delibera:<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cUn\u2019opera pubblica frutto di un\u2019attivit\u00e0 illecita che rappresenta per l\u2019Amministrazione Comunale un danno con effetti permanenti giacch\u00e9 rivelatasi del tutto inadeguata rispetto alle esigenze della citt\u00e0 e pressoch\u00e9 inutilizzata dalla popolazione\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Autorevoli esponenti della attuale minoranza si sono detti al fianco dell&#8217;amministrazione nel compimento del percorso di rimozione dell&#8217;infrastruttura. Fermare il filobus e con esso lo spreco di risorse pubbliche che provoca \u00e8 dunque una battaglia che non ha colore politico: \u00e8 nell&#8217;interesse comune di tutti i cittadini leccesi.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cIn campagna elettorale \u2013 conclude Salvemini &#8211; dissi che il mio governo cittadino sarebbe stato quello impegnato nella dismissione del filobus. Non cambio idea oggi: a questo fine l&#8217;amministrazione, nei tempi e nei modi consentiti dalla legge, lavorer\u00e0 per tappe alla rimozione di questo danno permanente\u201d.<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/10\/10\/toh-rimuovere-i-filobus-non-si-puo-fare-per-davvero-o-meglio-bisognera-aspettare-il-2035-cosi-il-nuovo-sindaco-in-campagna-elettorale-permanente-e-capace-di-risolvere-i-problemi-solo-a-pa\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/10\/10\/toh-rimuovere-i-filobus-non-si-puo-fare-per-davvero-o-meglio-bisognera-aspettare-il-2035-cosi-il-nuovo-sindaco-in-campagna-elettorale-permanente-e-capace-di-risolvere-i-problemi-solo-a-pa\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.)______Votatemi, e riqualificher\u00f2 le marine! Per ora, lo ha fatto con la cos\u00ec detta &#8216;comunicazione&#8217;, affidata all&#8217; agenzia specializzata dei suoi amici, come si chiama adesso la propaganda, e con le passeggiate romantiche in riva al mare, come se non bastassero quelle infinite della campagna elettorale. Votatemi, e basta bancarelle dei partiti nel salotto buono [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":127573,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/127572"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=127572"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/127572\/revisions"}],"predecessor-version":[{"id":127577,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/127572\/revisions\/127577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/127573"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=127572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=127572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=127572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}