{"id":12825,"date":"2013-03-14T17:50:20","date_gmt":"2013-03-14T17:50:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12825"},"modified":"2013-03-14T17:51:33","modified_gmt":"2013-03-14T17:51:33","slug":"vendola-vorrebbe-fare-pulizia-ma-e-te-la-capu-ca-nfetisce-lu-pisce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/vendola-vorrebbe-fare-pulizia-ma-e-te-la-capu-ca-nfetisce-lu-pisce\/","title":{"rendered":"VENDOLA VORREBBE FARE PULIZIA&#8230;MA &#8221; E&#8217; TE LA CAPU CA NFETISCE LU PISCE&#8221;"},"content":{"rendered":"<p><span style=\"font-family: 'Times New Roman'\">\u201cIl quarto Assessore alla Sanit\u00e0 in otto anni, terzo negli ultimi tre anni, \u00e8 una chiara ammissione di colpevolezza da parte del Governatore in relazione alla pi\u00f9 importante delle politiche regionali, che impegna l\u201985% del Bilancio dell\u2019Istituzione. D\u2019altronde l\u2019evidenza di questo fallimento \u00e8 sotto gli occhi e la pelle di chiunque sia costretto ad avere a che fare con il servizio sanitario regionale.&#8221;<br \/>\nQuesto \u00e8 quanto ha dichiarato in una nota inviata alla stampa il Consigliere regionale Saverio Congedo, ed ha poi continuato con: &#8211;<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">\u00a0&#8220;<\/span><span style=\"font-family: 'Times New Roman'\">Ma non meno significativo \u00e8 il siluramento degli Assessori alle Infrastrutture, ai Trasporti ed alle Risorse Umane e la nomina \u201cincredibile\u201d di quelli al Bilancio e all\u2019Agricoltura, scelte in settori-chiave che segnalano un\u2019esigenza di discontinuit\u00e0 e una sostanziale sfiducia del Governatore nei confronti dei Consiglieri che lo sostengono. Tutta da decifrare \u00e8 poi la retrocessione dalla Vice-Presidenza di Loredana Capone, assessore alle politiche per lo sviluppo economico.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">\u00a0<\/span><span style=\"text-decoration: underline\"><span style=\"font-family: 'Times New Roman'\">A ben vedere, siamo ad una riedizione del \u201crepulisti\u201d della fine della legislatura passata, con il quale Il Governatore volle scaricare sugli ex-assessori i \u201cpeccati\u201d del suo Governo regionale. Vendola farebbe bene, invece, a prendere atto che se le sue Giunte non funzionano, forse \u00e8 anche questione di manico.\u201d<\/span><\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'\">\u00a0<\/span><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/vendola-vorrebbe-fare-pulizia-ma-e-te-la-capu-ca-nfetisce-lu-pisce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/vendola-vorrebbe-fare-pulizia-ma-e-te-la-capu-ca-nfetisce-lu-pisce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cIl quarto Assessore alla Sanit\u00e0 in otto anni, terzo negli ultimi tre anni, \u00e8 una chiara ammissione di colpevolezza da parte del Governatore in relazione alla pi\u00f9 importante delle politiche regionali, che impegna l\u201985% del Bilancio dell\u2019Istituzione. D\u2019altronde l\u2019evidenza di questo fallimento \u00e8 sotto gli occhi e la pelle di chiunque sia costretto ad avere [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12825"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12825"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12825\/revisions"}],"predecessor-version":[{"id":12827,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12825\/revisions\/12827"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}