{"id":12847,"date":"2013-03-14T20:40:42","date_gmt":"2013-03-14T20:40:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=12847"},"modified":"2013-03-14T20:40:43","modified_gmt":"2013-03-14T20:40:43","slug":"salvo-per-miracolo-grazie-allintervento-dei-carabinieri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/salvo-per-miracolo-grazie-allintervento-dei-carabinieri\/","title":{"rendered":"SALVO PER MIRACOLO GRAZIE ALL&#8217;INTERVENTO DEI CARABINIERI"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/salvo-per-miracolo-grazie-allintervento-dei-carabinieri\/images-23\/\" rel=\"attachment wp-att-12848\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/images2.jpeg\" alt=\"\" width=\"194\" height=\"259\" class=\"alignleft size-full wp-image-12848\" \/><\/a>Alliste. Il pomeriggio del 12 marzo scorso, i Carabinieri del Nucleo Radiomobile della Compagnia di Casarano, sono intervenuti, in Alliste, presso l\u2019abitazione di una vedova pensionata, su richiesta di soccorso pervenuta alla locale Centrale Operativa. All\u2019equipaggio dei Carabinieri, giunto immediatamente sul posto, la donna, in evidente stato di agitazione, ha riferito, che suo figlio si era rinchiuso nel bagno e non rispondeva pi\u00f9. I militari, attraverso le persiane esterne, hanno notato l\u2019uomo riverso su se stesso che sembrava colpito da malore. Cos\u00ec, senza indugiare oltre i carabinieri hanno sfondato la porta del bagno ed accertato che l\u2019uomo, ormai cianotico, non rispondeva alle sollecitazioni ed \u00e8 stato subito messo in \u201cposizione di sicurezza\u201d mentre uno dei due carabinieri ha eseguito una manovra di\u00a0<em>sub lussazione\u00a0<\/em>della mandibola, liberando le vie aeree ostruite dalla lingua retratta, permettendo cos\u00ec la ripresa dell\u2019attivit\u00e0 respiratoria fino all\u2019arrivo del personale del\u00a0<em>118<\/em>. I sanitari, giunti poco dopo, hanno constatato l\u2019efficacia del provvidenziale intervento dei carabinieri. L\u2019uomo, che ha quarantuno anni, \u00e8 stato trasportato presso l\u2019Ospedale di Casarano per i controlli del caso, per essere poi dimesso.<\/p>\n<div style=\"text-align: left\"><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/salvo-per-miracolo-grazie-allintervento-dei-carabinieri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/14\/salvo-per-miracolo-grazie-allintervento-dei-carabinieri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Alliste. Il pomeriggio del 12 marzo scorso, i Carabinieri del Nucleo Radiomobile della Compagnia di Casarano, sono intervenuti, in Alliste, presso l\u2019abitazione di una vedova pensionata, su richiesta di soccorso pervenuta alla locale Centrale Operativa. All\u2019equipaggio dei Carabinieri, giunto immediatamente sul posto, la donna, in evidente stato di agitazione, ha riferito, che suo figlio si [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12848,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12847"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12847"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12847\/revisions"}],"predecessor-version":[{"id":12850,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/12847\/revisions\/12850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12848"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=12847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=12847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=12847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}