{"id":128819,"date":"2017-11-03T08:43:21","date_gmt":"2017-11-03T07:43:21","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=128819"},"modified":"2017-11-03T08:50:29","modified_gmt":"2017-11-03T07:50:29","slug":"xylella-lunedi-6-inizia-a-brindisi-il-processo-agli-oppositori-del-piano-silletti-a-lecce-giornata-di-riflessione-all-universita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/03\/xylella-lunedi-6-inizia-a-brindisi-il-processo-agli-oppositori-del-piano-silletti-a-lecce-giornata-di-riflessione-all-universita\/","title":{"rendered":"XYLELLA \/ LUNEDI&#8217; 6 INIZIA A BRINDISI IL PROCESSO AGLI OPPOSITORI DEL &#8216;PIANO SILLETTI&#8217;. A LECCE GIORNATA DI RIFLESSIONE E DI SOLIDARIETA&#8217; AL POPOLO DEGLI ULIVI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-128820\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/xylella-proteste-san-pietro-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/xylella-proteste-san-pietro-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/xylella-proteste-san-pietro-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/xylella-proteste-san-pietro-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/xylella-proteste-san-pietro.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>di <strong>Carlo Martignano______<\/strong><\/p>\n<p>Luned\u00ec prossimo, 6 novembre, ci sar\u00e0 a Lecce\u00a0una giornata di riflessione in Ateneo su \u201c<strong>La difesa di madre terra &#8211; processi di trasformazione capitalistica delle campagne e diritti costituzionali\u201d.<\/strong> Il tema, risulta subito evidente, \u00e8 estremamente importante, interessante e quanto mai attuale e i relatori sono certamente all\u2019altezza della situazione (nella locandina sotto), per cui sar\u00e0 un evento assolutamente da non perdere.<\/p>\n<p>Si terr\u00e0 in concomitanza con l\u2019apertura, davanti al Tribunale di Brindisi, del processo contro alcuni (46) dei cittadini, fra i quali ci sono anch\u2019io, che, per difendere la nostra Grande Madre Terra, ed in particolare la nostra Terra del Salento, ci opponemmo alle insensate devastazioni del \u201cpiano Silletti\u201d il quale prevedeva estirpazioni di migliaia di ulivi e appestamento dei terreni con veleni chimici, nelle operazioni di FINTA opposizione all\u2019espansione del batterio Xylella.<\/p>\n<p>Oltre alla difesa, noi proponevamo (e proponiamo ancora, sempre inascoltati) L\u2019APERTURA DELLA RICERCA A 360 GRADI per cercare le vere cause dei disseccamenti dei nostri ulivi e poter quindi impostare una RAZIONALE ricerca di possibili rimedi. Purtroppo l\u2019impostazione IRRAZIONALE di CACCIA ALLE STREGHE del piano Silletti \u00e8 sostanzialmente ancora quella in vigore: NON SIAMO RIUSCITI AD OTTENERE QUASI NIENTE, soltanto una minima riduzione della ottusa violenza vandalistica nell\u2019estirpazione degli ulivi, ma soltanto quelli monumentali (e soltanto quelli regolarmente censiti e registrati, che per\u00f2 sono solo una piccola minoranza) e il riconoscimento di alcune ricerche empiriche di possibili rimedi (necessariamente solo empiriche, malgrado la buona volont\u00e0 dei ricercatori interessati, IN MANCANZA TOTALE di uno studio diagnostico, da noi SEMPRE richiesto e a noi sempre nagato).<\/p>\n<p>La storia insegna che la caccia alle streghe non si \u00e8 mai limitata allo sfogo di insane perversioni sadiche e pulsioni distruttive e necrofile, ma \u00e8 sempre stata finalizzata a consolidare poteri concentrati, antidemocratici, e dare una forte accellerata ai processi di accumulazione. E la caccia alla strega Xylella e alla strega Sputacchina non fa eccezione. Di fatto l\u2019operazione, cos\u00ec come \u00e8 condotta, sta aprendo, ai grandi latifondisti, delle opportunit\u00e0 (ben finanziate con i soldi di tutti noi) di trasformazione produttiva verso un modello iper-industrializzato e sta portando ad un appesantimento insostenibile della situazione dei \u201cpiccoli\u201d produttori agricoli i quali sono spinti sempre pi\u00f9 vicini alla necessit\u00e0, all\u2019urgenza, di svendere i loro terreni a degli speculatori\/avvoltoi gi\u00e0 da tempo adeguatamente \u201cappostati\u201d.<\/p>\n<p>Sull\u2019 \u201caffaire\u201d xylella si gioca una partita che interessa pesantemente il tipo di agricoltura (con annessi: paesaggio e situazione economica) del nostro Salento: distruzione per centralizzare profitti e potere (come vogliono gli xylellisti. E, purtroppo pare che ci stiano riuscendo) oppure salvaguardia per distribuire benessere (come vogliamo noi).<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-128822\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/difesa-madre-terraa-100-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/difesa-madre-terraa-100-213x300.jpg 213w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/difesa-madre-terraa-100.jpg 680w\" sizes=\"(max-width: 213px) 100vw, 213px\" \/><\/p>\n<p>_______<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>______<\/p>\n<p>LA RICERCA nei nostro articoli del 18 dicembre 2015<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"C52fM5TVaa\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/18\/ultimora-clamoroso-sono-i-magistrati-a-fermare-l-abbattimento-degli-ulivi-indagato-il-commissario-giuseppe-silletti-con-altre-dieci-persone-stop-immediato-agli-abbattimenti-esulta-il-p\/\">ULTIM&#8217;ORA \/ CLAMOROSO \/ SONO I MAGISTRATI A FERMARE L&#8217; ERADICAZIONE DEGLI ULIVI VOLUTA DAI POLITICI DI BRUXELLES, ROMA E BARI \/ INDAGATO IL COMMISSARIO GIUSEPPE SILLETTI CON ALTRE DIECI PERSONE CON PESANTISSIME IPOTESI DI REATO \/ STOP IMMEDIATO AGLI ABBATTIMENTI \/ ESULTA &#8216;IL POPOLO DEGLI ULIVI&#8217;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/12\/18\/ultimora-clamoroso-sono-i-magistrati-a-fermare-l-abbattimento-degli-ulivi-indagato-il-commissario-giuseppe-silletti-con-altre-dieci-persone-stop-immediato-agli-abbattimenti-esulta-il-p\/embed\/#?secret=C52fM5TVaa\" data-secret=\"C52fM5TVaa\" width=\"500\" height=\"282\" title=\"&#8220;ULTIM&#8217;ORA \/ CLAMOROSO \/ SONO I MAGISTRATI A FERMARE L&#8217; ERADICAZIONE DEGLI ULIVI VOLUTA DAI POLITICI DI BRUXELLES, ROMA E BARI \/ INDAGATO IL COMMISSARIO GIUSEPPE SILLETTI CON ALTRE DIECI PERSONE CON PESANTISSIME IPOTESI DI REATO \/ STOP IMMEDIATO AGLI ABBATTIMENTI \/ ESULTA &#8216;IL POPOLO DEGLI ULIVI&#8217;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>e del 6 maggio 2016<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"mf30ToJ7TR\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/06\/forum-terzo-settore-lecce-solidarieta-ai-46-indagati-del-popolo-degli-ulivi\/\">FORUM TERZO SETTORE, LECCE: SOLIDARIETA&#8217; AI QUARANTASEI INDAGATI DEL POPOLO DEGLI ULIVI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/06\/forum-terzo-settore-lecce-solidarieta-ai-46-indagati-del-popolo-degli-ulivi\/embed\/#?secret=mf30ToJ7TR\" data-secret=\"mf30ToJ7TR\" width=\"500\" height=\"282\" title=\"&#8220;FORUM TERZO SETTORE, LECCE: SOLIDARIETA&#8217; AI QUARANTASEI INDAGATI DEL POPOLO DEGLI ULIVI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/03\/xylella-lunedi-6-inizia-a-brindisi-il-processo-agli-oppositori-del-piano-silletti-a-lecce-giornata-di-riflessione-all-universita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/03\/xylella-lunedi-6-inizia-a-brindisi-il-processo-agli-oppositori-del-piano-silletti-a-lecce-giornata-di-riflessione-all-universita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Carlo Martignano______ Luned\u00ec prossimo, 6 novembre, ci sar\u00e0 a Lecce\u00a0una giornata di riflessione in Ateneo su \u201cLa difesa di madre terra &#8211; processi di trasformazione capitalistica delle campagne e diritti costituzionali\u201d. Il tema, risulta subito evidente, \u00e8 estremamente importante, interessante e quanto mai attuale e i relatori sono certamente all\u2019altezza della situazione (nella locandina [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":128821,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/128819"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=128819"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/128819\/revisions"}],"predecessor-version":[{"id":128825,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/128819\/revisions\/128825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/128821"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=128819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=128819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=128819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}