{"id":129901,"date":"2017-11-27T14:28:06","date_gmt":"2017-11-27T13:28:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=129901"},"modified":"2017-11-27T14:30:58","modified_gmt":"2017-11-27T13:30:58","slug":"violenze-in-famiglia-un-arresto-a-massafra","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/27\/violenze-in-famiglia-un-arresto-a-massafra\/","title":{"rendered":"VIOLENZE IN FAMIGLIA, UN ARRESTO A MASSAFRA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-129902\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/1287-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/1287-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/1287-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/11\/1287.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(e.l.)______Un giovane di 36 anni \u00e8 stato arrestato questa mattina a Massafra (nella foto), su ordinanza di custodia cautelare emessa dal gip Benedetto Ruberto, richiesta del pubblico ministero della Procura della Repubblica di Taranto Antonella De Luca, con le accuse di maltrattamenti in famiglia e violenza sessuale. Si trova ora ai domiciliari nell&#8217; abitazione di un prente.<\/p>\n<p>Le indagini erano partite dopo la denuncia presentata dalla moglie, stanca di anni di soprusi, e ultimamente minacciata pure di morte.<\/p>\n<p>Secondo gli inquirenti, il marito l&#8217; ha picchiata pi\u00f9 volte, e l&#8217; ha spesso costretta ad avere rapporti sessuali contro la sua volont\u00e0; oltre, in altre occasioni, a prendere a botte anche i tre figli minorenni.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/27\/violenze-in-famiglia-un-arresto-a-massafra\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/27\/violenze-in-famiglia-un-arresto-a-massafra\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Un giovane di 36 anni \u00e8 stato arrestato questa mattina a Massafra (nella foto), su ordinanza di custodia cautelare emessa dal gip Benedetto Ruberto, richiesta del pubblico ministero della Procura della Repubblica di Taranto Antonella De Luca, con le accuse di maltrattamenti in famiglia e violenza sessuale. Si trova ora ai domiciliari nell&#8217; abitazione di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":129902,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/129901"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=129901"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/129901\/revisions"}],"predecessor-version":[{"id":129903,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/129901\/revisions\/129903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/129902"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=129901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=129901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=129901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}