{"id":130376,"date":"2017-12-12T00:02:52","date_gmt":"2017-12-11T23:02:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=130376"},"modified":"2017-12-12T09:00:49","modified_gmt":"2017-12-12T08:00:49","slug":"note-darte-leonardo-le-macchine-i-codici-e-i-segreti-dei-castelli-al-carlo-v-di-lecce-fino-al-31-marzo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/12\/note-darte-leonardo-le-macchine-i-codici-e-i-segreti-dei-castelli-al-carlo-v-di-lecce-fino-al-31-marzo\/","title":{"rendered":"NOTE D&#8217;ARTE \/ LEONARDO, LE MACCHINE, I CODICI E I SEGRETI, AL CARLO V DI LECCE FINO AL 31 MARZO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-130384\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-1020x1024.jpg 1020w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-768x771.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-1529x1536.jpg 1529w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-2039x2048.jpg 2039w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/A1ThCDEPKwL-60x60.jpg 60w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>di <strong>Eliana Masulli______<\/strong><\/p>\n<p>Gioved\u00ec 7 dicembre, nella sala conferenze della Torre Magistra del Castello Carlo V di Lecce, \u00e8 stata presentata la mostra dal titolo \u201cLeonardo, le macchine, i codici e i segreti dei castelli\u201d, organizzata da Theutra e Mapi Org&amp;design e curata dall\u2019architetto Cristina Martina.<\/p>\n<p>La conferenza del 7 dicembre ha visto la partecipazione del sindaco Carlo Salvemini, dell\u2019assessore regionale alla Pubblica Istruzione Sebastiano Leo, del professore Giorgio Zavarise, della dirigente dell\u2019Istituto Scolastico IV Circolo Sigismondo Castromediano Tiziana Faggiano e della curatrice Cristina Martina.<\/p>\n<p>La mostra \u00e8 patrocinata dal Comune di Lecce e dalla Regione Puglia con il contributo di Puglia Promozione e dell\u2019assessorato alla Pubblica Istruzione della Regione Puglia, partner la Scuola IV Circolo Sigismondo Castromediano.<\/p>\n<p>Visitabile fino al 31 marzo 2018, dalle 9,00 alle 13,00 e dalle 16,00 alle 20,00; sabato e domenica dalle 9,30 alle 13,00 e dalle 16,00 alle 20,00.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/12\/note-darte-leonardo-le-macchine-i-codici-e-i-segreti-dei-castelli-al-carlo-v-di-lecce-fino-al-31-marzo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/12\/note-darte-leonardo-le-macchine-i-codici-e-i-segreti-dei-castelli-al-carlo-v-di-lecce-fino-al-31-marzo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Eliana Masulli______ Gioved\u00ec 7 dicembre, nella sala conferenze della Torre Magistra del Castello Carlo V di Lecce, \u00e8 stata presentata la mostra dal titolo \u201cLeonardo, le macchine, i codici e i segreti dei castelli\u201d, organizzata da Theutra e Mapi Org&amp;design e curata dall\u2019architetto Cristina Martina. La conferenza del 7 dicembre ha visto la partecipazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":130384,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130376"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=130376"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130376\/revisions"}],"predecessor-version":[{"id":130445,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130376\/revisions\/130445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/130384"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=130376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=130376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=130376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}