{"id":130470,"date":"2017-12-12T15:40:49","date_gmt":"2017-12-12T14:40:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=130470"},"modified":"2017-12-18T10:45:17","modified_gmt":"2017-12-18T09:45:17","slug":"piano-traffico-per-le-festivita-a-lecce-citta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/12\/piano-traffico-per-le-festivita-a-lecce-citta\/","title":{"rendered":"PIANO TRAFFICO PER LE FESTIVITA&#8217; A LECCE CITTA&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-130471\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/Lecce-si-apre-al-Natale_ok-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/Lecce-si-apre-al-Natale_ok-300x212.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/Lecce-si-apre-al-Natale_ok-1024x723.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/Lecce-si-apre-al-Natale_ok-768x543.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/Lecce-si-apre-al-Natale_ok-1536x1085.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/Lecce-si-apre-al-Natale_ok.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(Rdl)______Da sabato prossimo, 16 dicembre e per tutti i sabato e domenica nel periodo festivo e venerd\u00ec 5 gennaio, sar\u00e0 in vigore un piano speciale di traffico, varato dall&#8217; amministrazione comunale, col fine di\u00a0 razionalizzare il flusso dei veicoli, e comunicato come qui di seguito.<\/p>\n<p>Per tutti i week end saranno a disposizione 1400 posti auto in apposite\u00a0aree a parcheggio collegate al centro da bus navetta o navette elettriche:\u00a0area dell&#8217;edificio universitario Principe Umberto (70 posti), parcheggio in via Bernardino Realino (180 posti), parcheggio Ateneo di Via Adua (70 posti), parcheggio edificio Parlangeli di via Stampacchia (40 posti); parcheggio (110 posti totali) in via Petraglione (alle spalle dell&#8217;edificio dell&#8217;Agenzia del Demanio);\u00a0direzione generale Asl, in via Miglietta (170 posti); Foro Boario (360 posti), Settelaquare (400 posti)<\/p>\n<p>Tutti i parcheggi concessi dagli Enti al Comune saranno aperti dalle 10 del sabato alle 02 del lunedi, fatta eccezione per il parcheggio Asl in via Miglietta disponibile dalle 15 del sabato. Nei giorni del 24 dicembre e del 31 dicembre sia i parcheggi che il servizio navetta si fermeranno alle 21. Servizi di trasporto pubblico:<\/p>\n<p>A disposizione dei cittadini saranno attivi i servizi di navetta e trasporto pubblico aggiuntivi con partenza e arrivo nei pressi delle aree a parcheggio. Saranno 4 i punti della citt\u00e0 nei quali sar\u00e0 possibile parcheggiare per raggiungere il centro comodamente in bus. In particolare:<\/p>\n<p>Dalle ore 10 alle ore 02 nei week end saranno disponibili<\/p>\n<p>Bus navetta Sgm<br \/>\nLINEA ROSSA dal\u00a0Foro Boario;<br \/>\nLINEA VERDE da\u00a0Settelacquare;<br \/>\nEntrambe fermeranno a pochi passi dal centro storico, in Via Costa.<\/p>\n<p>Bus elettrici<br \/>\nLINEA 1 da\u00a0Piazza Argento (Questura)\u00a0\u2013 fermata all&#8217;angolo tra Viale Lo Re e Via Marconi;<br \/>\nLINEA 2 da\u00a0Torre del Parco\u00a0(a pochi passi dal parcheggio Asl) \u2013 fermata in area Ex Caserma Massa;<\/p>\n<p>Provvedimenti sul flusso di circolazione delle automobili<br \/>\nDivieto di transito dalle ore 10 del sabato fino alle ore 02 del lunedi viger\u00e0 il divieto di transito in entrata su\u00a0viale De Pietro\u00a0(a partire da Piazza del Bastione) e\u00a0via XXV Luglio\u00a0fino all&#8217;incrocio con Via Fazzi;<br \/>\nPossibilit\u00e0 di\u00a0svolta a sinistra in viale Marconi\u00a0da viale Otranto con obbligo di percorso verso Viale Lo Re;<br \/>\nSu\u00a0via Costa\u00a0il divieto di fermata sul lato villa comunale.______<\/p>\n<p>In una nota mandata ai mass media, questo piano \u00e8 oggetto di rilievi critici da parte dell&#8217; associazione dei consumatori Adoc, che cos\u00ec si esprime:\u00a0<em>&#8220;Veniamo messi a parte del Piano Traffico Natalizio senza la minima consultazione. Pare che consultazioni con i commercianti ce ne siano state, non cos\u00ec con le associazioni della cittadinanza attiva con le quali non si \u00e8 sentito un bisogno di confronto.<\/em><\/p>\n<p><em>Non siamo stati mai per i piani emergenziali e non fa niente se per questo Natale i suggerimenti delle associazioni non sono attivate sul tavolo dell&#8217;Assessorato alla Mobilit\u00e0. Magari avremmo potuto proporre delle corse gratis da\/per Lecce in treno da Novoli o da San Cesario o altre proposte tipo la sosta tariffata la domenica per favorire il ricambio nella sosta.\u00a0Ci auguriamo che, al di l\u00e0 dei piani emergenziali, sia possibile, appena spente le luci del Capodanno, si possa cominciare a discutere seriamente della mobilit\u00e0 a Lecce, magari nelle sedi opportune come la Consulta della Mobilit\u00e0&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p align=\"JUSTIFY\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/12\/piano-traffico-per-le-festivita-a-lecce-citta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/12\/piano-traffico-per-le-festivita-a-lecce-citta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Da sabato prossimo, 16 dicembre e per tutti i sabato e domenica nel periodo festivo e venerd\u00ec 5 gennaio, sar\u00e0 in vigore un piano speciale di traffico, varato dall&#8217; amministrazione comunale, col fine di\u00a0 razionalizzare il flusso dei veicoli, e comunicato come qui di seguito. Per tutti i week end saranno a disposizione 1400 posti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":130471,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130470"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=130470"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130470\/revisions"}],"predecessor-version":[{"id":130476,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130470\/revisions\/130476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/130471"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=130470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=130470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=130470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}