{"id":13056,"date":"2013-03-19T15:12:30","date_gmt":"2013-03-19T15:12:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13056"},"modified":"2013-03-19T15:12:30","modified_gmt":"2013-03-19T15:12:30","slug":"via-fuortes-lassessore-guido-posiziona-il-cartello","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/19\/via-fuortes-lassessore-guido-posiziona-il-cartello\/","title":{"rendered":"VIA FUORTES, L\u2019ASSESSORE GUIDO POSIZIONA IL CARTELLO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/19\/via-fuortes-lassessore-guido-posiziona-il-cartello\/assessore-a-guido-carteloo-via-fuortes\/\" rel=\"attachment wp-att-13057\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Assessore-A.-Guido-carteloo-Via-Fuortes.jpg\" alt=\"\" width=\"960\" height=\"693\" class=\"alignleft size-full wp-image-13057\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Assessore-A.-Guido-carteloo-Via-Fuortes.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Assessore-A.-Guido-carteloo-Via-Fuortes-300x216.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a>Un gesto concreto e simbolico dell\u2019assessore <strong>Andrea Guido <\/strong>che ha fatto fronte a tutte le spese per la realizzazione e il montaggio del cartello segnaletico dedicato alla cofondatrice della Comunit\u00e0 Emmanuel.<br \/>\n<\/em>E\u2019 stato l\u2019assessore alle Politiche Ambientali,<strong> Andrea Guido <\/strong>a predisporre a proprie spese il posizionamento del cartello segnaletico verticale identificativo di <strong>Via Fuortes<\/strong>, proprio sulla via che conduce alla <strong>Comunit\u00e0 Emmanuel di Lecce<\/strong>.<\/p>\n<p>La posa in opera del segnale \u00e8 stata effettuata questa mattina alla presenza dello stesso Assessore il quale, partendo dal presupposto che le informazioni toponomastiche nelle aree urbane sono ormai diventate estremamente importanti dal punto di vista della sicurezza stradale e avendo ben presente il momento difficile che attraversa il Comune di Lecce sul piano economico, ha fatto installare il cartello segnaletico facendo fronte personalmente a tutte le spese relativa alla realizzazione e al montaggio.<\/p>\n<p><em>\u201cTengo a cuore particolarmente l\u2019operato della Comunit\u00e0 Emmanuel &#8211; <\/em>ha dichiarato <strong>Andrea Guido<\/strong><em> &#8211; e mi rendo conto quanto possa essere difficile mandare avanti un progetto di impegno sociale del genere. Sentivo il dovere di fare il possibile per coadiuvare il lavoro della Comunit\u00e0 e &#8211; avendo appreso che il Settore Lavori Pubblici non poteva di qui a breve far fronte all\u2019intervento, visti gli sforzi di tutta l\u2019Amministrazione tesi alla riduzione delle spese pubbliche comunali &#8211; \u00a0ho preferito procedere di persona e farmi carico della spesa per un dono che per me ha un doppio valore: oltre che pragmatico, vista la grande difficolt\u00e0 obiettiva connessa alla corrispondenza postale indirizzata all\u2019Ente, anche simbolico. Enrica Fuortes, infatti, \u00a0personaggio leccese a cui \u00e8 intitolata la strada, cofondatrice della Comunit\u00e0 Emmanuel rinunci\u00f2 alla sua realt\u00e0 familiare e lavorativa e dal 1981, \u00a0fino alla sua morte, port\u00f2 la Comunit\u00e0 a sviluppare un settore, quello della Dipendenza, capace di offrire servizi per la prevenzione e la cura, non solo dalle catene della droga, ma anche dell\u2019alcool, del fumo, di internet, del gioco patologico e di altri comportamenti compulsivi\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/19\/via-fuortes-lassessore-guido-posiziona-il-cartello\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/19\/via-fuortes-lassessore-guido-posiziona-il-cartello\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un gesto concreto e simbolico dell\u2019assessore Andrea Guido che ha fatto fronte a tutte le spese per la realizzazione e il montaggio del cartello segnaletico dedicato alla cofondatrice della Comunit\u00e0 Emmanuel. E\u2019 stato l\u2019assessore alle Politiche Ambientali, Andrea Guido a predisporre a proprie spese il posizionamento del cartello segnaletico verticale identificativo di Via Fuortes, proprio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13056"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13056"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13056\/revisions"}],"predecessor-version":[{"id":13059,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13056\/revisions\/13059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13057"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}