{"id":130700,"date":"2017-12-19T14:05:52","date_gmt":"2017-12-19T13:05:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=130700"},"modified":"2017-12-19T14:07:18","modified_gmt":"2017-12-19T13:07:18","slug":"salento-fuoco-e-fumo-da-vanini-allilva-mario-carparelli-e-nandu-popu-a-confronto-a-ugento-mercoledi-20","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/19\/salento-fuoco-e-fumo-da-vanini-allilva-mario-carparelli-e-nandu-popu-a-confronto-a-ugento-mercoledi-20\/","title":{"rendered":"\u201cSalento fuoco e fumo: da Vanini all\u2019Ilva\u201d, MARIO CARPARELLI E NANDU POPU A CONFRONTO SUI TEMI DELL&#8217; AMBIENTE E DEL TERRITORIO A UGENTO MERCOLEDI&#8217; 20"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-130701\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/carparelli-nando-300x101.jpg\" alt=\"\" width=\"300\" height=\"101\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/carparelli-nando-300x101.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/carparelli-nando-1024x346.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/carparelli-nando-768x259.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/carparelli-nando.jpg 1066w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>di <strong>Roberto Molle<\/strong>______<\/p>\n<p>L\u2019occasione per assistere al confronto di due personaggi abbastanza agli antipodi, su temi altrettanto \u2013 almeno all\u2019apparenza \u2013 lontani, \u00e8 per domani, mercoled\u00ec 20 dicembre, alle ore 20.30 presso il nuovo museo archeologico di Ugento, in via della Zecca.<\/p>\n<p>Da un lato, il giovane filosofo <strong>Mario Carparelli<\/strong> (tra i maggiori studiosi del filosofo Giulio Cesare Vanini), dall\u2019altro, <strong>Nandu Popu<\/strong>, pioniere (con i suoi Sud Sound System) del raggamuffin italiano e tra gli artisti salentini pi\u00f9 apprezzati in giro per l\u2019Europa.<\/p>\n<p>I temi sul tavolo spazieranno dalla filosofia all\u2019ambiente; una parte del dibattito sar\u00e0 dedicata alla situazione dell\u2019Ilva di Taranto.<\/p>\n<p>La manifestazione, che prende il titolo di: <em>\u201cSalento fuoco e fumo: da Vanini all\u2019Ilva\u201d<\/em>, \u00e8 stata organizzata dalla \u201cconsulta dei giovani di Ugento\u201d in collaborazione dell\u2019associazione \u201cGranelli di sabbia\u201d e della scuola di danza Koin\u00e8. Il tutto \u00e8 patrocinato dal comune di Ugento \u2013 Assessorato alle politiche giovanili.<\/p>\n<p>Noi di <strong>leccecronaca.it<\/strong> ci saremo, e vi daremo poi il resoconto completo dell\u2019evento, con le testimonianze raccolte dai relatori, e fra coloro i quali interverranno al dibattito.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Roberto Molle<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/19\/salento-fuoco-e-fumo-da-vanini-allilva-mario-carparelli-e-nandu-popu-a-confronto-a-ugento-mercoledi-20\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/19\/salento-fuoco-e-fumo-da-vanini-allilva-mario-carparelli-e-nandu-popu-a-confronto-a-ugento-mercoledi-20\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Roberto Molle______ L\u2019occasione per assistere al confronto di due personaggi abbastanza agli antipodi, su temi altrettanto \u2013 almeno all\u2019apparenza \u2013 lontani, \u00e8 per domani, mercoled\u00ec 20 dicembre, alle ore 20.30 presso il nuovo museo archeologico di Ugento, in via della Zecca. Da un lato, il giovane filosofo Mario Carparelli (tra i maggiori studiosi del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":130701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31,75,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130700"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=130700"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130700\/revisions"}],"predecessor-version":[{"id":130704,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/130700\/revisions\/130704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/130701"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=130700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=130700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=130700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}