{"id":131070,"date":"2017-12-29T16:29:46","date_gmt":"2017-12-29T15:29:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=131070"},"modified":"2017-12-29T16:34:54","modified_gmt":"2017-12-29T15:34:54","slug":"di-fronte-ai-sindaci-sul-piede-di-guerra-il-governo-blocca-l-autorizzazione-per-la-centrale-snamtap-di-sulmona-per-il-momento-e-per-il-momento-anna-maria-casini-continua-la-sua-battaglia-in-d","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/29\/di-fronte-ai-sindaci-sul-piede-di-guerra-il-governo-blocca-l-autorizzazione-per-la-centrale-snamtap-di-sulmona-per-il-momento-e-per-il-momento-anna-maria-casini-continua-la-sua-battaglia-in-d\/","title":{"rendered":"DI FRONTE AI SINDACI SUL PIEDE DI GUERRA, IL GOVERNO BLOCCA L&#8217; AUTORIZZAZIONE PER LA CENTRALE SNAM\/TAP DI SULMONA &#8220;per il momento&#8221;. E PER IL MOMENTO ANNA MARIA CASINI CONTINUA LA SUA BATTAGLIA IN DIFESA DEI PROPRI CITTADINI E NON RITIRA LE DIMISSIONI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-131071\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/sindaci-a-roma-gasdotto-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/sindaci-a-roma-gasdotto-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/sindaci-a-roma-gasdotto-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/12\/sindaci-a-roma-gasdotto.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>di <strong>Emanuele Lezzi______<\/strong><\/p>\n<p><em>&#8220;Per il momento \u00e8 congelato il decreto che autorizzerebbe il via libera alla realizzazione della centrale di compressione Snam a Sulmona&#8221;.<\/em><\/p>\n<p>Lo ha annunciato nel primo pomeriggio Anna Maria Casini (nella foto), a Roma, con una delegazione dei sindaci del centro Abruzzo,\u00a0presenti quelli di Anversa, Acciano,\u00a0Atleta, Bugnara,\u00a0Campo di Giove, Cansano,\u00a0Castel di Sangro, Castelvecchio,\u00a0Castel di Ieri, Cocullo,\u00a0Introdacqua, Gagliano,\u00a0Goriano, Molina,\u00a0Pettorano, Prezza,\u00a0Roccacasale, Roccapia,\u00a0Roccaraso, Scanno,\u00a0Secinaro\u00a0e Villalago, accompagnata\u00a0dal sottosegretario alla presidenza della Giunta regionale d&#8217;Abruzzo Mario Mazzocca, al termine dell&#8217; incontro a palazzo Chigi con il consigliere politico del presidente del Consiglio Gabriele De Giorgi.<\/p>\n<p>Le parti si sono aggiornate al prossimo 8 gennaio.<\/p>\n<p>Anche se legittimamente soddisfatta dell&#8217; esito di questo primo incontro, Anna Maria Casini ha fatto sapere<br \/>\ndi non essere intenzionata a ritirare le dimissioni. ______<\/p>\n<p>LA RICERCA nei nostri articoli del 24 e 27 dicmbre<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"CXG2pNfhZ1\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/24\/al-sindaco-donna-di-sulmona-girano-le-palle-di-natale-il-governo-autorizza-la-centrale-di-compressione-tapsnam-e-lei-pianta-casini-biblici-e-si-dimette-live-con-parole-di-fuoco-mi-hanno-vio\/\">AL SINDACO &#8211; DONNA &#8211; DI SULMONA GIRANO LE PALLE DI NATALE. IL GOVERNO AUTORIZZA LA CENTRALE DI COMPRESSIONE TAP\/SNAM  E LEI PIANTA CASINI BIBLICI. PER PRIMA COSA SI DIMETTE: &#8220;Mi hanno violentata&#8221;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/24\/al-sindaco-donna-di-sulmona-girano-le-palle-di-natale-il-governo-autorizza-la-centrale-di-compressione-tapsnam-e-lei-pianta-casini-biblici-e-si-dimette-live-con-parole-di-fuoco-mi-hanno-vio\/embed\/#?secret=CXG2pNfhZ1\" data-secret=\"CXG2pNfhZ1\" width=\"500\" height=\"282\" title=\"&#8220;AL SINDACO &#8211; DONNA &#8211; DI SULMONA GIRANO LE PALLE DI NATALE. IL GOVERNO AUTORIZZA LA CENTRALE DI COMPRESSIONE TAP\/SNAM  E LEI PIANTA CASINI BIBLICI. PER PRIMA COSA SI DIMETTE: &#8220;Mi hanno violentata&#8221;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"m0MAP0FcAJ\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/27\/annamaria-casini-fa-sul-serio-contro-la-centrale-snam-di-sulmona-il-sindaco-parla-di-battaglia-e-venerdi-va-a-roma-a-dirgliene-quattro-a-paolo-gentiloni\/\">ANNA MARIA CASINI FA SUL SERIO CONTRO LA CENTRALE SNAM DI SULMONA. IL SINDACO CONTINUA LA &#8220;battaglia&#8221;. E VA A ROMA, A DIRGLIENE QUATTRO DIRETTAMENTE AL PRESIDENTE DEL CONSIGLIO PAOLO GENTILONI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/27\/annamaria-casini-fa-sul-serio-contro-la-centrale-snam-di-sulmona-il-sindaco-parla-di-battaglia-e-venerdi-va-a-roma-a-dirgliene-quattro-a-paolo-gentiloni\/embed\/#?secret=m0MAP0FcAJ\" data-secret=\"m0MAP0FcAJ\" width=\"500\" height=\"282\" title=\"&#8220;ANNA MARIA CASINI FA SUL SERIO CONTRO LA CENTRALE SNAM DI SULMONA. IL SINDACO CONTINUA LA &#8220;battaglia&#8221;. E VA A ROMA, A DIRGLIENE QUATTRO DIRETTAMENTE AL PRESIDENTE DEL CONSIGLIO PAOLO GENTILONI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/29\/di-fronte-ai-sindaci-sul-piede-di-guerra-il-governo-blocca-l-autorizzazione-per-la-centrale-snamtap-di-sulmona-per-il-momento-e-per-il-momento-anna-maria-casini-continua-la-sua-battaglia-in-d\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/12\/29\/di-fronte-ai-sindaci-sul-piede-di-guerra-il-governo-blocca-l-autorizzazione-per-la-centrale-snamtap-di-sulmona-per-il-momento-e-per-il-momento-anna-maria-casini-continua-la-sua-battaglia-in-d\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Emanuele Lezzi______ &#8220;Per il momento \u00e8 congelato il decreto che autorizzerebbe il via libera alla realizzazione della centrale di compressione Snam a Sulmona&#8221;. Lo ha annunciato nel primo pomeriggio Anna Maria Casini (nella foto), a Roma, con una delegazione dei sindaci del centro Abruzzo,\u00a0presenti quelli di Anversa, Acciano,\u00a0Atleta, Bugnara,\u00a0Campo di Giove, Cansano,\u00a0Castel di Sangro, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":131071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/131070"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=131070"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/131070\/revisions"}],"predecessor-version":[{"id":131075,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/131070\/revisions\/131075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/131071"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=131070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=131070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=131070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}